{"id":431200,"date":"2012-12-04T23:06:49","date_gmt":"2012-12-05T04:06:49","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=431200"},"modified":"2012-12-04T23:06:49","modified_gmt":"2012-12-05T04:06:49","slug":"inmigrando-a-canada-15","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2012\/12\/04\/inmigrando-a-canada-15\/","title":{"rendered":"INMIGRANDO A CANADA"},"content":{"rendered":"<p>Por Vilma Filici<\/p>\n<p>vilma@filici.com<\/p>\n<p>Toronto. El jueves y viernes de la semana pasada asist\u00ed, en Ottawa, a una reuni\u00f3n con altos funcionarios de las distintas \u00e1reas dentro de los Departamentos de Inmigraci\u00f3n y de Recursos Humanos del gobierno canadiense. Yo fui en calidad de Directora de Educaci\u00f3n de la Asociaci\u00f3n Canadiense de Consultores de Inmigraci\u00f3n, y a la misma tambi\u00e9n asistieron representantes del Canadian Bar Association y de la Asociaci\u00f3n de Abogados de Quebec.<\/p>\n<p>Esta reuni\u00f3n se lleva a cabo dos veces al a\u00f1o y el objetivo del gobierno es dar a conocer a los profesionales en inmigraci\u00f3n los planes en la materia, como por ejemplo las fechas de ejecuci\u00f3n de los distintos cambios que se est\u00e1n implementando, y a la vez tambi\u00e9n dar oportunidad a las organizaciones de presentar sus observaciones al respecto.<\/p>\n<p>Esta reuni\u00f3n fue particularmente importante porque en estos momentos se est\u00e1n dando much\u00edsimos cambio que estamos viendo que ya se est\u00e1n implementando. Por ejemplo, muchas personas est\u00e1n preguntando por qu\u00e9 est\u00e1n cambiando los n\u00fameros de expedientes de los casos, ya que estamos viendo variaciones en esos n\u00fameros, y la raz\u00f3n es que el Departamento de Inmigraci\u00f3n se encuentra en un periodo de transici\u00f3n en que est\u00e1n cambiando todos los sistemas para convertirlo en un \u00fanico sistema global electr\u00f3nico.<\/p>\n<p>La idea que persiguen es que todos los formularios y la presentaci\u00f3n de las solicitudes se van a hacer de forma electr\u00f3nica en el a\u00f1o 2014, de tal forma que para el 2017 van a poder implementar el nuevo sistema global remplazando los actuales (actualmente hay un sistema que es para casos dentro del pa\u00eds y otro para casos fuera del pa\u00eds).<\/p>\n<p>Sin embargo, una de las discusiones mas importantes que hubo dentro de la reuni\u00f3n fue sobre la implementaci\u00f3n de los cambios al programa de refugio que se va a llevar a cabo el 15 de diciembre pr\u00f3ximo, y donde uno de los cambios fundamentales es que ahora se van a crear tres distintos grupos de refugiados.<\/p>\n<p>El primer grupo es el de \u201cirregular arrival\u201d, que son personas que llegan al pa\u00eds en grupos organizados que vienen a pedir refugio. La intenci\u00f3n del gobierno, seg\u00fan explicaron, es impedir que las personas sean abusadas, como por ejemplo que lleguen hacinadas en barcos o en camiones, en condiciones inhumanas, donde en el pasado se ha visto que muchas de esas personas han muerto asfixiadas, enfermas, etc.<\/p>\n<p>Sin embargo, lo que muchos defensores de los refugiados plantean es que si bien esa secci\u00f3n es supuestamente para proteger a los refugiados, se puede usar mal, ya que el gobierno tiene el poder de declarar como \u201cirregular arrival\u201d incluso a un grupo de dos personas que lleguen para pedir refugio.<\/p>\n<p>El segundo grupo es el de las personas que van a venir de \u201cPa\u00edses Designados\u201d por el Ministro de Inmigraci\u00f3n, es decir, de una lista de pa\u00edses que ser\u00e1n designados como tal en base a lo que hist\u00f3ricamente ha sucedido con los casos de refugio de sus ciudadanos aqu\u00ed en Canad\u00e1.<\/p>\n<p>Se espera que los pa\u00edses que van a aparecer en esa lista sean aquellos cuyo porcentaje de rechazo de casos de refugio por parte del Consejo de Refugiados sea del 75 por ciento, o personas que vienen de pa\u00edses donde el porcentaje de casos de refugio abandonados en Canad\u00e1 sea del 60 por ciento.<\/p>\n<p>El tercer grupo es el de las personas que vienen de pa\u00edses que NO est\u00e1n en esa lista de \u201cPa\u00edses Designados\u201d.<\/p>\n<p>Para ver las diferencias en el tratamiento de estos dos grupos hay que observar que las personas que vienen de pa\u00edses que est\u00e1n en la lista van a tener entre 15 y 45 d\u00edas para poder presentar su caso y terminarlo, mientras que las personas que vengan de pa\u00edses que no aparecen en esa lista van a tener un total de 239 d\u00edas, lo que implica una diferencia enorme.<\/p>\n<p>Esto significa que las personas que vengan de pa\u00edses que aparecen en la lista van a tener que moverse mucho m\u00e1s r\u00e1pidamente para procesar sus casos, para presentar sus solicitudes y la documentaci\u00f3n necesaria como evidencia. En esa l\u00f3gica, lo que estas personas deber\u00edan hacer es venir preparadas, contactar a un representante legal desde el pa\u00eds de origen, para que desde el momento que lleguen ya vengan con toda la documentaci\u00f3n y todo lo que van a necesitar para poder presentar el caso.<\/p>\n<p>Por ejemplo, si una persona viene y pide refugio en el puerto de entrada, se le va a dar un formulario donde va a tener que presentar toda su historia y toda su informaci\u00f3n, y ese documento tiene que estar en el Consejo de Refugiados en un periodo m\u00e1ximo de 15 d\u00edas.<\/p>\n<p>Las personas que piden refugio en el puerto de entrada van a tener su audiencia en 45 d\u00edas, mientras que las personas que vienen de pa\u00edses que no aparen en la lista, no importa donde pidan refugio, van a tener su audiencia en un periodo de dos meses.<\/p>\n<p>El 15 de diciembre tambi\u00e9n se va a implementar la Divisi\u00f3n de Apelaciones de Inmigraci\u00f3n, que es algo por lo cual se ha estado luchando por much\u00edsimo tiempo. Pero nuevamente vemos que las personas que vienen de pa\u00edses que aparecen en la lista de pa\u00edses designados no tienen derecho a esta apelaci\u00f3n.<\/p>\n<p>Las personas que s\u00ed tienen derecho a apelar deber\u00e1n presentar una apelaci\u00f3n perfeccionada, con toda la documentaci\u00f3n, en un periodo de 30 d\u00edas de haber recibido la negaci\u00f3n del Consejo de Refugiados, y la documentaci\u00f3n a presentar tiene que ser de pruebas que no se encontraban disponibles en el momento que la persona hizo la petici\u00f3n de refugio.<\/p>\n<p>Cuando uno mira las reglas de la Divisi\u00f3n de Apelaciones realmente ve que son muy parecidas a las del PRRA (Pre Removal Risk Assessment), y ya sabemos que el nivel de aprobaci\u00f3n del PRRA fue de menos del uno por ciento.<\/p>\n<p>Lo que se teme en las apelaciones es que con la prohibici\u00f3n de introducir evidencia nueva, que no se haya presentado antes, va a ser muy dif\u00edcil ganarlas, a menos de que hayan sucedido eventos importantes que de alguna manera afecten el caso de la persona mientras est\u00e1 haciendo esa apelaci\u00f3n.<\/p>\n<p>Otro problema con la nueva legislaci\u00f3n es que las personas que pidan refugio no van a tener derecho a una revisi\u00f3n de su caso, o un PRRA, si no han pasado 12 meses desde el momento en que se les rechazo el caso, y peor aun, las personas que vienen de pa\u00edses designados no van a poder tener un PRRA si no pasan 36 meses.<\/p>\n<p>Otra cosa que hay que observar es que en el pasado se deten\u00eda la deportaci\u00f3n autom\u00e1ticamente cuando una persona ten\u00eda derecho a PRRA o cuando hac\u00eda una apelaci\u00f3n ante la Corte Federal, pero bajo la nueva ley esto ya no va a suceder para las personas que vengan de pa\u00edses designados (la lista), para personas cuyos casos se consideren \u201cno cre\u00edbles\u201d, para \u201cirregular arrivals\u201d y personas que lleguen de un tercer pa\u00eds seguro.<\/p>\n<p>Definitivamente son muchos los cambios que entrar\u00e1n en vigencia a partir del 15 de diciembre, y mientras el gobierno sigue tratando de remover a las personas lo m\u00e1s pronto posible, de igual forma tambi\u00e9n va a continuar con el programa de asistencia voluntaria para que las personas regresen a sus pa\u00edses de origen. Esto es a trav\u00e9s del programa que se inici\u00f3 este a\u00f1o como un programa piloto en el GTA, en el cual b\u00e1sicamente se le da cierta cantidad de dinero a la persona, en especies, para que salga del pa\u00eds de manera r\u00e1pida sin que el CBSA tenga que tomar cartas en el asunto.<\/p>\n<p>En la columna de la pr\u00f3xima semana, siempre como parte de los cambios que entrar\u00e1n en vigencia el 15 de diciembre, hablaremos sobre la posibilidad de p\u00e9rdida de la residencia permanente de los refugiados y otros temas de inter\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las personas que piden refugio en el puerto de entrada van a tener su audiencia en 45 d\u00edas.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,81,25,290],"tags":[4629,289],"class_list":["post-431200","post","type-post","status-publish","format-standard","hentry","category-canada","category-columnistas","category-inmigracion","category-inmigrando-a-canada","tag-columnista","tag-inmigracion-2"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/431200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=431200"}],"version-history":[{"count":0,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/431200\/revisions"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=431200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=431200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=431200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}