{"id":436066,"date":"2013-01-08T23:30:59","date_gmt":"2013-01-09T04:30:59","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=436066"},"modified":"2013-01-08T23:30:59","modified_gmt":"2013-01-09T04:30:59","slug":"inmigrando-a-canada-20","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2013\/01\/08\/inmigrando-a-canada-20\/","title":{"rendered":"INMIGRANDO A CANADA"},"content":{"rendered":"<p>Por Vilma Filici<\/p>\n<p>vilma@filici.com<\/p>\n<p>Toronto. A finales del a\u00f1o pasado, el Ministro de Inmigraci\u00f3n y Ciudadan\u00eda, Jason Kenney, anunci\u00f3 con bombo y platillo la implementaci\u00f3n del nuevo Programa Federal de Trabajadores Calificados, y hay muchas personas que lo han recibido como una fuerte posibilidad para poder ingresar a Canad\u00e1 con la residencia permanente.<\/p>\n<p>Hasta el 2 de enero solamente ten\u00edamos los reglamentos y una idea general de c\u00f3mo funcionar\u00eda el programa, sin embargo, ese d\u00eda el gobierno dio a conocer el manual de procedimientos que establece exactamente c\u00f3mo los oficiales de inmigraci\u00f3n deben trabajar en el procesamiento de este programa.<\/p>\n<p>Este programa, conocido como \u201cFederal Skilled Trades Program\u201d, tiene como objetivo aceptar personas bas\u00e1ndose en sus habilidades para poder establecerse econ\u00f3micamente en Canad\u00e1 utilizando los conocimientos de la ocupaci\u00f3n para la que vienen, y es un programa que funciona en todas las provincias y territorios del pa\u00eds excepto en Quebec, dado que esta provincia tiene sus propios programas de inmigraci\u00f3n.<\/p>\n<p>El programa tiene cuatro requisitos b\u00e1sicos que la persona debe reunir, y si no los re\u00fane autom\u00e1ticamente queda descalificado.<\/p>\n<p>El primero es que debe demostrar que tiene o excede el nivel de idioma establecido en los reglamentos (ingl\u00e9s o franc\u00e9s).<\/p>\n<p>El segundo es que en los \u00faltimos cinco a\u00f1os debe haber adquirido por lo menos dos a\u00f1os de experiencia de tiempo completo (o el equivalente en tiempo parcial) en la ocupaci\u00f3n para la cual viene a trabajar. \u00a0Pero esta experiencia de trabajo tiene que haber sido adquirida despu\u00e9s de que la persona obtuvo en el pa\u00eds de origen la calificaci\u00f3n necesaria para poder trabajar en esta ocupaci\u00f3n.<\/p>\n<p>El tercer requisito es que la persona debe reunir los requerimientos del empleo en esa ocupaci\u00f3n espec\u00edfica de acuerdo a lo que est\u00e1 estipulado en el Diccionario Canadiense de Clasificaci\u00f3n de Ocupaciones a nivel nacional. Aqu\u00ed hay una excepci\u00f3n, y se da en el caso donde la ocupaci\u00f3n requiera que para poder trabajar la persona tenga una certificaci\u00f3n en Canad\u00e1.<\/p>\n<p>El cuarto requisito, que es muy importante, es que la persona debe tener una oferta de trabajo de tiempo completo por lo menos por un a\u00f1o, de una compa\u00f1\u00eda canadiense. Esa oferta puede ser de dos empleadores, por ejemplo seis meses con uno y seis meses con otro, pero la oferta de trabajo debe ser por un a\u00f1o minimo.<\/p>\n<p>En el caso de que la persona no tenga una oferta de trabajo, de la \u00fanica forma que puede calificar es si puede obtener la certificaci\u00f3n de sus calificaciones por parte de una asociaci\u00f3n provincial o territorial canadiense para esa ocupaci\u00f3n.<\/p>\n<p>Esto realmente pareciera ser una contradicci\u00f3n, ya que por un lado est\u00e1n diciendo que para llenar los requisitos ocupacionales no es necesario obtener esta certificaci\u00f3n antes de venir a Canad\u00e1 (dado que el gobierno sabe que es bastante complicado poderla obtener), pero por el otro lado piden una oferta de trabajo o la certificaci\u00f3n para que la persona pueda calificar.<\/p>\n<p>Tambi\u00e9n hay otro requisito: que la persona que viene a Canad\u00e1 debe tener una cierta cantidad de dinero para poder mantenerse y mantener a su familia durante los primeros meses que este en el pa\u00eds. Sin embargo, en el caso de que la persona tenga una oferta de trabajo, esto no es requerido.<\/p>\n<p>De igual forma, cuando se habla de oferta de trabajo, si la persona ya se encuentra en Canad\u00e1 con un permiso de trabajo como resultado de un permiso del Departamento de Recursos Humanos, o si se encuentra trabajando bajo la excepci\u00f3n 186 del Reglamento de Inmigraci\u00f3n (que son por ejemplo jugadores de futbol, pastores, artistas) o personas que est\u00e1n trabajando bajo Nafta o cualquiera de los acuerdos entre Canad\u00e1 y otros pa\u00edses, pueden procesar su caso bajo este programa.<\/p>\n<p>En su anuncio del 2 de enero, el Ministro de Inmigraci\u00f3n dio la lista de ocupaciones en demanda para las cuales se procesar\u00e1n 3,000 aplicaciones de residencia permanente bajo este programa este a\u00f1o, y estas son ocupaciones en el \u00e1rea: el\u00e9ctrica, construcci\u00f3n, mantenimiento y operaci\u00f3n de equipos; Supervisores y t\u00e9cnicos en recursos naturales, agricultura y producci\u00f3n; \u00a0supervisores en manufactura, ensamblaje, servicios al publico y especialistas en miner\u00eda y petr\u00f3leo. Cada una de estas \u00e1reas tiene otras ocupaciones. Esto significa que hay 43 ocupaciones abiertas para poder obtener la residencia permanente en Canad\u00e1 bajo este programa.<\/p>\n<p>Para hacer el examen de ingl\u00e9s el gobierno ha designado el IELTS o el CELPIP y estas instituciones fueron elegidas por su experiencia, su confiabilidad, su integridad, porque tiene controles de antifraude, y porque est\u00e1n disponibles en distintos pa\u00edses del mundo.<\/p>\n<p>Un dato que es importante tener en cuenta es que estas instituciones ofrecen dos tipos de ex\u00e1menes: el examen de ingl\u00e9s acad\u00e9mico y el examen de ingl\u00e9s general. Para los efectos de este programa se necesita el examen de ingl\u00e9s de nivel general.<\/p>\n<p>Algo que me pareci\u00f3 muy interesante al leer la gu\u00eda de procedimientos dada a conocer el\u00a0 2 de enero, es que en el momento que se anunci\u00f3 este programa el Ministro de Inmigraci\u00f3n dijo que las personas que se encontraban en el pa\u00eds de manera indocumentada, si reun\u00edan los requisitos y si estaban dispuestas a salir del pa\u00eds, pod\u00edan solicitar la residencia permanente.<\/p>\n<p>Sin embargo, hay una nota en el manual de procedimientos que dice que si la persona no cumple con el requisito de ley 30 (1) (que es que toda persona en Canad\u00e1 debe solicitar y obtener un permiso de trabajo antes de trabajar), por haber trabajado de manera indocumentada podr\u00eda ser encontrado inadmisible a Canad\u00e1 bajo otra secci\u00f3n que dice que rompi\u00f3 las leyes de Canad\u00e1.<\/p>\n<p>En resumen, antes de iniciar un tr\u00e1mite bajo este programa, la persona debe hacer un examen de ingl\u00e9s, debe hacer una investigaci\u00f3n de la ocupaci\u00f3n en el pa\u00eds de origen para ver cu\u00e1les son los requisitos para poder trabajar en la posici\u00f3n, hay que hacer una evaluaci\u00f3n de cu\u00e1les son los requisitos que la persona debe cumplir aqu\u00ed en Canad\u00e1, debe tener una oferta de trabajo, y si no hay una oferta de trabajo debe ponerse en contacto con la asociaci\u00f3n profesional para obtener la certificaci\u00f3n y con esa certificaci\u00f3n poder hacer el tr\u00e1mite para la residencia permanente.<\/p>\n<p>Definitivamente es un proceso complejo, a pesar de que inicialmente parec\u00eda ser un programa bondadoso que beneficiar\u00eda a las personas que trabajan como mano de obra especializada. Porque el hecho de que existan requisitos de idioma, de una oferta de trabajo o de una certificaci\u00f3n, va a hacer el procesamiento de este programa un poco m\u00e1s complicado de lo que se esper\u00f3 inicialmente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A finales del a\u00f1o pasado, el Ministro de Inmigraci\u00f3n y Ciudadan\u00eda, Jason Kenney, anunci\u00f3 con bombo y platillo la implementaci\u00f3n del nuevo Programa Federal de Trabajadores Calificados<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,81,25,290],"tags":[77,2575],"class_list":["post-436066","post","type-post","status-publish","format-standard","hentry","category-canada","category-columnistas","category-inmigracion","category-inmigrando-a-canada","tag-canada-2","tag-inmigrando"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/436066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=436066"}],"version-history":[{"count":0,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/436066\/revisions"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=436066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=436066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=436066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}