{"id":445056,"date":"2013-02-26T23:10:31","date_gmt":"2013-02-27T04:10:31","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=445056"},"modified":"2013-02-26T23:10:31","modified_gmt":"2013-02-27T04:10:31","slug":"inmigrando-a-canada-27","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2013\/02\/26\/inmigrando-a-canada-27\/","title":{"rendered":"INMIGRANDO A CANADA"},"content":{"rendered":"<p>Por Vilma Filici<\/p>\n<p>vilma@filici.com<\/p>\n<p>Toronto. Hace varias semanas, uno de mis clientes fue a la oficina de licencias de matrimonio de una alcald\u00eda de un municipio en el \u00c1rea del Gran Toronto (Greater Toronto \u00c1rea, GTA) para tratar de obtener una licencia para poder casarse con su prometida canadiense. Lamentablemente dicha oficina no le pudo dar la licencia porque el se\u00f1or s\u00f3lo ten\u00eda una copia de su pasaporte, dado que el pasaporte original qued\u00f3 manos de Inmigraci\u00f3n en el momento en que \u00e9l pidi\u00f3 refugio.<\/p>\n<p>Por suerte, la semana pasada el Consejo Municipal de Toronto aprob\u00f3 una pol\u00edtica declarando a esta ciudad como Santuario para los m\u00e1s de 200 mil indocumentados que aqu\u00ed residen. Pero desde que se public\u00f3 la noticia de que\u00a0 Toronto es Santuario, muchas personas se han preguntado cu\u00e1les ser\u00e1n los beneficios reales que recibir\u00e1n los indocumentados con esta nueva pol\u00edtica, dado que ya en estos momentos la mayor\u00eda de las personas reciben los servicios de la ciudad sin importar su estado inmigratorio.<\/p>\n<p>Todo residente de Toronto tiene acceso a sus parques, a sus piscinas, a las bibliotecas, a tomar el transporte p\u00fablico y a que su basura y reciclaje sean recolectados sin necesidad de mostrar su tarjeta de residente o ciudadano. Tambi\u00e9n, los ni\u00f1os de los indocumentados tienen el derecho por parte de la ley inmigratoria Federal y la ley de educaci\u00f3n (provincial) de estudiar, y ni los administradores de los consejos escolares o de las escuelas, ni los maestros, pueden negarle la admisi\u00f3n a un ni\u00f1o. Tampoco pueden denunciar a ning\u00fan ni\u00f1o o a su familia ante el Departamento de Inmigraci\u00f3n, y las autoridades migratorias no pueden llegar a ninguna escuela y sacar a un ni\u00f1o de la misma para usarlo de carnada para atrapar a sus padres.<\/p>\n<p>Algo como \u00e9sto de hecho lo hicieron en el 2006 con una familia \u00a0Costarricense, pero hubo una movilizaci\u00f3n masiva de activistas que trabajan para el beneficio y la seguridad de los inmigrantes e indocumentados y organizaciones comunitarias, y el resultado fue que el Distrito Escolar de Toronto reafirm\u00f3 su pol\u00edtica de \u201cNo preguntes no Respondas\u201d (Don\u2019t ask don\u2019t tell)<\/p>\n<p>De la misma manera, los lugares de refugio para mujeres abusadas tambi\u00e9n tienen una pol\u00edtica de \u201cno preguntes no respondas\u201d como consecuencia de una movilizaci\u00f3n de los mismos grupos ante el arresto de una joven indocumentada de 16 a\u00f1os de edad. Esta jovencita se hab\u00eda refugiado en un \u201cshelter\u201d y fue arrestada por la polic\u00eda en dicho lugar y entregada al Departamento de Inmigraci\u00f3n.<\/p>\n<p>En el 2006 la Junta de Servicios de Polic\u00eda tambi\u00e9n aprob\u00f3 una pol\u00edtica de \u201cDon\u2019t Ask Dont Tell\u201d,\u00a0 pero no ha sido acatada con consistencia por los polic\u00edas, por lo que la mayor\u00eda de activistas comunitarios creen que esta pol\u00edtica no ha sido suficiente y por lo tanto se contin\u00faa la campa\u00f1a para que sea observada efectiva y uniformemente por toda la fuerza policial de la ciudad.<\/p>\n<p>En este sentido, lo que ha quedado claro con la proclamaci\u00f3n de la ciudad de Toronto como Santuario la semana pasada es que la lucha reci\u00e9n comienza dado que aun hay mucho trabajo por hacer.<\/p>\n<p>Las decisiones del Consejo Municipal, que fueron aprobadas por una amplia mayor\u00eda, reafirman el compromiso de la ciudad de ofrecer servicios \u201csin temor\u201d a las personas sin estatus.<\/p>\n<p>En los pasos a seguir qued\u00f3 establecido que los distintos departamentos de la municipalidad preparar\u00e1n un reporte en el cual se establecer\u00e1n los mecanismos en que se pueden dar servicios de tal forma que las\u00a0 personas que viven sin estatus en la ciudad no sientan temor de presentarse a las diversas dependencias municipales para solicitar servicios.<\/p>\n<p>De igual forma, se va a entrenar a los funcionarios municipales sobre c\u00f3mo tratar al p\u00fablico, poniendo especial atenci\u00f3n en c\u00f3mo seguir los procedimientos sin que los usuarios indocumentados sientan temor de acercarse a pedir los servicios. Para cumplir este objetivo tambi\u00e9n se va a crear un protocolo y un programa de educaci\u00f3n p\u00fablica para informar a los residentes de Toronto sobre esta nueva pol\u00edtica de la ciudad.<\/p>\n<p>Adicionalmente, en el momento en que se aprob\u00f3 esta proclamaci\u00f3n, los concejales del municipio tambi\u00e9n votaron a favor de que la ciudad de Toronto le pidiera al gobierno Federal que estableciera un programa de regularizaci\u00f3n para los residentes indocumentados, y que se le enviara una carta al gobierno conservador y los partidos de oposici\u00f3n al respecto.<\/p>\n<p>Tambi\u00e9n, el consejo de la ciudad aprob\u00f3 solicitar al gobierno Federal que incremente los niveles de personas que pueden llegar bajo los programas de nominaciones provinciales, a fin de que las provincias puedan seleccionar y retener trabajadores con ciertos oficios requeridos. Con esta petici\u00f3n lo que quieren es que las provincias puedan traer nuevamente a personas que fueron deportadas del pa\u00eds, sobre todo aquellas familias que tienen ni\u00f1os nacidos en Canad\u00e1, para quienes pidieron que se les d\u00e9 prioridad en el procesamiento de sus casos.<\/p>\n<p>Otro de los acuerdos del Consejo Municipal es pedirle al gobierno provincial que revise sus pol\u00edticas con respecto a los servicios que la provincia presta a los indocumentados, a fin de asegurarse de que se les otorgue acceso a servicios de salud, servicios de emergencia y servicios de vivienda.<\/p>\n<p>Definitivamente la proclamaci\u00f3n de Toronto como Ciudad Santuario, la primera que se proclama en Canad\u00e1, marca un hito hist\u00f3rico en el pa\u00eds dado que abre las puertas para que otras ciudades puedan hacer lo mismo, con lo cual se va a proporcionar un mejor trato para esas decenas de miles de personas que, no obstante no tener un estatus legal en Canad\u00e1, producen, pagan impuestos y est\u00e1n haciendo crecer este pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toronto fue declarada la primera \u201cCiudad Santuario\u201d para los indocumentados en territorio canadiense<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,81,290],"tags":[2574,77,2575],"class_list":["post-445056","post","type-post","status-publish","format-standard","hentry","category-canada","category-columnistas","category-inmigrando-a-canada","tag-a","tag-canada-2","tag-inmigrando"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/445056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=445056"}],"version-history":[{"count":0,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/445056\/revisions"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=445056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=445056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=445056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}