{"id":448367,"date":"2013-04-17T01:05:40","date_gmt":"2013-04-17T05:05:40","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=448367"},"modified":"2013-06-17T18:28:47","modified_gmt":"2013-06-17T22:28:47","slug":"el-problema-en-canada-no-son-los-trabajadores-temporales-sino-la-subcontratacion-de-servicios-fuera-del-pais","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2013\/04\/17\/el-problema-en-canada-no-son-los-trabajadores-temporales-sino-la-subcontratacion-de-servicios-fuera-del-pais\/","title":{"rendered":"El problema en Canad\u00e1 no son los trabajadores temporales sino la subcontrataci\u00f3n de servicios fuera del pa\u00eds"},"content":{"rendered":"<p>Por Vilma Filici<\/p>\n<p>vilma@filici.com<\/p>\n<p>TORONTO. Con mucho inter\u00e9s he venido d\u00e1ndole seguimiento a las noticias sobre las actuaciones del Royal Bank of Canad\u00e1 y la manera en que los medios de comunicaci\u00f3n han presentado la historia acerca de los 45 empleados del Departamento de Computo que han sido despedidos dado que el banco va a subcontratar fuera del pa\u00eds esos trabajos.<\/p>\n<p>Esa deber\u00eda realmente ser la historia enfatizada por los medios, y el punto de critica deber\u00eda haber sido la avaricia del banco que por ganar m\u00e1s dinero despide a sus empleados canadienses para que personas en la India hagan el trabajo por much\u00edsimo menos dinero de lo que le pagan a los especialistas canadienses.<\/p>\n<p>La historia realmente deber\u00eda haber sido acerca de la avaricia de las multinacionales que est\u00e1n llevando nuestros trabajos fuera de Canad\u00e1 para incrementar sus ganancias. De hecho, el Royal Bank of Canad\u00e1 report\u00f3 una ganancia de 7.5 billones de d\u00f3lares en el a\u00f1o 2012, y por lo tanto es solamente avaricia el tratar de ahorrar en los sueldos de sus especialistas en computaci\u00f3n.<\/p>\n<p>Lamentablemente los medios se fijaron solamente en el hecho de que el banco trajo a los trabajadores de la India a Canad\u00e1 para entrenarse con las personas que iban a reemplazar, y todos los art\u00edculos y programas radiales hablaron acerca de los trabajadores temporales y c\u00f3mo estos vienen a quitar el trabajo a los residentes y ciudadanos canadienses.<\/p>\n<p>Definitivamente hay un error fundamental en todos estos reportajes, dado que ninguna de las personas que vinieron de la India son t\u00e9cnicamente considerados trabajadores temporales. Estas personas son simplemente visitantes que vinieron a entrenarse, y hay una secci\u00f3n de ley que permite que una persona venga a entrenar a un ciudadano canadiense, o que venga a Canad\u00e1 a entrenarse por un ciudadano canadiense. Esta persona viene bajo una secci\u00f3n de ley que la define como visitante de negocios.<\/p>\n<p>Si en realidad la situaci\u00f3n fuera como lo est\u00e1n diciendo los medios, entonces habr\u00eda un problema muy serio dado que los peri\u00f3dicos han estado diciendo que estas personas vinieron con un Labour Market Opinion. Y un Labour Market Opinion es un documento que consiguen las compa\u00f1\u00edas cuando quieren traer a un trabajador temporal porque han buscado por todos los medios conseguir dentro de Canad\u00e1 a un ciudadano o residente permanente, y no lo han logrado. Entonces, en ese momento pueden hacer una solicitud al Departamento de Recursos Humanos y pueden obtener un permiso para traer a un trabajador temporal.<\/p>\n<p>Otro de los factores que el Departamento de Recursos Humanos ve, aparte de si hay o no ciudadanos o residentes permanentes que quieran hacer el trabajo, es de qu\u00e9 manera va a afectar el traer a un trabajador temporal a la fuerza laboral canadiense. Por lo tanto, ser\u00eda contra la ley que se le otorgara un Labour Market Opinion a estas 45 personas que vinieron a entrenarse para quitarle los trabajos a quienes ya estaban trabajando.<\/p>\n<p>Yo estoy segura que despu\u00e9s de que se termine con la investigaci\u00f3n la opini\u00f3n p\u00fablica va a darse cuenta de que en realidad no hubo tal Labour Market Opinion otorgado a estas personas.<\/p>\n<p>El problema de toda esta situaci\u00f3n es que como siempre es el inmigrante, y en este caso el trabajador temporal, quien termina siendo perjudicado por la mala informaci\u00f3n o por la xenofobia que se crea cuando es publicada este tipo de historias.<\/p>\n<p>La semana pasada incluso el Primer Ministro del pa\u00eds, Stephen Harper, dijo que iba a hacer una investigaci\u00f3n y que iba a asegurarse de que se tomaran las medidas necesarias para que este tipo de situaci\u00f3n no volviera a suceder. Esto significa que probablemente van a hacer mucho m\u00e1s dif\u00edcil la entrada de trabajadores temporales dado que se ha despertado el inter\u00e9s de la opini\u00f3n p\u00fablica al respecto.<\/p>\n<p>Pero la realidad es que nos guste o no nos guste Canad\u00e1 tiene un problema muy serio de falta de mano de obra especializada y mano de obra com\u00fan. La realidad es que, por ejemplo en la provincia de Alberta, \u00a0su econom\u00eda se mueve b\u00e1sicamente con la fuerza laboral de trabajadores temporales con permisos de trabajo.<\/p>\n<p>Todos sabemos que tenemos una poblaci\u00f3n que est\u00e1 envejeciendo, que pronto van a retirarse much\u00edsimos \u201cBaby boomers\u201d, y que la necesidad de trabajadores para mantener la econom\u00eda va a aumentar a\u00fan m\u00e1s.<\/p>\n<p>Pero sabemos tambi\u00e9n que hay dos teor\u00edas con respecto a c\u00f3mo llenar estas vacantes laborales. Una es que se traigan m\u00e1s inmigrantes, y hay personas que consideran que se deber\u00eda estar trayendo por lo menos un mill\u00f3n de inmigrantes al a\u00f1o. Esa es la teor\u00eda pro inmigrante.<\/p>\n<p>Pero tambi\u00e9n tenemos una teor\u00eda que es contra la inmigraci\u00f3n y que b\u00e1sicamente plantea que para poder mantener la econom\u00eda activa aunque haya escases de trabajadores, lo que se tiene que hacer es aumentar la edad de jubilaci\u00f3n (que es algo que el gobierno ya hizo) y exportar los trabajos a otros pa\u00edses en el marco de la globalizaci\u00f3n y de los distintos tratados de libre comercio que Canad\u00e1 tiene con diversos pa\u00edses.<\/p>\n<p>Yo creo que en la pr\u00e1ctica lo que se est\u00e1 utilizando en este momento en Canad\u00e1 es la segunda teor\u00eda, que es la de importar trabajadores temporales para posiciones de servicios o trabajos que se tienen que hacer en Canad\u00e1, y por eso hemos visto un crecimiento grande de trabajadores temporales. Pero tambi\u00e9n hemos visto la imposici\u00f3n de un nivel m\u00ednimo de idioma para que las personas puedan calificar para obtener la residencia permanente, con lo que queda claro que s\u00f3lo los queremos traer a Canad\u00e1 para usarlos mientras los utilicemos y despu\u00e9s sacarlos del pa\u00eds. Esto aunado a lo que estamos viendo de subcontratar fuera del pa\u00eds como es el caso de estos 45 trabajos del Royal Bank of Canada que van a estar siendo enviados a la India.<\/p>\n<p>Y as\u00ed como estos 45 trabajos vemos que hay much\u00edsimas compa\u00f1\u00edas que est\u00e1n subcontratando fuera del pa\u00eds todo tipo de servicios, lo que refleja que el problema realmente no est\u00e1 en la cantidad de trabajadores temporales que traigamos sino que m\u00e1s bien en el hecho de que, hoy por hoy, el gobierno s\u00f3lo est\u00e1 creando pol\u00edticas para beneficio de las compa\u00f1\u00edas y de sus ganancias, y no para beneficio de los trabajadores canadiense y mucho menos para los trabajadores temporales que llegan al pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Vilma Filici vilma@filici.com TORONTO. Con mucho inter\u00e9s he venido d\u00e1ndole seguimiento a las noticias sobre las actuaciones del Royal Bank of Canad\u00e1 y la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,81,25,290],"tags":[2574,77,2575],"class_list":["post-448367","post","type-post","status-publish","format-standard","hentry","category-canada","category-columnistas","category-inmigracion","category-inmigrando-a-canada","tag-a","tag-canada-2","tag-inmigrando"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/448367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=448367"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/448367\/revisions"}],"predecessor-version":[{"id":451397,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/448367\/revisions\/451397"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=448367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=448367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=448367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}