{"id":448520,"date":"2013-04-24T01:05:16","date_gmt":"2013-04-24T05:05:16","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=448520"},"modified":"2013-06-17T18:28:47","modified_gmt":"2013-06-17T22:28:47","slug":"inmigrando-a-canada-32","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2013\/04\/24\/inmigrando-a-canada-32\/","title":{"rendered":"INMIGRANDO A CANADA"},"content":{"rendered":"<p>Por Vilma Filici<\/p>\n<p>vilma@filici.com<\/p>\n<p>TORONTO. El pasado 18 de abril, el Ministro de Inmigraci\u00f3n y Ciudadan\u00eda, Jason Kenney, hizo un anuncio que hab\u00edamos estado esperando desde hace varios meses en relaci\u00f3n al Programa de Trabajadores Calificados (el Foreign Skilled Workers Program), el cual comenzar\u00e1 a funcionar nuevamente a partir del cuatro de Mayo de este a\u00f1o.<\/p>\n<p>Lo que se estaba esperando era la lista de ocupaciones que van a estar abiertas para que las personas puedan hacer su tr\u00e1mite de residencia permanente sin necesidad de una oferta de trabajo, as\u00ed como tambi\u00e9n la lista de las instituciones educacionales designadas por el gobierno para que puedan hacer la evaluaci\u00f3n de las calificaciones de las personas que van a solicitar la residencia permanente en Canad\u00e1.<\/p>\n<p>Como ya lo hemos dicho muchas veces en columnas anteriores, el nuevo Programa de Trabajadores Calificados comenzar\u00e1 el cuatro de Mayo con importantes cambios en los factores que deben ser sumados para obtener el puntaje necesario para obtener la residencia permanente.<\/p>\n<p>Uno de los cambios es la edad. Las personas deber\u00e1n tener entre 18 y 35 a\u00f1os para poder obtener el puntaje m\u00e1ximo en t\u00e9rminos de edad, lo que significa que antes de los 18 y despu\u00e9s de los 35 la persona va a ir perdiendo puntos hasta quedar en cero en este factor edad.<\/p>\n<p>Otro de los cambios importantes es que con el nuevo programa el ingl\u00e9s va\u00a0 a ser evaluado dos veces. La primera vez ser\u00e1 a trav\u00e9s de un examen, y la persona deber\u00e1 tener un m\u00ednimo de siete, que es un nivel bastante alto, como requisito m\u00ednimo para poder procesar la solicitud de residencia permanente.<\/p>\n<p>Adem\u00e1s, la persona deber\u00e1 tener experiencia de trabajo continua por un m\u00ednimo de un a\u00f1o en la ocupaci\u00f3n en la que va a hacer la solicitud, y dicha experiencia de trabajo deber\u00e1 ser durante los \u00faltimos diez a\u00f1os.<\/p>\n<p>Para poder hacer la solicitud la persona deber\u00e1 tener una ocupaci\u00f3n que aparezca bajo los \u00a0c\u00f3digos \u201c0\u201d, \u201cA\u201d, o \u201cB\u201d de la Clasificaci\u00f3n Nacional de Ocupaciones (National Occupation Classification, NOC) y deber\u00e1 tener una de las 24 ocupaciones que aparecen en la lista o tener una oferta de trabajo que haya sido aprobada por el Departamento de Recursos Humanos de Canad\u00e1.<\/p>\n<p>Si no cumple aunque sea uno de estos requisitos no puede hacer la solicitud.<\/p>\n<p>Un dato importante es que el nivel de ingl\u00e9s requerido es un requisito b\u00e1sico, pero despu\u00e9s tambi\u00e9n cuenta como uno de los factores que se suma para ver si la persona tiene el puntaje necesario para iniciar el proceso, que es 67 puntos.<\/p>\n<p>Las 24 ocupaciones que est\u00e1n en la lista en su mayor\u00eda est\u00e1n relacionadas con las \u00e1reas de ingenier\u00eda y tecnolog\u00eda m\u00e9dica, y son:<\/p>\n<p>Directores en servicios de ingenier\u00eda, Analistas financieros y de inversi\u00f3n, Geocient\u00edficos y ocean\u00f3grafos, Ingenieros civiles, Ingenieros mec\u00e1nicos, Ingenieros qu\u00edmicos, Ingenieros mineros, Ingenieros ge\u00f3logos, Ingenieros aeroespaciales, Ingenieros inform\u00e1ticos (sin incluir los dise\u00f1adores de software), Agrimensor, Programadores en computaci\u00f3n y desarrolladores de medios interactivos, T\u00e9cnicos en mec\u00e1nica de instrumentos industriales, Inspectores en salud p\u00fablica, del ambiente y de higiene y de la seguridad en el trabajo, Audi\u00f3logos y ortofonistas, Fisioterapeutas, Ergoterapeutas, Tecn\u00f3logo de laboratorios m\u00e9dicos, T\u00e9cnico de laboratorio m\u00e9dico y asistente en patolog\u00eda, Inhaloterapeuta, perfusionista cardiovascular y tecn\u00f3logos cardiopulmonares, Tecn\u00f3logo en radiaci\u00f3n m\u00e9dica, Tecn\u00f3logo en ecograf\u00eda, y Tecn\u00f3logo en cardiolog\u00eda y tecn\u00f3logos en diagn\u00f3stico electrofisiol\u00f3gico<\/p>\n<p>Es importante tener en cuenta que en el momento en que se env\u00ede la solicitud para la residencia permanente se deber\u00e1 enviar tambi\u00e9n la evaluaci\u00f3n de la credencial educacional obtenida en el pa\u00eds del cual viene la persona, y que se tiene que hacer una comparaci\u00f3n de \u00e9sta a trav\u00e9s \u00a0de una instituci\u00f3n educacional canadiense.<\/p>\n<p>Para las \u00e1reas de ingenier\u00eda y tecnolog\u00eda m\u00e9dica el gobierno ha elegido instituciones que se especializan en estas \u00e1reas, como por ejemplo el Consejo M\u00e9dico de Canad\u00e1, el Servicio de Educaci\u00f3n Comparativa de la Universidad de Toronto, el Servicio de Evaluaci\u00f3n de Credenciales Internacionales del Departamento de Recursos Humanos de Canad\u00e1, y el Servicios de Educaci\u00f3n Mundial (World Education Services, WES).<\/p>\n<p>Resumiendo. Para que una persona pueda enviar la solicitud de residencia permanente a Inmigraci\u00f3n, primeramente debe hacer una evaluaci\u00f3n para ver si cumple con el puntaje necesario al ser sumados todos los factores.<\/p>\n<p>Luego, se tiene que asegurar que cumple con los requisitos m\u00ednimos, y para ello tiene que hacerse el examen de ingl\u00e9s y hacer la evaluaci\u00f3n de sus credenciales en una de las instituciones mencionadas arriba. Si no cumple con todos estos requisitos definitivamente no puede presentar la solicitud.<\/p>\n<p>Otro dato importante es que el Ministro Kenney dijo en su anuncio que las evaluaciones deber\u00edan ser hechas hasta despu\u00e9s del 17 de abril, porque de lo contrario ser\u00eda injusto dado que s\u00f3lo hay un cupo cinco mil posiciones (aproximadamente 300 para cada una de las ocupaciones). En este sentido, las evaluaciones deben estar fechadas despu\u00e9s de abril 17 del 2013, y las mismas van a tener una validez de cinco a\u00f1os desde el momento en que hayan sido otorgadas.<\/p>\n<p>Visto todo lo anterior, las personas que est\u00e9n interesadas en solicitar la residencia permanente bajo este nuevo programa, y que tengan una de estas 24 ocupaciones, es importante que se aseguren no solamente de hacer la evaluaci\u00f3n para ver si llegan a los 67 puntos necesarios, sino que tambi\u00e9n se aseguren de que cumplen con todos los requisitos para el programa, particularmente del nivel requerido de ingl\u00e9s, que es una de las \u00e1rea donde presentan m\u00e1s problemas las personas de origen latinoamericano que quieren inmigrar a Canad\u00e1.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Vilma Filici vilma@filici.com TORONTO. El pasado 18 de abril, el Ministro de Inmigraci\u00f3n y Ciudadan\u00eda, Jason Kenney, hizo un anuncio que hab\u00edamos estado esperando&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,81,25,290],"tags":[2574,77,2575],"class_list":["post-448520","post","type-post","status-publish","format-standard","hentry","category-canada","category-columnistas","category-inmigracion","category-inmigrando-a-canada","tag-a","tag-canada-2","tag-inmigrando"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/448520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=448520"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/448520\/revisions"}],"predecessor-version":[{"id":451396,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/448520\/revisions\/451396"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=448520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=448520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=448520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}