{"id":476776,"date":"2018-03-24T10:59:29","date_gmt":"2018-03-24T14:59:29","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=476776"},"modified":"2018-03-24T10:59:29","modified_gmt":"2018-03-24T14:59:29","slug":"los-estudiantes-de-jalisco-se-organizan-para-exigir-a-las-autoridades-un-alto-a-la-violencia","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/03\/24\/los-estudiantes-de-jalisco-se-organizan-para-exigir-a-las-autoridades-un-alto-a-la-violencia\/","title":{"rendered":"Los estudiantes de Jalisco se organizan para exigir a las autoridades un alto a la violencia"},"content":{"rendered":"<div id=\"attachment_476777\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/03\/1521834967_960320_1521835172_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-476777\" class=\"size-large wp-image-476777\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/03\/1521834967_960320_1521835172_noticia_normal_recorte1-560x370.jpg\" alt=\"Dos j\u00f3venes marchan en solidaridad con sus compa\u00f1eros desaparecidos. \" width=\"560\" height=\"370\" \/><\/a><p id=\"caption-attachment-476777\" class=\"wp-caption-text\">Dos j\u00f3venes marchan en solidaridad con sus compa\u00f1eros desaparecidos.<\/p><\/div>\n<p style=\"font-style: inherit\">Los estudiantes han arremetido contra las autoridades para exigir un alto a la violencia.\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/03\/22\/mexico\/1521744565_067870.html\" target=\"_blank\">La desaparici\u00f3n de cuatro j\u00f3venes en Jalisco en la \u00faltima semana<\/a>\u00a0ha desatado una serie de movilizaciones y actos de protesta en contra de la inseguridad en el Estado. La Federaci\u00f3n de Estudiantes de la Universidad de Guadalajara (UdG) realiz\u00f3 un paro de labores este viernes, al que se sumaron otras instituciones como el instituto Tecnol\u00f3gico y de Estudios Superiores de Occidente (ITESO) y la Universidad de Medios Audiovisuales (CAAV). &#8220;<span style=\"font-style: inherit\">Los j\u00f3venes en M\u00e9xico somos las principales v\u00edctimas de la desaparici\u00f3n forzada, nos est\u00e1n desapareciendo y nos est\u00e1n arrebatando nuestro futuro&#8221;, dijo una integrante del Movimiento Estudiantil del CAAV.\u00a0<\/span>Los alumnos han convocado una asamblea estudiantil para este viernes y otra manifestaci\u00f3n el s\u00e1bado.<\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"font-style: inherit\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">El lunes pasado, Salom\u00f3n Aceves Gast\u00e9lum, de 25 a\u00f1os; Daniel D\u00edaz y Marco Avalos, ambos de 20 a\u00f1os, fueron raptados por un grupo de hombres armados cuando terminaban de realizar una grabaci\u00f3n en\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/jalisco\/a\" target=\"_blank\">Tonal\u00e1, una localidad de la zona metropolitana de Guadalajara<\/a>. Los estudiantes de cine viajaban en compa\u00f1\u00eda de otros tres amigos y hab\u00edan acudido a esa zona a realizar una tarea escolar. En el camino de regreso a Guadalajara se detuvieron a atender una falla mec\u00e1nica y fueron rodeados por dos coches de los que bajaron los empistolados para llevarse a los tres chicos.<\/div>\n<\/div>\n<div id=\"inread1\" style=\"font-style: inherit\">\u00a0C\u00e9sar Ulises Arellano, que cursa el segundo semestre de Medicina en la Universidad de Guadalajara, desapareci\u00f3 tambi\u00e9n el pasado lunes.\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/c\/7d38ddd846cdf7da4731b0fc86ca35b1\" target=\"_blank\">El \u00faltimo reporte que sus familiares ten\u00edan de \u00e9l era que hab\u00eda sido visto<\/a>\u00a0frente a una cl\u00ednica del IMSS (el instituto de sanidad mexicano) en la localidad de Tala, en la regi\u00f3n Valles de Jalisco. El gobernador del Estado, Arist\u00f3teles Sandoval, inform\u00f3 en una conferencia de prensa que contin\u00faan con las indagatorias y ofreci\u00f3 una recompensa de un mill\u00f3n de pesos (54.000 d\u00f3lares) a quien brinde informaci\u00f3n para dar con su paradero. En el caso donde hay una pista es en el de Ulises Arellano. Se sabe que sali\u00f3 de Tala y lleg\u00f3 Guadalajara, donde estuvo subiendo y bajando de varios camiones de macrob\u00fas de una manera &#8220;intraquila&#8221;, dijo el fiscal general, Ra\u00fal S\u00e1nchez Jim\u00e9nez en una conferencia de prensa.<\/div>\n<p style=\"font-style: inherit\">Ante el hartazgo por la violencia, los estudiantes han comenzado a organizarse para elevar la exigencia al Gobierno estatal y federal. Una alumna de la Universidad de Medios Audiovisuales (CAAV), donde estudian los tres j\u00f3venes raptados en Tonal\u00e1, considera que las autoridades han tardado en reaccionar ante los hechos. &#8220;Nos sentimos vulnerables por ser j\u00f3venes viviendo en M\u00e9xico (&#8230;) Ser joven en este pa\u00eds es un peligro porque nadie nos protege y porque las personas que est\u00e1n en el poder siempre que un amigo desaparece nos preguntan en qu\u00e9 estaba metido&#8221;, expone otra estudiante del movimiento estudiantil del CAAV.<\/p>\n<section id=\"sumario_5|html\" class=\"sumario_html centro\" style=\"font-style: inherit\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_5\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"SandboxRoot env-bp-350\" style=\"color: #1c2022\">\n<div id=\"twitter-widget-0\" class=\"EmbeddedTweet EmbeddedTweet--edge EmbeddedTweet--mediaForward media-forward js-clickToOpenTarget js-tweetIdInfo tweet-InformationCircle-widgetParent\" lang=\"es\">\n<article class=\"MediaCard\n           MediaCard--mediaForward\n\n           customisable-border\" dir=\"ltr\"><\/p>\n<div class=\"MediaCard-mediaContainer js-cspForcedStyle\">\n<div class=\"MediaCard-mediaAsset ImageGrid ImageGrid--3 ImageGrid--roundedTop\"><a class=\"ImageGrid-image ImageGrid-image-0 CroppedImage CroppedImage--fillHeight\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/caavuniversidad\/status\/977269953610076161\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"CroppedImage-image js-cspForcedStyle\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY_zCseVMAAjvcA?format=jpg&amp;name=360x360\" alt=\"Ver imagen en Twitter\" width=\"1200\" height=\"898\" \/><\/a><a class=\"ImageGrid-image ImageGrid-image-1 CroppedImage CroppedImage--fillWidth\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/caavuniversidad\/status\/977269953610076161\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"CroppedImage-image js-cspForcedStyle\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY_1qbnU8AAsYLv?format=jpg&amp;name=360x360\" alt=\"Ver imagen en Twitter\" width=\"1200\" height=\"898\" \/><\/a><a class=\"ImageGrid-image ImageGrid-image-2 CroppedImage CroppedImage--fillWidth\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/caavuniversidad\/status\/977269953610076161\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"CroppedImage-image js-cspForcedStyle\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY_1yx8U0AER-zE?format=jpg&amp;name=360x360\" alt=\"Ver imagen en Twitter\" width=\"1200\" height=\"898\" \/><\/a><\/div>\n<\/div>\n<\/article>\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/caavuniversidad\/status\/977269953610076161\">\n<div class=\"Tweet-header u-cf\">\n<div class=\"Tweet-brand u-floatRight\"><\/div>\n<div class=\"TweetAuthor js-inViewportScribingTarget\"><a class=\"TweetAuthor-link Identity u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/caavuniversidad\"><span class=\"TweetAuthor-avatar Identity-avatar\"><img decoding=\"async\" class=\"Avatar Avatar--edge\" src=\"https:\/\/pbs.twimg.com\/profile_images\/963439851235303424\/VwOueb2D_normal.jpg\" alt=\"\" \/><\/span><span class=\"TweetAuthor-decoratedName\"><span class=\"TweetAuthor-name Identity-name customisable-highlight\" style=\"font-weight: bold\" title=\"CAAV\">CAAV<\/span><\/span><span class=\"TweetAuthor-screenName Identity-screenName\" dir=\"ltr\" style=\"color: #697882\" title=\"@caavuniversidad\">@caavuniversidad<\/span><\/a><\/div>\n<\/div>\n<div class=\"Tweet-body e-entry-content\">\n<div class=\"u-hiddenVisually js-inViewportScribingTarget\"><\/div>\n<p class=\"Tweet-text e-entry-title\" dir=\"ltr\" lang=\"es\">Sum\u00e1ndonos al paro de <a class=\"PrettyLink profile customisable h-card\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/ITESO\"><span class=\"PrettyLink-prefix\">@<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">ITESO<\/span><\/a> y <a class=\"PrettyLink profile customisable h-card\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/udg_oficial\"><span class=\"PrettyLink-prefix\">@<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">udg_oficial<\/span><\/a> la comunidad de alumnos, profesores y directivos nos reunimos para reflexionar sobre los sucesos que estamos viviendo. <a class=\"PrettyLink hashtag customisable\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/hashtag\/NoSomosTresSomosTodxs?src=hash\" rel=\"tag\"><span class=\"PrettyLink-prefix\">#<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">NoSomosTresSomosTodxs<\/span><\/a><\/p>\n<div class=\"Tweet-metadata dateline\" style=\"color: #697882\"><a class=\"u-linkBlend u-url customisable-highlight long-permalink\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/caavuniversidad\/status\/977269953610076161\">15:44 &#8211; 23 mar. 2018<\/a><\/div>\n<ul class=\"Tweet-actions Tweet-action--newsActions\">\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--heartEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--heart TweetAction TweetAction--heartEdge\" style=\"color: #697882\" title=\"Me gusta\" href=\"https:\/\/twitter.com\/intent\/like?tweet_id=977269953610076161\"><span class=\"TweetAction-stat\">20<\/span><\/a><\/li>\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--replyEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--replyEdge TweetAction TweetAction--replyEdge\" style=\"color: #697882\" title=\"Ver la conversaci\u00f3n en Twitter\" href=\"https:\/\/twitter.com\/caavuniversidad\/status\/977269953610076161\"><span class=\"TweetAction-stat\">17 personas est\u00e1n hablando de esto<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/blockquote>\n<\/div>\n<div class=\"tweet-InformationCircle--top tweet-InformationCircle--topEdge tweet-InformationCircle\"><a class=\"Icon Icon--informationCircleWhite js-inViewportScribingTarget\" style=\"color: #2b7bb9\" title=\"Informaci\u00f3n y privacidad de Twitter Ads\" href=\"https:\/\/support.twitter.com\/articles\/20175256\"><span class=\"u-hiddenVisually\">Informaci\u00f3n y privacidad de Twitter Ads<\/span><\/a><\/div>\n<\/div>\n<div class=\"resize-sensor\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p style=\"font-style: inherit\">La Federaci\u00f3n de Estudiantes de la Universidad de Guadalajara (UdG) realiz\u00f3 la tarde del viernes un paro de labores para manifestar su indignaci\u00f3n por\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/c\/7d38ddd846cdf7da4731b0fc86ca35b1\" target=\"_blank\">las recientes desapariciones<\/a>. Jes\u00fas Medina, presidente de la Federaci\u00f3n, dijo que en la UdeG detendr\u00edan actividades unos 275.000 estudiantes de todo el Estado, 15.500 acad\u00e9micos y 7.500 directivos y personal administrativo. \u201cEl paro es en solidaridad y bajo la consigna de que los queremos vivos. Si no nos movilizamos estos casos seguir\u00e1n como una cifra m\u00e1s\u201d, dice el joven. El ITESO y el CAAV tambi\u00e9n se sumaron a la iniciativa.<\/p>\n<section id=\"sumario_1|html\" class=\"sumario_html centro\" style=\"font-style: inherit\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_1\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"SandboxRoot env-bp-350\" style=\"color: #1c2022\">\n<div id=\"twitter-widget-1\" class=\"EmbeddedTweet EmbeddedTweet--edge EmbeddedTweet--mediaForward media-forward js-clickToOpenTarget js-tweetIdInfo tweet-InformationCircle-widgetParent\" lang=\"es\">\n<article class=\"MediaCard\n           MediaCard--mediaForward\n\n           customisable-border\" dir=\"ltr\"><\/p>\n<div class=\"MediaCard-mediaContainer js-cspForcedStyle\">\n<div class=\"MediaCard-mediaAsset ImageGrid ImageGrid--3 ImageGrid--roundedTop\"><a class=\"ImageGrid-image ImageGrid-image-0 CroppedImage CroppedImage--fillHeight\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/alumnositeso\/status\/977266976837001216\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"CroppedImage-image js-cspForcedStyle\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY_yzqlVwAA_OYB?format=jpg&amp;name=360x360\" alt=\"Ver imagen en Twitter\" width=\"1024\" height=\"768\" \/><\/a><a class=\"ImageGrid-image ImageGrid-image-1 CroppedImage CroppedImage--fillWidth\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/alumnositeso\/status\/977266976837001216\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"CroppedImage-image js-cspForcedStyle\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY_yzqlU8AAMyeM?format=jpg&amp;name=360x360\" alt=\"Ver imagen en Twitter\" width=\"1024\" height=\"768\" \/><\/a><a class=\"ImageGrid-image ImageGrid-image-2 CroppedImage CroppedImage--fillWidth\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/alumnositeso\/status\/977266976837001216\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"CroppedImage-image js-cspForcedStyle\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY_yzqmV4AA8-BQ?format=jpg&amp;name=360x360\" alt=\"Ver imagen en Twitter\" width=\"1024\" height=\"768\" \/><\/a><\/div>\n<\/div>\n<\/article>\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/alumnositeso\/status\/977266976837001216\">\n<div class=\"Tweet-header u-cf\">\n<div class=\"Tweet-brand u-floatRight\"><\/div>\n<div class=\"TweetAuthor js-inViewportScribingTarget\"><a class=\"TweetAuthor-link Identity u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/alumnositeso\"><span class=\"TweetAuthor-avatar Identity-avatar\"><img decoding=\"async\" class=\"Avatar Avatar--edge\" src=\"https:\/\/pbs.twimg.com\/profile_images\/2496200369\/lwf86o3j6wlwajhwi98x_normal.jpeg\" alt=\"\" \/><\/span><span class=\"TweetAuthor-decoratedName\"><span class=\"TweetAuthor-name Identity-name customisable-highlight\" style=\"font-weight: bold\" title=\"Alumnos ITESO\">Alumnos ITESO<\/span><\/span><span class=\"TweetAuthor-screenName Identity-screenName\" dir=\"ltr\" style=\"color: #697882\" title=\"@alumnositeso\">@alumnositeso<\/span><\/a><\/div>\n<\/div>\n<div class=\"Tweet-body e-entry-content\">\n<div class=\"u-hiddenVisually js-inViewportScribingTarget\"><\/div>\n<p class=\"Tweet-text e-entry-title\" dir=\"ltr\" lang=\"es\">Comienza el paro activo <a class=\"PrettyLink hashtag customisable\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/hashtag\/HastaEncontrARTE?src=hash\" rel=\"tag\"><span class=\"PrettyLink-prefix\">#<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">HastaEncontrARTE<\/span><\/a> en <a class=\"PrettyLink profile customisable h-card\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/ITESO\"><span class=\"PrettyLink-prefix\">@<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">ITESO<\/span><\/a> con una charla de reflexi\u00f3n sobre el tema de desaparecidos a nivel estatal.<a class=\"PrettyLink hashtag customisable\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/hashtag\/NoSonTresSomosTodxs?src=hash\" rel=\"tag\"><span class=\"PrettyLink-prefix\">#<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">NoSonTresSomosTodxs<\/span><\/a><\/p>\n<div class=\"Tweet-metadata dateline\" style=\"color: #697882\"><a class=\"u-linkBlend u-url customisable-highlight long-permalink\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/alumnositeso\/status\/977266976837001216\">15:32 &#8211; 23 mar. 2018<\/a><\/div>\n<ul class=\"Tweet-actions Tweet-action--newsActions\">\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--heartEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--heart TweetAction TweetAction--heartEdge\" style=\"color: #697882\" title=\"Me gusta\" href=\"https:\/\/twitter.com\/intent\/like?tweet_id=977266976837001216\"><span class=\"TweetAction-stat\">43<\/span><\/a><\/li>\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--replyEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--replyEdge TweetAction TweetAction--replyEdge\" style=\"color: #697882\" title=\"Ver la conversaci\u00f3n en Twitter\" href=\"https:\/\/twitter.com\/alumnositeso\/status\/977266976837001216\"><span class=\"TweetAction-stat\">47 personas est\u00e1n hablando de esto<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/blockquote>\n<\/div>\n<div class=\"tweet-InformationCircle--top tweet-InformationCircle--topEdge tweet-InformationCircle\"><a class=\"Icon Icon--informationCircleWhite js-inViewportScribingTarget\" style=\"color: #2b7bb9\" title=\"Informaci\u00f3n y privacidad de Twitter Ads\" href=\"https:\/\/support.twitter.com\/articles\/20175256\"><span class=\"u-hiddenVisually\">Informaci\u00f3n y privacidad de Twitter Ads<\/span><\/a><\/div>\n<\/div>\n<div class=\"resize-sensor\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p style=\"font-style: inherit\">En la Universidad de Guadalajara, la segunda instituci\u00f3n educativa m\u00e1s grande del pa\u00eds, la Federaci\u00f3n document\u00f3 el a\u00f1o pasado que hubo 500 incidentes delictivos (como asaltos, hostigamientos y casos de acoso) en las inmediaciones a los planteles de la zona metropolitana. \u201cEn el Estado en lo que va de marzo han ocurrido\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/02\/21\/mexico\/1519242722_897326.html\" target=\"_blank\">125 homicidios dolosos<\/a>, es decir, cada tres horas asesinan a una persona de forma violenta, y vemos que dinero para las campa\u00f1as s\u00ed hay, pero no para la seguridad de las personas\u201d, expone Medina.<\/p>\n<p style=\"font-style: inherit\">El viernes por la tarde tienen programada una asamblea donde planear\u00e1n las acciones a seguir a fin de continuar con la presi\u00f3n a las autoridades para que encuentren a sus compa\u00f1eros. \u201cEstamos viviendo\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/c\/9db9f63693348f232b365791d44d7db8\" target=\"_blank\">la c\u00faspide de la violencia<\/a>, entre asesinatos y compa\u00f1eros desaparecidos, y necesitamos ponernos de acuerdo para acordar c\u00f3mo nos vamos a cuidar y como vamos a mantener el movimiento visible\u201d, menciona. El s\u00e1bado est\u00e1 contemplada una marcha, a la que se sumar\u00e1n estudiantes en otros Estados del pa\u00eds.<\/p>\n<section id=\"sumario_6|html\" class=\"sumario_html centro\" style=\"font-style: inherit\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_6\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"SandboxRoot env-bp-350\" style=\"color: #1c2022\">\n<div id=\"twitter-widget-2\" class=\"EmbeddedTweet EmbeddedTweet--edge EmbeddedTweet--mediaForward media-forward js-clickToOpenTarget js-tweetIdInfo tweet-InformationCircle-widgetParent\" lang=\"es\">\n<article class=\"MediaCard\n           MediaCard--mediaForward\n\n           customisable-border\" dir=\"ltr\"><\/p>\n<div class=\"MediaCard-media\"><a class=\"MediaCard-borderOverlay\" style=\"color: #2b7bb9\" title=\"Ver imagen en Twitter\" href=\"https:\/\/twitter.com\/19mEstudiantes\/status\/976993738785353728\/photo\/1\"><span class=\"u-hiddenVisually\">Ver imagen en Twitter<\/span><\/a><\/p>\n<div class=\"MediaCard-widthConstraint js-cspForcedStyle\">\n<div class=\"MediaCard-mediaContainer js-cspForcedStyle\"><a class=\"MediaCard-mediaAsset NaturalImage\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/19mEstudiantes\/status\/976993738785353728\/photo\/1\"><img loading=\"lazy\" decoding=\"async\" class=\"NaturalImage-image\" title=\"Ver imagen en Twitter\" src=\"https:\/\/pbs.twimg.com\/media\/DY76nqoUQAA2_rA?format=jpg&amp;name=small\" alt=\"Ver imagen en Twitter\" width=\"927\" height=\"1200\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/19mEstudiantes\/status\/976993738785353728\">\n<div class=\"Tweet-header u-cf\">\n<div class=\"Tweet-brand u-floatRight\"><\/div>\n<div class=\"TweetAuthor js-inViewportScribingTarget\"><a class=\"TweetAuthor-link Identity u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/19mEstudiantes\"><span class=\"TweetAuthor-avatar Identity-avatar\"><img decoding=\"async\" class=\"Avatar Avatar--edge\" src=\"https:\/\/pbs.twimg.com\/profile_images\/976627475605176320\/elBEkaEf_normal.jpg\" alt=\"\" \/><\/span><span class=\"TweetAuthor-decoratedName\"><span class=\"TweetAuthor-name Identity-name customisable-highlight\" style=\"font-weight: bold\" title=\"#LosTresEstudiantesDeCine\">#LosTresEstudiantesDeCine<\/span><\/span><span class=\"TweetAuthor-screenName Identity-screenName\" dir=\"ltr\" style=\"color: #697882\" title=\"@19mEstudiantes\">@19mEstudiantes<\/span><\/a><\/div>\n<\/div>\n<div class=\"Tweet-body e-entry-content\">\n<div class=\"u-hiddenVisually js-inViewportScribingTarget\"><\/div>\n<p class=\"Tweet-text e-entry-title\" dir=\"ltr\" lang=\"es\">\u00a1Hagamos ruido! Esto ya no es asunto tapat\u00edo. Es un problema nacional y debe ser escuchado. Nuestros compa\u00f1eros son for\u00e1neos tambi\u00e9n. Esto nos incluye a todos. <a class=\"PrettyLink hashtag customisable\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/hashtag\/LosTresEstudiantesDeCine?src=hash\" rel=\"tag\"><span class=\"PrettyLink-prefix\">#<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">LosTresEstudiantesDeCine<\/span><\/a> <a class=\"PrettyLink hashtag customisable\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/hashtag\/NoSonTresSomosTodxs?src=hash\" rel=\"tag\"><span class=\"PrettyLink-prefix\">#<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">NoSonTresSomosTodxs<\/span><\/a> <a class=\"PrettyLink hashtag customisable\" style=\"color: #2b7bb9\" href=\"https:\/\/twitter.com\/hashtag\/Vivoslosqueremos?src=hash\" rel=\"tag\"><span class=\"PrettyLink-prefix\">#<\/span><span class=\"PrettyLink-value Tweet-prettyLink\">Vivoslosqueremos<\/span><\/a><\/p>\n<div class=\"Tweet-metadata dateline\" style=\"color: #697882\"><a class=\"u-linkBlend u-url customisable-highlight long-permalink\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/19mEstudiantes\/status\/976993738785353728\">21:27 &#8211; 22 mar. 2018<\/a><\/div>\n<ul class=\"Tweet-actions Tweet-action--newsActions\">\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--heartEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--heart TweetAction TweetAction--heartEdge\" style=\"color: #697882\" title=\"Me gusta\" href=\"https:\/\/twitter.com\/intent\/like?tweet_id=976993738785353728\"><span class=\"TweetAction-stat\">170<\/span><\/a><\/li>\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--replyEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--replyEdge TweetAction TweetAction--replyEdge\" style=\"color: #697882\" title=\"Ver la conversaci\u00f3n en Twitter\" href=\"https:\/\/twitter.com\/19mEstudiantes\/status\/976993738785353728\"><span class=\"TweetAction-stat\">288 personas est\u00e1n hablando de esto<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/blockquote>\n<\/div>\n<div class=\"tweet-InformationCircle--top tweet-InformationCircle--topEdge tweet-InformationCircle\"><a class=\"Icon Icon--informationCircleWhite js-inViewportScribingTarget\" style=\"color: #2b7bb9\" title=\"Informaci\u00f3n y privacidad de Twitter Ads\" href=\"https:\/\/support.twitter.com\/articles\/20175256\"><span class=\"u-hiddenVisually\">Informaci\u00f3n y privacidad de Twitter Ads<\/span><\/a><\/div>\n<\/div>\n<div class=\"resize-sensor\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p style=\"font-style: inherit\">El Alto Comisionado de la ONU para los Derechos Humanos se sum\u00f3 en la exigencia a las autoridades de dar con el paradero de los j\u00f3venes. \u201cNos solidarizamos con la comunidad universitaria de Jalisco por la desaparici\u00f3n de Javier Salom\u00f3n Aceves, Daniel D\u00edaz y Marco \u00c1valos, estudiantes de cine de la Universidad de Medios Audiovisuales CAAV, ocurrida la noche del lunes 19 de marzo en Tonal\u00e1, Jalisco\u201d, escribi\u00f3 el organismo en su cuenta de Twitter.<\/p>\n<section id=\"sumario_3|html\" class=\"sumario_html centro\" style=\"font-style: inherit\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_3\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"SandboxRoot env-bp-350\" style=\"color: #1c2022\">\n<div id=\"twitter-widget-3\" class=\"EmbeddedTweet EmbeddedTweet--edge js-clickToOpenTarget tweet-InformationCircle-widgetParent\" lang=\"es\">\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/ONUDHmexico\/status\/976972316478287872\">\n<div class=\"Tweet-header u-cf\">\n<div class=\"Tweet-brand u-floatRight\"><\/div>\n<div class=\"TweetAuthor js-inViewportScribingTarget\"><span class=\"TweetAuthor-avatar Identity-avatar\" style=\"color: inherit\"><a class=\"TweetAuthor-link Identity u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/ONUDHmexico\"><img decoding=\"async\" class=\"Avatar Avatar--edge\" src=\"https:\/\/pbs.twimg.com\/profile_images\/944014685572960256\/2NCjU9Af_normal.jpg\" alt=\"\" \/><\/a><\/span>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>La desaparici\u00f3n de cuatro j\u00f3venes en la \u00faltima semana ha desatado una serie de movilizaciones encabezadas por los universitarios<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-476776","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=476776"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476776\/revisions"}],"predecessor-version":[{"id":476778,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476776\/revisions\/476778"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=476776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=476776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=476776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}