{"id":476795,"date":"2018-03-24T17:36:03","date_gmt":"2018-03-24T21:36:03","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=476795"},"modified":"2018-03-24T17:36:03","modified_gmt":"2018-03-24T21:36:03","slug":"la-justicia-peruana-registra-dos-casas-del-expresidente-kuczynski-y-le-prohibe-la-salida-del-pais","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/03\/24\/la-justicia-peruana-registra-dos-casas-del-expresidente-kuczynski-y-le-prohibe-la-salida-del-pais\/","title":{"rendered":"La justicia peruana registra dos casas del expresidente Kuczynski y le proh\u00edbe la salida del pa\u00eds"},"content":{"rendered":"<div id=\"attachment_476796\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/03\/1521919329_268256_1521919513_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-476796\" class=\"size-large wp-image-476796\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/03\/1521919329_268256_1521919513_noticia_normal_recorte1-560x373.jpg\" alt=\"La polic\u00eda peruana durante el registro de una de las casas del expresidente Kuczynski\" width=\"560\" height=\"373\" \/><\/a><p id=\"caption-attachment-476796\" class=\"wp-caption-text\">La polic\u00eda peruana durante el registro de una de las casas del expresidente Kuczynski<\/p><\/div>\n<p style=\"color: #444444\">Apenas un d\u00eda despu\u00e9s de que el Congreso aceptara\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/03\/21\/america\/1521651903_028672.html\" target=\"_blank\">la carta de renuncia del presidente Pedro Pablo Kuczynski,<\/a>\u00a0un juez del sistema de corrupci\u00f3n de funcionarios ha dictado este s\u00e1bado una orden de arraigo por 18 meses que impedir\u00e1 al exmandatario la salida del pa\u00eds. Durante ese plazo se llevar\u00e1 a cabo la investigaci\u00f3n por los supuestos pagos que Odebrecht realiz\u00f3 a empresas ligadas con el expresidente y su socio Gerardo Sep\u00falveda durante la \u00e9poca en que Kuczynski era ministro de la administraci\u00f3n de Alejandro Toledo, quien se encuentra en busca y captura por su implicaci\u00f3n en el caso de la constructora brasile\u00f1a.<\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">La ma\u00f1ana del s\u00e1bado, en la audiencia conducida por el juez Juan Carlos S\u00e1nchez Balbuena, el fiscal Hamilton Castro, cabeza del equipo de tarea Lava Jato, defendi\u00f3 el pedido de impedimento de salida alegando no solo una raz\u00f3n judicial sino la historia reciente peruana. &#8220;Desde el siglo pasado vemos el triste espect\u00e1culo de los presidentes que se van del pa\u00eds y nunca m\u00e1s regresan, o esperan los pedidos de extradici\u00f3n, y otros retornan cuando las acciones penales han prescrito. Eso no debe repetirse nunca m\u00e1s en el Per\u00fa&#8221;, afirm\u00f3 Castro.<\/div>\n<\/div>\n<div id=\"inread1\" style=\"font-style: inherit\">\u00a0&#8220;Fumus boni iuris&#8221;, a\u00f1adi\u00f3 el fiscal, para argumentar la convicci\u00f3n de las pruebas de posible lavado de activos: un listado de dep\u00f3sitos no solo de Odebrecht Latinvest a Westfield y First Capital, sino transferencias de otras firmas ligadas a Kuczynski entre 2007 y 2015. El fiscal tambi\u00e9n mencion\u00f3 un decreto supremo que firm\u00f3 Kuczynski como ministro en febrero de 2006 y que respaldaba financieramente al gigante brasile\u00f1o: fue el otorgamiento de garant\u00eda para asegurar los pagos a un contrato de concesi\u00f3n.<\/div>\n<section id=\"sumario_1|html\" class=\"sumario_html centro\" style=\"color: #444444\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_1\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"SandboxRoot env-bp-350\" style=\"color: #1c2022\">\n<div id=\"twitter-widget-0\" class=\"EmbeddedTweet EmbeddedTweet--edge js-clickToOpenTarget tweet-InformationCircle-widgetParent\" lang=\"es\">\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/ppkamigo\/status\/977627518952878080\">\n<div class=\"Tweet-header u-cf\">\n<div class=\"Tweet-brand u-floatRight\"><\/div>\n<div class=\"TweetAuthor js-inViewportScribingTarget\"><a class=\"TweetAuthor-link Identity u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/ppkamigo\"><span class=\"TweetAuthor-avatar Identity-avatar\"><img decoding=\"async\" class=\"Avatar Avatar--edge\" src=\"https:\/\/pbs.twimg.com\/profile_images\/804670530141962241\/ogAdD6YD_normal.jpg\" alt=\"\" \/><\/span><span class=\"TweetAuthor-decoratedName\"><span class=\"TweetAuthor-name Identity-name customisable-highlight\" style=\"font-weight: bold\" title=\"PedroPablo Kuczynski\">PedroPablo Kuczynski<\/span><\/span><\/a><\/p>\n<div class=\"Icon Icon--verified \" title=\"Cuenta verificada\"><\/div>\n<p><a class=\"TweetAuthor-link Identity u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/ppkamigo\"><span class=\"TweetAuthor-decoratedName\"><span class=\"TweetAuthor-verifiedBadge\"><span class=\"u-hiddenVisually\">\u2714<\/span><\/span><\/span><span class=\"TweetAuthor-screenName Identity-screenName\" dir=\"ltr\" style=\"color: #697882\" title=\"@ppkamigo\">@ppkamigo<\/span><\/a><\/div>\n<\/div>\n<div class=\"Tweet-body e-entry-content\">\n<div class=\"u-hiddenVisually js-inViewportScribingTarget\"><\/div>\n<p class=\"Tweet-text e-entry-title\" dir=\"ltr\" lang=\"es\">Reafirmo mi total disposici\u00f3n para colaborar con las diligencias fiscales. Soy el principal interesado en que las acusaciones de las que soy v\u00edctima se esclarezcan y permitan limpiar mi nombre y honor. (1\/4)<\/p>\n<div class=\"Tweet-metadata dateline\" style=\"color: #697882\"><a class=\"u-linkBlend u-url customisable-highlight long-permalink\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/ppkamigo\/status\/977627518952878080\">15:25 &#8211; 24 mar. 2018<\/a><\/div>\n<ul class=\"Tweet-actions Tweet-action--newsActions\">\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--heartEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--heart TweetAction TweetAction--heartEdge\" style=\"color: #697882\" title=\"Me gusta\" href=\"https:\/\/twitter.com\/intent\/like?tweet_id=977627518952878080\"><span class=\"TweetAction-stat\">711<\/span><\/a><\/li>\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--replyEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--replyEdge TweetAction TweetAction--replyEdge\" style=\"color: #697882\" title=\"Ver la conversaci\u00f3n en Twitter\" href=\"https:\/\/twitter.com\/ppkamigo\/status\/977627518952878080\"><span class=\"TweetAction-stat\">298 personas est\u00e1n hablando de esto<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/blockquote>\n<\/div>\n<div class=\"tweet-InformationCircle--bottom tweet-InformationCircle\"><a class=\"Icon Icon--informationCircleWhite js-inViewportScribingTarget\" style=\"color: #2b7bb9\" title=\"Informaci\u00f3n y privacidad de Twitter Ads\" href=\"https:\/\/support.twitter.com\/articles\/20175256\"><span class=\"u-hiddenVisually\">Informaci\u00f3n y privacidad de Twitter Ads<\/span><\/a><\/div>\n<\/div>\n<div class=\"resize-sensor\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p style=\"color: #444444\">&#8220;El se\u00f1or Pedro Pablo Kuczynski acaba de ostentar la m\u00e1xima magistratura del Per\u00fa y tiene contactos internacionales en el mundo de las finanzas econ\u00f3micas y podr\u00eda abandonar el pa\u00eds cuando lo quisiera&#8221;, a\u00f1adi\u00f3 el fiscal que dirige las investigaciones de Lava Jato en Per\u00fa para justificar el riesgo de fuga.<\/p>\n<p style=\"color: #444444\">El abogado del exmandatario, Cesar Nakazaki, respondi\u00f3 que su patrocinado tiene voluntad de colaborar con la investigaci\u00f3n y se allanaba al pedido de arraigo hecho por la Fiscal\u00eda. Pero luego plante\u00f3 al juez terminar r\u00e1pidamente la audiencia, &#8220;porque hay un allanamiento en la casa de mi patrocinado&#8221;, dijo. Nakazaki defendi\u00f3 la d\u00e9cada pasada al aut\u00f3crata Alberto Fujimori, en juicios por violaci\u00f3n de derechos humanos, robo y corrupci\u00f3n.<\/p>\n<p style=\"color: #444444\">En paralelo, la Fiscal\u00eda inform\u00f3 por Twitter que dos fiscales estaban este s\u00e1bado realizando diligencias de allanamiento en dos casas del expresidente Kuczynski: dos inmuebles en la cuadra 9 de la calle Choquehuanca en el acomodado distrito de San Isidro y una casa de campo en Cieneguilla, en las afueras de Lima por \u201cla por la presunta comisi\u00f3n del delito de lavado de activos en agravio del Estado&#8221;.<\/p>\n<p style=\"color: #444444\">Kuczynski transfiri\u00f3 hace algunos a\u00f1os la propiedad de su casa campestre a Dorado Assets, una empresa que luego inscribi\u00f3 a nombre de su hija. Hace dos semanas, al responder preguntas de la comisi\u00f3n parlamentaria de investigaci\u00f3n Lava Jato, justific\u00f3 el traspaso de esa casa a la offshore Dorado Assets para pagar menos impuestos en Estados Unidos cuando renunci\u00f3 a la nacionalidad estadounidense.<\/p>\n<p style=\"color: #444444\">Nakazaki se traslad\u00f3 a Cieneguilla, para encontrarse con su patrocinado, pero trascendi\u00f3 entre los periodistas apostados en la calle Choquehuanca, que Kuczynski estaba por volver a su domicilio de San Isidro, donde est\u00e1 su biblioteca y el escritorio al que siempre volv\u00eda durante los meses de campa\u00f1a electoral en 2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez anticorrupci\u00f3n investiga supuestos pagos de la constructora Odebrecht a empresas ligadas al exmandatario durante su etapa de ministro en el Gobierno de Alejandro Toledo<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-476795","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=476795"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476795\/revisions"}],"predecessor-version":[{"id":476797,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476795\/revisions\/476797"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=476795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=476795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=476795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}