{"id":476806,"date":"2018-03-26T08:56:07","date_gmt":"2018-03-26T12:56:07","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=476806"},"modified":"2018-03-26T08:56:07","modified_gmt":"2018-03-26T12:56:07","slug":"martin-vizcarra-un-presidente-con-fortalezas-simbolicas","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/03\/26\/martin-vizcarra-un-presidente-con-fortalezas-simbolicas\/","title":{"rendered":"Mart\u00edn Vizcarra, un presidente con fortalezas simb\u00f3licas"},"content":{"rendered":"<div id=\"attachment_476807\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/03\/1522038919_547474_1522047572_noticia_fotograma.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-476807\" class=\"size-large wp-image-476807\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/03\/1522038919_547474_1522047572_noticia_fotograma-560x315.jpg\" alt=\"Vizcarra, en su toma de posesi\u00f3n.\" width=\"560\" height=\"315\" \/><\/a><p id=\"caption-attachment-476807\" class=\"wp-caption-text\">Vizcarra, en su toma de posesi\u00f3n.<\/p><\/div>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">El ingeniero civil\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/03\/23\/america\/1521829723_964634.html\" target=\"_blank\">Mart\u00edn Vizcarra<\/a>, que reemplaz\u00f3 el viernes a\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/pedro_pablo_kuczynski_godard\/a\" target=\"_blank\">Pedro Pablo Kuczysnki<\/a>\u00a0como presidente de\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/peru\/a\" target=\"_blank\">Per\u00fa<\/a>\u00a0tras una grave crisis pol\u00edtica, tiene una primera meta: centrarse en el interior del pa\u00eds. \u201cMi ejercicio del cargo ser\u00e1 de mucho viaje, todas las semanas estar\u00e9 en los sitios m\u00e1s alejados viendo las necesidades e implementando soluciones\u201d, prometi\u00f3 en su primera entrevista radiof\u00f3nica desde que asumi\u00f3 el bast\u00f3n de mando de la s\u00e9ptima mayor econom\u00eda de Am\u00e9rica Latina. Su mensaje cuenta con una ventaja, a ojos de la mayor\u00eda de analistas y economistas peruanos: \u00e9l no es parte de la \u00e9lite pol\u00edtica ni empresarial capitalina. &#8220;Ese es un factor favorable desde el punto de vista simb\u00f3lico: no es un hombre de las multinacionales, no tiene conexiones fuertes con el poder pol\u00edtico y los c\u00edrculos empresariales de Lima&#8221;, apunta el soci\u00f3logo<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/escuela.pucp.edu.pe\/gobierno\/escuela\/plana-docente\/francisco-durand-arp-nissen\/\" target=\"_blank\">Francisco Durand<\/a>, el principal investigador de grupos de poder econ\u00f3mico en Per\u00fa. &#8220;Hay una expectativa positiva sobre \u00e9l en este momento de tregua: si construye su imagen de justiciero en fuerte vinculaci\u00f3n con el pueblo, puede salir adelante&#8221;.<\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">En un momento de fuerte oposici\u00f3n a los grupos tradicionales de poder pol\u00edtico y econ\u00f3mico, al nuevo presidente peruano le interesa no ser visto como parte de ninguno de ellos. As\u00ed lo ve\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/iep.org.pe\/investigadores\/patricia-zarate\/\" target=\"_blank\">Patricia Z\u00e1rate<\/a>,\u00a0investigadora del Instituto de Estudios Peruanos: \u201cEn el corto plazo, ante la opini\u00f3n p\u00fablica le favorece a Vizcarra estar al margen de un partido pol\u00edtico, por el descr\u00e9dito que tienen. El porcentaje de confianza que registramos (a los partidos) en 2017 fue de 7,5%\u201d.<\/div>\n<\/div>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">La llegada al poder del aut\u00f3crata\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/alberto_fujimori\/a\" target=\"_blank\">Alberto Fujimori<\/a>, con el consecuente da\u00f1o a la imagen de los partidos y el posterior cierre del Congreso \u2014donde su bancada era minoritaria\u2014 dio paso a una fase de pragmatismo en la pol\u00edtica peruana que contin\u00faa hasta la actualidad: la mayor\u00eda de formaciones pol\u00edticas son conglomerados creados antes de las elecciones. &#8220;La personalizaci\u00f3n de la pol\u00edtica viene de tiempo atr\u00e1s. La imagen de Vizcarra, de un provinciano que ha salido adelante en base al esfuerzo propio, le da la fortaleza simb\u00f3lica que ning\u00fan partido ahora le podr\u00eda otorgar&#8221;, explica Z\u00e1rate.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">El nuevo jefe de Estado y de Gobierno peruano lleg\u00f3 a la vicepresidencia en 2016 como invitado del partido de Kuczynski, Peruanos por el Kambio (PPK), pero no tiene afiliaci\u00f3n partidaria alguna. Aunque la primera vez que se present\u00f3 como candidato para la presidencia regional de Moquegua (sur), en 2006, lo hizo por el Partido Aprista \u2014al que perteneci\u00f3 su padre, exalcalde de la localidad hom\u00f3nima\u2014 nunca ha formado parte de ning\u00fan partido pol\u00edtico.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">Estas caracter\u00edsticas llevan a algunos analistas a comparar a Vizcarra con<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/valentin_paniagua\/a\" target=\"_blank\">Valent\u00edn Paniagua<\/a>, presidente de transici\u00f3n que tuvo capacidad de di\u00e1logo para salir de la crisis institucional tras la renuncia de Fujimori por corrupci\u00f3n. El economista y catedr\u00e1tico\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.pucp.edu.pe\/profesor\/waldo-mendoza-bellido\/\" target=\"_blank\">Waldo Mendoza<\/a>\u00a0dijo en Radioprogramas que este momento le hac\u00eda recordar al a\u00f1o 2000, cuando Paniagua accedi\u00f3 a la presidencia. \u201cVizcarra tiene capacidad de convocatoria, pocos le van a decir que no (para integrar el Gabinete). Los partidos que piensen ser Gobierno en el 2021 tendr\u00e1n que dejar trabajar al presidente\u201d, plante\u00f3, aludiendo al obstruccionismo del fujimorista\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/01\/31\/america\/1517427377_280207.html\" target=\"_blank\">Fuerza Popular<\/a>\u00a0en el Congreso durante los 20 meses de la Administraci\u00f3n Kuczynski.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">Sin embargo, Francisco Durand, de la\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/escuela.pucp.edu.pe\/gobierno\/\" target=\"_blank\">Escuela de Gobierno y Pol\u00edticas P\u00fablicas de la\u00a0Pontificia Universidad Cat\u00f3lica del Per\u00fa<\/a>, ve un escenario &#8220;m\u00e1s complicado&#8221; que en el a\u00f1o 2000. &#8220;La corrupci\u00f3n entonces era de un solo lado [el fujimorismo]: ahora es transversal y toca a gran parte de la clase pol\u00edtica y empresarial. La fiscal\u00eda va a tener que ser firme cuando profundice en las investigaciones por lavado de activos\u201d. Por dicho delito est\u00e1n bajo investigaci\u00f3n el propio Kuczynski; la excandidata presidencial\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/keiko_sofia_fujimori\/a\" target=\"_blank\">Keiko Fujimori<\/a>:\u00a0los expresidentes\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/alejandro_toledo\/a\" target=\"_blank\">Alejandro Toledo<\/a>,<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/alan_garcia\/a\" target=\"_blank\">Alan Garc\u00eda<\/a>\u00a0y\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/ollanta_humala_tasso\/a\" target=\"_blank\">Ollanta Humala<\/a>; y la exalcaldesa de Lima, Susana Villar\u00e1n, entre otros exfuncionarios p\u00fablicos mencionados por los representantes de la constructora brasile\u00f1a\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/odebrecht\/a\" target=\"_blank\">Odebrecht<\/a>, que\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/03\/08\/america\/1520467389_977266.html\" target=\"_blank\">pag\u00f3 sobornos en Per\u00fa y aport\u00f3 fondos, al margen de la ley, a diversas campa\u00f1as para las elecciones de 2006 y 2011<\/a>. Adem\u00e1s, la justicia ha dictado este s\u00e1bado una orden de arraigo a Kuczynski por 18 meses.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">Vizcarra podr\u00eda tener otros aliados. El secretario general del gremio magisterial, Alfredo Vel\u00e1squez, reconoci\u00f3 este domingo que el nuevo presidente \u201ctiene una fortaleza que es su esposa, quien ha sido directora de una escuela p\u00fablica\u201d. Durand a\u00f1ade que el mandatario inicia su gesti\u00f3n con margen para que el Estado invierta en obras p\u00fablicas y un entorno econ\u00f3mico internacional favorable: \u201cNo hay perspectivas de que caigan los precios de los minerales y ello puede incrementar la econom\u00eda exportadora. Puede haber un modesto crecimiento dependiendo de a qui\u00e9n nombre como ministro de Econom\u00eda\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Su trayectoria pol\u00edtica, que discurri\u00f3 siempre lejos de Lima, y su poca conexi\u00f3n con los c\u00edrculos empresariales y los partidos pol\u00edticos son los principales puntos fuertes del nuevo jefe de Estado peruano<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-476806","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=476806"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476806\/revisions"}],"predecessor-version":[{"id":476808,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/476806\/revisions\/476808"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=476806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=476806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=476806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}