{"id":477046,"date":"2018-04-10T13:20:42","date_gmt":"2018-04-10T17:20:42","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477046"},"modified":"2018-04-10T13:20:42","modified_gmt":"2018-04-10T17:20:42","slug":"pinera-anuncia-en-chile-la-regularizacion-gradual-de-300-000-inmigrantes","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/04\/10\/pinera-anuncia-en-chile-la-regularizacion-gradual-de-300-000-inmigrantes\/","title":{"rendered":"Pi\u00f1era anuncia en Chile la regularizaci\u00f3n gradual de 300.000 inmigrantes"},"content":{"rendered":"<div id=\"attachment_477047\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/04\/1523294949_287480_1523295371_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477047\" class=\"size-large wp-image-477047\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/04\/1523294949_287480_1523295371_noticia_normal_recorte1-560x373.jpg\" alt=\"El presidente de Chile, Sebasti\u00e1n Pi\u00f1era, presenta su reforma a la Ley de Migraciones.\" width=\"560\" height=\"373\" \/><\/a><p id=\"caption-attachment-477047\" class=\"wp-caption-text\">El presidente de Chile, Sebasti\u00e1n Pi\u00f1era, presenta su reforma a la Ley de Migraciones.<\/p><\/div>\n<p style=\"color: #444444\">El presidente chileno\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/sebastian_pinera\/a\/\" target=\"_blank\">Sebasti\u00e1n Pi\u00f1era<\/a>, a d\u00edas de cumplir\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/03\/11\/america\/1520783253_124016.html\" target=\"_blank\">el primer mes<\/a>\u00a0en el Gobierno, ha dado a conocer este lunes una reforma migratoria para reemplazar la normativa vigente de 1975. La propuesta contempla, entre otras medidas, una regularizaci\u00f3n extraordinaria gradual que beneficiar\u00eda a los cerca de 300.000 inmigrantes que permanecen en el pa\u00eds sin documentaci\u00f3n, seg\u00fan estimaciones del propio Ejecutivo. La norma apunta a todos los que hayan ingresado al pa\u00eds antes del domingo 8 de abril, pero excluir\u00e1 a los extranjeros que tengan antecedentes penales en Chile o en su pa\u00eds de origen. La actualizaci\u00f3n de la ley era esperada, porque el Estado y su legislaci\u00f3n anticuada no dan abasto. Chile es el pa\u00eds latinoamericano donde m\u00e1s ha crecido el n\u00famero de inmigrantes en los \u00faltimos a\u00f1os y se ha doblado desde 2014 a la fecha. Si hace cuatro a\u00f1os hab\u00eda 416.000, en la actualidad se calcula que hay un mill\u00f3n.<\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">&#8220;Ha llegado el momento de poner orden en este hogar que compartimos en esta casa que es la casa de todos&#8221;, se\u00f1al\u00f3 en su discurso el presidente chileno de la coalici\u00f3n de derecha Chile Vamos, acompa\u00f1ado de varios ministros de su gabinete. Los anuncios se materializar\u00e1n a trav\u00e9s de dos caminos. Por una parte, el Ejecutivo realizar\u00e1 indicaciones a un proyecto de ley de la anterior Administraci\u00f3n de Pi\u00f1era (2010-2014), que se discutir\u00e1 en el Parlamento. A la espera del trabajo legislativo, sin embargo, el Gobierno dict\u00f3 un instructivo presidencial para hacerse cargo de aquellas situaciones que, seg\u00fan La Moneda, no pueden esperar.<\/div>\n<\/div>\n<div id=\"inread1\" style=\"font-style: inherit\">\u00a0Una de las principales transformaciones tiene relaci\u00f3n con la visa de turista. La actual legislaci\u00f3n permite que los extranjeros entren al pa\u00eds con este permiso y desde dentro de Chile cambiar el visado, con la obtenci\u00f3n de un trabajo, por ejemplo. El decreto de Pi\u00f1era que entrar\u00e1 en vigencia el 23 de abril pr\u00f3ximo eliminar\u00e1 &#8220;la posibilidad de solicitar el visado temporario en Chile, por motivos laborales&#8221;. A cambio, el Gobierno anunci\u00f3 tres tipos nuevos de visas temporarias, como la de oportunidades: orientada a los inmigrantes que busquen viajar a Chile para trabajar, debe pedirse desde fuera del pa\u00eds.<\/div>\n<p style=\"color: #444444\">Entre los anuncios de Pi\u00f1era est\u00e1 el reforzamiento de la institucionalidad. El Gobierno pretende formar un Consejo de Pol\u00edtica Migratoria, que deber\u00e1 formular las pol\u00edticas p\u00fablicas, y el Servicio Nacional de Migraciones, que deber\u00e1 ejecutar estas normas y ser\u00e1 el canal del Estado para relacionarse con los migrantes.<\/p>\n<p style=\"color: #444444\">La reforma migratoria de Pi\u00f1era hace menci\u00f3n de dos nacionalidades en particular: la\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/04\/09\/america\/1523226516_383567.html\" target=\"_blank\">haitiana<\/a>\u00a0y la\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2017\/08\/10\/actualidad\/1502379778_751102.html\" target=\"_blank\">venezolana<\/a>, que han representado el mayor crecimiento en los \u00faltimos a\u00f1os. Si en 2014 ingresaron a Chile 1.649 haitianos, en 2017 lo hicieron 73.098. En lo que va de 2018, seg\u00fan la polic\u00eda, 411 nacionales de Hait\u00ed han arribado diariamente al pa\u00eds sudamericano. Con los venezolanos sucede algo parecido. Son la quinta nacionalidad m\u00e1s numerosa entre los inmigrantes \u2013luego de la peruana, colombiana, boliviana y argentina\u2013 y actualmente llegan a 794 diariamente al pa\u00eds, seg\u00fan datos de la polic\u00eda. Se calcula que en total unos 85.724 habitan en Chile.<\/p>\n<p style=\"color: #444444\">En relaci\u00f3n con los haitianos, Pi\u00f1era anunci\u00f3 que a partir del 16 de abril pr\u00f3ximo, al igual que la mayor\u00eda de los pa\u00edses latinoamericanos, se les pedir\u00e1 una visa consular de turismo simple a quienes con un m\u00e1ximo de 30 d\u00edas busquen ingresar a Chile &#8220;con fines de recreaci\u00f3n, deportivos, de salud, de estudios, de gestiones de negocios, familiares, religiosos u otros similares, sin prop\u00f3sito de inmigraci\u00f3n, residencia o desarrollo de actividades remuneradas&#8221;. Como deber\u00e1 pedirse en Hait\u00ed y una vez en Chile no se podr\u00e1 cambiar de visa de turista a una temporaria, esta medida representar\u00e1 una barrera.<\/p>\n<p style=\"color: #444444\">Como la inmigraci\u00f3n haitiana a su vez se encuentra en etapa de reunificaci\u00f3n familiar, el Gobierno chileno establecer\u00e1 un visado para fines humanitarios de 12 meses de duraci\u00f3n, que solo podr\u00e1 pedirse en el consulado chileno en\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/haiti\/a\" target=\"_blank\">Hait\u00ed<\/a>. Entrar\u00e1 en vigor el 2 de julio, podr\u00e1 ser ampliada a 24 meses y, luego de ese per\u00edodo, el ciudadano podr\u00e1 aspirar a la residencia definitiva en Chile. El Ejecutivo, sin embargo, aclara que &#8220;se autorizar\u00e1 un m\u00e1ximo anual de visados con fines humanitario&#8221;.<\/p>\n<p style=\"color: #444444\">Respecto de los venezolanos, &#8220;un pa\u00eds que acogi\u00f3 a muchos chilenos que buscaban refugio en sus fronteras&#8221;, Pi\u00f1era anunci\u00f3 la creaci\u00f3n de una visa de responsabilidad democr\u00e1tica, que deber\u00e1 solicitarse en el consulado chileno de Caracas a partir del 16 de abril. &#8220;Otorgar\u00e1 un permiso de residencia temporal por un a\u00f1o, prorrogable por una vez, que posibilita luego pedir la residencia definitiva&#8221;, se\u00f1al\u00f3 el presidente.<\/p>\n<section id=\"sumario_1|despiece\" class=\"sumario_despiece centro\" style=\"color: #444444\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_1\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<header class=\"sumario-encabezado\" style=\"font-style: inherit\">\n<h4 class=\"sumario-titulo\" style=\"font-style: inherit;color: #111111\"><span class=\"sin_enlace\" style=\"font-weight: inherit;font-style: inherit\">\u201cSE ALEJA COMPLETAMENTE DE LAS EXPECTATIVAS\u201d<\/span><\/h4>\n<\/header>\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<p style=\"font-style: inherit\">El director social del Servicio Jesuita a Migrantes, Pablo Valenzuela, se\u00f1ala que aunque hasta ahora solo se conocen las medidas anunciadas por el presidente Sebasti\u00e1n Pi\u00f1era en su discurso, sin los detalles, &#8220;se aleja completamente de las expectativas que ten\u00edan las organizaciones de migrantes y pro migrantes de tener por fin una legislaci\u00f3n con enfoque a derecho&#8221;.<\/p>\n<p style=\"font-style: inherit\">Valenzuela valora la decisi\u00f3n de regularizaci\u00f3n extraordinaria, aunque se\u00f1ala que es importante conocer si el beneficio dejar\u00e1 afuera, por ejemplo, a quienes hayan ingresado por pasos no habilitados. &#8220;Por otra parte, cuesta entender que las medidas espec\u00edficas y especiales para Hait\u00ed no sean discriminatorias, siendo que su flujo no es el mayoritario, sino el venezolano. No pareciera ser justo&#8221;, se\u00f1ala Valenzuela respecto de la petici\u00f3n de una visa consular de turismo desde Hait\u00ed. &#8220;Corremos el riesgo de que en busca de una migraci\u00f3n segura, ordenada y regular, tengamos una insegura, desordenada e irregular&#8221;.<\/p>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Un mill\u00f3n de extranjeros vive en el pa\u00eds de Latinoam\u00e9rica donde m\u00e1s ha crecido la inmigraci\u00f3n, pero que tiene una ley de 1975<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-477046","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477046"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477046\/revisions"}],"predecessor-version":[{"id":477048,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477046\/revisions\/477048"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}