{"id":477247,"date":"2018-04-24T09:59:24","date_gmt":"2018-04-24T13:59:24","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477247"},"modified":"2018-04-24T09:59:24","modified_gmt":"2018-04-24T13:59:24","slug":"el-tlc-es-una-de-las-causas-del-estancamiento-de-mexico","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/04\/24\/el-tlc-es-una-de-las-causas-del-estancamiento-de-mexico\/","title":{"rendered":"\u201cEl TLC es una de las causas del estancamiento de M\u00e9xico\u201d"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div id=\"attachment_477248\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/04\/1524522409_552355_1524525632_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477248\" class=\"size-large wp-image-477248\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/04\/1524522409_552355_1524525632_noticia_normal_recorte1-560x373.jpg\" alt=\"Romero Tellaeche, en un momento de la entrevista. A. FERN\u00c1NDEZ\" width=\"560\" height=\"373\" \/><\/a><p id=\"caption-attachment-477248\" class=\"wp-caption-text\">Romero Tellaeche, en un momento de la entrevista. A. FERN\u00c1NDEZ<\/p><\/div>\n<p><a style=\"font-weight: bold;color: #111111\" title=\"Ver todas las noticias de Ignacio Fariza\" href=\"https:\/\/elpais.com\/autor\/ignacio_fariza_somolinos\/a\/\">IGNACIO FARIZA<\/a><\/p>\n<p><a style=\"color: #016ca2\" href=\"http:\/\/cee.colmex.mx\/jose-romero\" target=\"_blank\" rel=\"noopener noreferrer\">Jos\u00e9 Antonio Romero Tellaeche<\/a><span style=\"color: #444444\">\u00a0(Ciudad de M\u00e9xico, 1950) rema a contracorriente. En el M\u00e9xico de los tratados comerciales (12, con casi medio centenar de pa\u00edses), que acaba de sellar la puesta en marcha de\u00a0<\/span><a style=\"color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/tpp_acuerdo_estrategico_transpacifico_asociacion_economica\/a\" target=\"_blank\">un ambicioso acuerdo con el resto de la cuenca del Pac\u00edfico<\/a><span style=\"color: #444444\">, que el pasado s\u00e1bado acord\u00f3 con la actualizaci\u00f3n de su pacto de libre cambio y que apura los plazos para firmar una nueva versi\u00f3n del\u00a0<\/span><a style=\"color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/tlcan_tratado_libre_comercio_america_norte\/a\" target=\"_blank\">Tratado de Libre Comercio de Am\u00e9rica del Norte (TLC, que le une desde 1994 a Estados Unidos y Canad\u00e1)<\/a><span style=\"color: #444444\">, el hasta hace dos meses director del\u00a0<\/span><a style=\"color: #016ca2\" href=\"http:\/\/cee.colmex.mx\/corea-y-mexico-dos-estrategias-de-crecimiento-con-resultados-dispares\" target=\"_blank\">Centro de Estudios Econ\u00f3micos de El Colegio de M\u00e9xico<\/a><span style=\"color: #444444\">\u00a0carga contra el mayor acuerdo comercial del planeta, defiende el modelo del\u00a0<\/span><a style=\"color: #016ca2\" href=\"https:\/\/www.youtube.com\/watch?v=Q3OiIk6s_Zo\" target=\"_blank\">Estado desarrollador<\/a><span style=\"color: #444444\">\u00a0y carga contra las doctrinas econ\u00f3micas establecidas. Tiempo para el debate.<\/span><\/p>\n<p style=\"color: #444444\">Su \u00faltimo libro \u2014<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/cee.colmex.mx\/corea-y-mexico-dos-estrategias-de-crecimiento-con-resultados-dispares\" target=\"_blank\"><em>Corea y M\u00e9xico, dos estrategias de crecimiento con resultados dispares<\/em>, El Colegio de M\u00e9xico 2018<\/a>\u2014, coescrito con el tambi\u00e9n economista Julen Berasaluce, compara el diferencial de crecimiento de M\u00e9xico y el de\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/corea_del_sur\/a\" target=\"_blank\">Corea del Sur<\/a>\u00a0en las tres \u00faltimas d\u00e9cadas: mientras que el primero \u2014en origen, m\u00e1s rico\u2014 ha registrado un crecimiento del ingreso por habitante solo ligeramente superior al 0,7% en el periodo, el pa\u00eds asi\u00e1tico ha logrado dar un salto exponencial de desarrollo, hasta el punto de haber logrado acceder al selecto club de las 30 naciones con mayor renta per c\u00e1pita del mundo.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">Pregunta.<\/strong>\u00a0\u00bfPor qu\u00e9 M\u00e9xico crece por debajo de su potencial?<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">Respuesta.<\/strong>\u00a0Porque opt\u00f3 por una estrategia fallida. Hubo dos errores: considerar que el libre comercio iba a generar de por s\u00ed el crecimiento y [pensar] que, a trav\u00e9s de la inversi\u00f3n extranjera se iba a transferir tecnolog\u00eda a M\u00e9xico y eso iba a hacer m\u00e1s productivos a los mexicanos, cosa que no sucedi\u00f3. La crisis de la deuda [de los a\u00f1os 80] supuso un cataclismo en un momento en el que el mundo entraba en la etapa del neoliberalismo, y M\u00e9xico fue uno de los primeros pa\u00edses que se someti\u00f3 al tratamiento del<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/fmi_fondo_monetario_internacional\/a\" target=\"_blank\">Fondo Monetario Internacional (FMI)<\/a>. Al mismo tiempo, en EE UU [el presidente\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/ronald_reagan\/a\" target=\"_blank\">Ronald] Reagan<\/a>, en algo parecido a lo que sucede hoy con\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/donald_trump\/a\" target=\"_blank\">[Donald] Trump<\/a>, ve\u00eda un d\u00e9ficit estructural con M\u00e9xico y pidi\u00f3 que se desmantelaran todos los programas industriales mexicanos. Ese fue el principio de la apertura comercial. Uno de los grandes mitos es que, si uno tiene libre comercio, democracia y Estado de derecho solito se va al crecimiento. La historia nos ha demostrado que no.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0Pero las exportaciones de M\u00e9xico no han dejado de crecer desde aquella apertura al libre comercio y la posterior firma del TLC.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0S\u00ed, exporta mucho. Pero no son empresas mexicanas: son empresas estadounidenses. El TLC fue precisamente para atraer esas inversiones permitiendo [a las compa\u00f1\u00edas] traer todos los insumos de EE UU que quisieran y ensamblar en M\u00e9xico.\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/china\/a\" target=\"_blank\">China<\/a>\u00a0y\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/corea_del_sur\/a\" target=\"_blank\">Corea<\/a>, en cambio, no basaron su crecimiento en la inversi\u00f3n extranjera, sino en la nacional. Y cuando empezaron a admitir inversi\u00f3n extranjera, la obligaron a asociarse con inversionistas nacionales. De esa forma fueron aprendieron c\u00f3mo se hacen las cosas.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0\u00bfPodr\u00eda M\u00e9xico haber optado por la v\u00eda china o coreana?<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0No estaba en el ADN de los economistas que se fueron a estudiar a EE UU. Ten\u00edan una visi\u00f3n de la\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/economia\/2017\/12\/28\/actualidad\/1514459479_033738.html\" target=\"_blank\">econom\u00eda neocl\u00e1sica<\/a>, que ve al individuo en s\u00ed mismo y no al individuo como parte de una sociedad en la que lo que importa es el bienestar de la sociedad en su conjunto y el crecimiento de la naci\u00f3n. Ellos ve\u00edan solo por la apertura de los mercados y por que los productos fueran baratos. No pensaban en el largo plazo, sino \u00fanicamente en que el libre comercio es lo mejor, dando por hecho que el TLC es bueno para M\u00e9xico.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0\u00bfY Ud. cree que es positivo?<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0No. Es una de las causas del estancamiento, porque a la inversi\u00f3n extranjera no se le pidieron ni requisitos de exportaci\u00f3n, ni de contenido nacional, ni de asociarse con mexicanos. Ninguno. Y se les dio el mismo tratamiento que a un inversionista mexicano. [Ahora] subsidiamos, por ejemplo, investigaci\u00f3n que luego es patentada en otras partes del mundo. Es de locos. La industria nacional pr\u00e1cticamente ha desaparecido: toda est\u00e1 en manos extranjeras. La \u00fanica raz\u00f3n de ser es exportar al mercado estadounidense.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0Lo ve como algo necesariamente negativo.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0Las empresas exportadoras no son mexicanas y no se identifican con M\u00e9xico. Si cae el tratado, lo que har\u00e1n ser\u00e1 cruzar la frontera. Hay que recordar, adem\u00e1s, que la di\u00e1spora mexicana a EE UU coincide con el TLC: las proporciones fueron b\u00edblicas. Se fue pr\u00e1cticamente el 1% de la poblaci\u00f3n cada a\u00f1o, cinco millones en un periodo de tiempo muy corto.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0\u00bfNo hay forma de renegociar el TLC en positivo para M\u00e9xico?<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0No. EE UU tendr\u00eda que aceptar restricciones a la inversi\u00f3n extranjera directa en M\u00e9xico, tanto la suya como la europea o japonesa. Que para poder entrar a M\u00e9xico tengan que comprometerse a ense\u00f1ar a los mexicanos. Que haya transferencia tecnol\u00f3gica. No sabemos hacer nada: somos, supuestamente, una potencia y no sabemos ni fabricar los vagones del metro. Eso refleja que no hay ninguna transferencia de tecnolog\u00eda.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0No teme la ruptura, entonces.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0Estamos en un momento de quiebre: este modelo est\u00e1 en sus \u00faltimos estertores, no solo en M\u00e9xico, sino tambi\u00e9n en EE UU y en Europa. Cuando son ganadores, todos los pa\u00edses defienden el libre comercio: sucedi\u00f3 en Inglaterra en su momento y en EE UU despu\u00e9s. Pero ahora se ven acorralados por China y empiezan a replegarse con proteccionismo selectivo, reindustrializaci\u00f3n, etc. En eso deber\u00eda pensar tambi\u00e9n M\u00e9xico.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0Va a contracorriente, tambi\u00e9n, con esta defensa cerrada del modelo de Estado desarrollador.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0Es la mejor estrategia para alcanzar a los l\u00edderes en poco tiempo. Son muchos casos: Corea, Alemania, Jap\u00f3n, China\u2026<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0Pero lo hicieron en otra \u00e9poca, en un mundo mucho menos globalizado. Hoy la competencia entre empresas y entre pa\u00edses es feroz.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0La cr\u00edtica habitual es que eso se pudo hacer antes, pero ya no. No es cierto: est\u00e1 el caso de Vietnam, un pa\u00eds de 100 millones de habitantes, m\u00e1s atrasado que M\u00e9xico y que est\u00e1 siguiendo esa estrategia. M\u00e1s de lo mismo ya no da: en 1950, M\u00e9xico ocupaba el puesto 37 [mundial] en ingreso per c\u00e1pita; en 1982, a pesar de lo que crecimos, ya est\u00e1bamos en el lugar 41 porque otros pa\u00edses crecieron m\u00e1s r\u00e1pido; en 2015 ya est\u00e1bamos en el 78. El verdadero desarrollo lleg\u00f3 hasta 1970, luego vinieron [los presidentes\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/luis_echeverria_alvarez\/a\" target=\"_blank\">Luis] Echeverr\u00eda<\/a>\u00a0y\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/jose_lopez_portillo\/a\" target=\"_blank\">[Jos\u00e9] L\u00f3pez Portillo<\/a>\u00a0y aunque la econom\u00eda sigui\u00f3 creciendo, ya fue artificialmente. Despu\u00e9s, el liberalismo no funcion\u00f3. El panorama para toda Am\u00e9rica Latina es muy desolador si seguimos con el mismo patr\u00f3n.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0Muchos economistas tachar\u00edan esas ideas de antiguas y nacionalistas.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0Los economistas neocl\u00e1sicos parten de que hay pleno empleo y de que hay que ocupar los recursos escasos en las mejores actividades. En M\u00e9xico no se dan esos supuestos. La cr\u00edtica es que tenemos una oferta ilimitada de mano de obra que no est\u00e1 empleada o est\u00e1 en el subempleo. Hay un 60% de informalidad, as\u00ed que no estamos hablando de lo mismo. Y, \u00bfc\u00f3mo ocupamos esa mano de obra? Hasta ahora la respuesta ha consistido en planes de solidaridad: darles paliativos hasta que se mueran. Quienes reciben buenos ingresos est\u00e1n felices, pero para la mayor\u00eda hay escasez de ingresos y el ingreso medio por habitante est\u00e1 rezagado. Ya no se cree en la ret\u00f3rica que hemos escuchado en 30 a\u00f1os, de que especializ\u00e1ndonos en lo que tenemos ventajas comparativas es lo mejor y de que cualquier intervenci\u00f3n del Estado en la econom\u00eda es perjudicial.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0\u00bfA qu\u00e9 achaca ese rechazo a la presencia del Estado?<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0El desprestigio del Estado es completamente ideol\u00f3gico. No se concibe ni siquiera el concepto de pol\u00edtica industrial. Es la ideolog\u00eda dominante y ha hecho mucho da\u00f1o. Creo que hay que planificar la econom\u00eda sin sustituir al mercado: lo que importan son las econom\u00edas de escala. Y, cuando se tiene \u00e9xito, ya puedes entrar al libre mercado porque ya eres desarrollado.<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">P.<\/strong>\u00a0\u00bfEst\u00e1 M\u00e9xico a tiempo de optar por ese modelo?<\/p>\n<p style=\"color: #444444\"><strong style=\"font-style: inherit\">R.<\/strong>\u00a0Siempre se est\u00e1 a tiempo. China pudo haberlo aplicado 100 a\u00f1os antes, pero cuando lo hizo tuvo \u00e9xito. Igual Alemania. Perdimos 30 a\u00f1os, pero en alg\u00fan momento hay que iniciar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El investigador de El Colegio de M\u00e9xico defiende la planificaci\u00f3n econ\u00f3mica sin sustituir al mercado<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,23],"tags":[],"class_list":["post-477247","post","type-post","status-publish","format-standard","hentry","category-canada","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477247"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477247\/revisions"}],"predecessor-version":[{"id":477249,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477247\/revisions\/477249"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}