{"id":477308,"date":"2018-04-28T17:10:08","date_gmt":"2018-04-28T21:10:08","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477308"},"modified":"2018-04-28T17:10:08","modified_gmt":"2018-04-28T21:10:08","slug":"ee-uu-mexico-y-canada-encaran-la-recta-final-de-la-negociacion-del-tlc","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/04\/28\/ee-uu-mexico-y-canada-encaran-la-recta-final-de-la-negociacion-del-tlc\/","title":{"rendered":"EE UU, M\u00e9xico y Canad\u00e1 encaran la recta final de la negociaci\u00f3n del TLC"},"content":{"rendered":"<div id=\"attachment_477309\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/04\/1524853466_821905_1524853835_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477309\" class=\"size-large wp-image-477309\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/04\/1524853466_821905_1524853835_noticia_normal_recorte1-560x303.jpg\" alt=\"Los ministros a cargo de la negociaci\u00f3n: Freeland (Canad\u00e1), Guajardo (M\u00e9xico) y Lighthizer (EE UU).\" width=\"560\" height=\"303\" \/><\/a><p id=\"caption-attachment-477309\" class=\"wp-caption-text\">Los ministros a cargo de la negociaci\u00f3n: Freeland (Canad\u00e1), Guajardo (M\u00e9xico) y Lighthizer (EE UU).<\/p><\/div>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">El ensayista y financiero\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/cultura\/2013\/07\/04\/actualidad\/1372948269_591349.html\" target=\"_blank\">Nassim Nicholas Taleb<\/a>\u00a0acu\u00f1\u00f3 el t\u00e9rmino\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/economia\/2017\/12\/29\/actualidad\/1514548113_726173.html\" target=\"_blank\">\u201ccisne negro\u201d<\/a>para referirse a hechos harto improbables, que muy pocos lograron predecir, pero que a la postre cambian el curso de los acontecimientos. Diez a\u00f1os despu\u00e9s de la publicaci\u00f3n del libro hom\u00f3nimo en el que desarrollaba su teor\u00eda, este tipo de lances se han multiplicado a lo largo y ancho del mundo, como si de la noche a la ma\u00f1ana nos hubi\u00e9semos dado cuenta de que lo probable es eso, simplemente probable y no seguro. Que no todo lo que tiene visos de cumplirse acaba convirti\u00e9ndose en un hecho. Ocurri\u00f3 con el\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/referendum_permanencia_reino_unido_ue\/a\" target=\"_blank\"><em>Brexit<\/em><\/a>, en junio de 2016; se repiti\u00f3 con<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2016\/11\/09\/estados_unidos\/1478647677_279555.html\" target=\"_blank\">la victoria de Donald Trump<\/a>, cinco meses despu\u00e9s; y tiene muchos visos de volver suceder con la renegociaci\u00f3n exitosa del\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/tlcan_tratado_libre_comercio_america_norte\/a\" target=\"_blank\">Tratado de Libre Comercio de Am\u00e9rica del Norte (TLC)<\/a>: hace solo tres meses pr\u00e1cticamente nadie lo cre\u00eda posible y hoy las tres partes involucradas -Estados Unidos, M\u00e9xico y Canad\u00e1- se acercan a marchas forzadas a un acuerdo en los pr\u00f3ximos d\u00edas o semanas.<\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">Tanto a M\u00e9xico como a EE UU les interesa que el pacto para la renegociaci\u00f3n del mayor acuerdo comercial del planeta se cierre antes de mediados de mayo para que la aprobaci\u00f3n de los respectivos Legislativos llegue antes de dos citas clave con las urnas: las elecciones presidenciales mexicanas de julio y los comicios legislativos de mitad de mandato (<em>midterm<\/em>) en la primera potencia mundial. Desde el inicio de las negociaciones, el verano pasado, M\u00e9xico siempre ha suspirado un acuerdo r\u00e1pido para disipar la incertidumbre comercial que se cierne sobre su econom\u00eda, la segunda mayor de Latinoam\u00e9rica.<\/div>\n<div style=\"font-style: inherit\">El temor no es en vano: con el TLC se juega el 80% de sus exportaciones. \u201cEstamos avanzando y nos vamos a volver a ver ma\u00f1ana [por este viernes]\u201d, dijo el jueves el canciller mexicano,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/luis_videgaray_caso\/a\" target=\"_blank\">Luis Videgaray<\/a>, uno de los hombres clave en el dise\u00f1o del acuerdo.<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/ildefonso_guajardo_villarreal\/a\/1\" target=\"_blank\">Ildefonso Guajardo<\/a>, mano derecha de\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/enrique_pena_nieto\/a\" target=\"_blank\">Enrique Pe\u00f1a Nieto (PRI)<\/a>\u00a0en materia econ\u00f3mica, ve, por su parte,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/04\/09\/mexico\/1523286419_068964.html\" target=\"_blank\">un 80% de probabilidades de que el acuerdo cristalice<\/a>.<\/div>\n<div style=\"font-style: inherit\"><\/div>\n<\/div>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">En la orilla norte del r\u00edo Bravo, las prisas son m\u00e1s recientes: a las encuestas que sit\u00faan al Partido Republicano en una coyuntura complicada para reeditar su estrecha mayor\u00eda en el Senado en los comicios de noviembre, se suma la presi\u00f3n de los muchos gobernadores de la formaci\u00f3n conservadora que se juegan la reelecci\u00f3n en los muchos Estados que dependen de las ventas a M\u00e9xico y Canad\u00e1. Para ellos, llegar a las urnas con un acuerdo debajo del brazo es fundamental y es la principal raz\u00f3n por la que Washington -vaivenes de Trump al margen- ha pisado el acelerador en las \u00faltimas semanas. Las buenas perspectivas electorales de\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/andres_manuel_lopez_obrador\/a\" target=\"_blank\">Andr\u00e9s Manuel L\u00f3pez Obrador<\/a>\u00a0-la alternativa que menos gusta en los grandes foros empresariales y financieros- para convertirse en el pr\u00f3ximo presidente de M\u00e9xico han hecho el resto: si la negociaci\u00f3n con el Ejecutivo de Pe\u00f1a Nieto ha sido dif\u00edcil, se reflexiona en muchos despachos de la capital estadounidense, con el l\u00edder de Morena en Los Pinos lo ser\u00eda a\u00fan m\u00e1s. En los \u00faltimos d\u00edas, los asesores econ\u00f3micos m\u00e1s cercanos a L\u00f3pez Obrador han dejado caer, que acatar\u00e1n el tratado que salga de las actuales negociaciones siempre y cuando este no conlleve \u201cgrandes cesiones\u201d para M\u00e9xico.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">La fecha l\u00edmite para pactar las l\u00edneas b\u00e1sicas del nuevo tratado de libre cambio es, seg\u00fan todas las fuentes consultadas, el 15 de mayo. Solo as\u00ed podr\u00eda quedar el tiempo suficiente para su tramitaci\u00f3n parlamentaria en EE UU en la actual composici\u00f3n de las C\u00e1maras. Tambi\u00e9n porque el periodo de poderes especiales que el Congreso le otorg\u00f3 a Trump -el llamado\u00a0<em>fast-track<\/em>&#8211; est\u00e1 cerca de expirar y, de alargarse las conversaciones, el presidente necesitar\u00eda de una pr\u00f3rroga adicional.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">\u201cEn M\u00e9xico, como ha ocurrido con el\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/economia\/2018\/03\/08\/actualidad\/1520522599_033974.html\" target=\"_blank\">TPP<\/a>\u00a0[Acuerdo de Asociaci\u00f3n Transpac\u00edfico, que ha sido ratificado apenas un mes despu\u00e9s de que se cerrase el acuerdo], el Senado lo aprobar\u00eda en nada\u201d, augura Ignacio Mart\u00ednez, coordinador del Laboratorio de An\u00e1lisis en Comercio Exterior de la Universidad Nacional Aut\u00f3noma de M\u00e9xico (UNAM). \u201cPero en EE UU ser\u00e1 diferente: all\u00ed la tramitaci\u00f3n ser\u00e1 m\u00e1s dura\u201d. Su pron\u00f3stico es rotundo: el acuerdo llegar\u00e1, dice, entre el 5 y el 10 de mayo. Las fechas cuadran: los ministros al cargo de la negociaci\u00f3n volver\u00e1n a verse las caras el pr\u00f3ximo d\u00eda 7, una de las fechas se\u00f1aladas en el calendario trilateral. Pero el acuerdo no est\u00e1 ni mucho menos garantizado. \u201cEl riesgo es pecar de optimismo\u201d, subraya un ex alto funcionario que trabaj\u00f3 activamente en la firma del actual TLC, en 1994, que prefiere mantenerse en el anonimato. \u201cIgual que hasta hace bien poco \u00e9ramos demasiado pesimistas, quiz\u00e1 ahora estemos siendo demasiado optimistas. Nada est\u00e1 cerrado hasta que todo est\u00e1 cerrado\u201d.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">Si llega el acuerdo, una posibilidad ha ido tomando fuerza en los \u00faltimos d\u00edas tanto en Washington como en la Ciudad de M\u00e9xico: que, inmediatamente despu\u00e9s de que Trump anuncie el principio de entendimiento, anuncie la cancelaci\u00f3n del texto actualmente vigente. De esa forma, cumplir\u00eda una de sus grandes promesas electorales -que el TLC actual acabe siendo papel mojado- y el reloj echar\u00eda a andar. El mensaje para sus propios senadores ser\u00eda inequ\u00edvoco: o hay fumata blanca -por la v\u00eda r\u00e1pida- para el nuevo tratado o EE UU, M\u00e9xico y Canad\u00e1 se quedar\u00e1n sin un marco rector para los m\u00e1s de 1,2 billones de d\u00f3lares de intercambios comerciales anuales.<\/p>\n<p class=\"x_MsoNormal\" style=\"color: #444444\">Aunque cada vez m\u00e1s cercanas, las posturas de los tres pa\u00edses a\u00fan no terminan de converger. Los temas m\u00e1s espinosos -las llamadas \u201cp\u00edldoras venenosas\u201d, a saber: contenido regional en la industria automotriz, resoluci\u00f3n de controversia o el intento de Trump de cancelar el TLC cada cinco a\u00f1os si los tres pa\u00edses no acuerdan antes lo contrario- todav\u00eda est\u00e1n sin resolver. Pero las posiciones se han acercado mucho. En el caso del\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/economia\/2017\/08\/29\/actualidad\/1503973886_606405.html\" target=\"_blank\">sector automotor<\/a>, contrario a la propuesta inicial de la Administraci\u00f3n Trump sobre reglas de origen, las negociaciones se han multiplicado en las \u00faltimas semanas y el Gobierno estadounidense\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/economia\/2018\/03\/21\/actualidad\/1521649737_025893.html\" target=\"_blank\">ya ha dejado caer sus pol\u00e9micas exigencias iniciales<\/a>. \u201cTanto M\u00e9xico como Estados Unidos han comenzado a ceder. Canad\u00e1 es quien muestra mayor resistencia, en aspectos como modificar los mecanismos de soluci\u00f3n de disputas comerciales\u201d, concluye Jos\u00e9 Luis de la Cruz, director del Instituto para el Desarrollo Industrial y el Crecimiento Econ\u00f3mico de M\u00e9xico. \u201cHay elementos para considerar que se puede concluir la negociaci\u00f3n en las pr\u00f3ximas semanas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los tres pa\u00edses aceleran el paso en las conversaciones con la vista puesta en llegar a un acuerdo antes de mediados de mayo<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,23],"tags":[],"class_list":["post-477308","post","type-post","status-publish","format-standard","hentry","category-canada","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477308"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477308\/revisions"}],"predecessor-version":[{"id":477310,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477308\/revisions\/477310"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}