{"id":477484,"date":"2018-05-11T17:39:45","date_gmt":"2018-05-11T21:39:45","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477484"},"modified":"2018-05-11T17:39:45","modified_gmt":"2018-05-11T21:39:45","slug":"asesinado-a-balazos-un-candidato-de-morena-en-guanajuato-mientras-pedia-el-voto","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/05\/11\/asesinado-a-balazos-un-candidato-de-morena-en-guanajuato-mientras-pedia-el-voto\/","title":{"rendered":"Asesinado a balazos un candidato de Morena en Guanajuato mientras ped\u00eda el voto"},"content":{"rendered":"<div id=\"attachment_477485\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1526067404_446569_1526068546_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477485\" class=\"size-large wp-image-477485\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1526067404_446569_1526068546_noticia_normal_recorte1-560x368.jpg\" alt=\"Jos\u00e9 Aguirre en un evento con AMLO.\" width=\"560\" height=\"368\" \/><\/a><p id=\"caption-attachment-477485\" class=\"wp-caption-text\">Jos\u00e9 Aguirre en un evento con AMLO.<\/p><\/div>\n<p style=\"color: #444444\">La violencia ha alcanzado a otro candidato a alcalde en M\u00e9xico. Jos\u00e9 Remedios Aguirre, contendiente por Morena (izquierda) a la alcald\u00eda de Apaseo el Alto,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/guanajuato\/a\/\">Guanajuato<\/a>, fue atacado este viernes por un grupo armado en la entrada a un parque ecol\u00f3gico en el centro de la ciudad ubicada en la regi\u00f3n de El Baj\u00edo. En el suceso tambi\u00e9n result\u00f3 herida otra persona, de acuerdo con informaci\u00f3n de la polic\u00eda municipal.<\/p>\n<section id=\"sumario_1|apoyos\" class=\"sumario_apoyos derecha\" style=\"color: #444444\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_1\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<header class=\"sumario-encabezado\" style=\"font-style: inherit\">\n<h3 class=\"sumario-titulo\" style=\"font-style: inherit;color: #111111\"><span class=\"sin_enlace\" style=\"font-weight: inherit;font-style: inherit\">M\u00c1S INFORMACI\u00d3N<\/span><\/h3>\n<\/header>\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"apoyos\" style=\"font-style: inherit\">\n<ul class=\"apoyos-listado\" style=\"font-style: inherit\">\n<li class=\"apoyo_normal apoyo_sinfoto\" style=\"font-style: inherit\"><span class=\"apoyo-titulo\" style=\"font-style: inherit\"><a style=\"font-style: inherit;color: #000000\" href=\"https:\/\/elpais.com\/internacional\/2018\/05\/09\/mexico\/1525825144_065754.html\">Matan a Abel Mont\u00fafar: ya van 18 pol\u00edticos asesinados en Guerrero en ocho meses<\/a><\/span><\/li>\n<li class=\"apoyo_ apoyo_sinfoto\" style=\"font-style: inherit\"><span class=\"apoyo-titulo\" style=\"font-style: inherit\"><a style=\"font-style: inherit;color: #000000\" href=\"https:\/\/elpais.com\/internacional\/2018\/05\/10\/actualidad\/1525908899_782602.html\">M\u00e9xico resuelve el asesinato de un exgobernador siete a\u00f1os despu\u00e9s<\/a><\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">Los atacantes viajaban en un Ford Mustang convertible blanco con placas de Estados Unidos, seg\u00fan los primeros reportes. Antes de convertirse en candidato, Aguirre S\u00e1nchez fungi\u00f3 como director de Seguridad P\u00fablica de este municipio entre 2012 y 2015. Autoridades ministeriales dijeron que el aspirante ten\u00eda abierto un proceso penal por el delito de homicidio y contaba con un amparo.<\/div>\n<\/div>\n<div id=\"inread1\" style=\"font-style: inherit\">\u00a0El candidato de\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/morena_movimiento_regeneracion_nacional\/a\">Morena<\/a>\u00a0al Gobierno local de Guanajuato, Ricardo Sheffield Padilla, ha condenado el homicidio a trav\u00e9s de su cuenta de Twitter y para exigir seguridad para los aspirantes locales. \u201cPor este hecho tan lamentable, todos los candidatos de la coalici\u00f3n en Guanajuato de Juntos Haremos Historia [una coalici\u00f3n junto a los partidos Encuentro Social y del Trabajo] hemos suspendido actividades de campa\u00f1a hasta no contar con las garant\u00edas indispensables por parte del Gobierno Estatal y del Gobierno Federal para continuar\u201d,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/twitter.com\/SheffieldGto\/status\/995008453327208448\">escribi\u00f3<\/a>.<\/div>\n<section id=\"sumario_2|html\" class=\"sumario_html centro\" style=\"color: #444444\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_2\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<div class=\"SandboxRoot env-bp-350\" style=\"color: #1c2022\">\n<div id=\"twitter-widget-0\" class=\"EmbeddedTweet EmbeddedTweet--edge js-clickToOpenTarget tweet-InformationCircle-widgetParent\" lang=\"es\">\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/SheffieldGto\/status\/995011826579525632\">\n<div class=\"Tweet-header\"><a class=\"TweetAuthor-avatar Identity-avatar u-linkBlend\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/SheffieldGto\"><img decoding=\"async\" class=\"Avatar Avatar--edge\" src=\"https:\/\/pbs.twimg.com\/profile_images\/979742111640772608\/B1mZWYQh_normal.jpg\" alt=\"\" \/><\/a><\/p>\n<div class=\"TweetAuthor js-inViewportScribingTarget\">\n<div class=\"TweetAuthor-nameScreenNameContainer\"><span class=\"TweetAuthor-decoratedName\"><span class=\"TweetAuthor-name Identity-name customisable-highlight\" style=\"font-weight: bold\" title=\"Ricardo Sheffield\">Ricardo Sheffield<\/span><\/span><span class=\"TweetAuthor-screenName Identity-screenName\" dir=\"ltr\" style=\"color: #697882\" title=\"@SheffieldGto\">@SheffieldGto<\/span><\/div>\n<\/div>\n<div class=\"Tweet-brand\"><\/div>\n<\/div>\n<div class=\"Tweet-body e-entry-content\">\n<div class=\"u-hiddenVisually js-inViewportScribingTarget\"><\/div>\n<p class=\"Tweet-text e-entry-title\" dir=\"ltr\" lang=\"es\">Nuestro compa\u00f1ero Remedios Aguirre, era un hombre apreciado en Apaseo el Alto, hace a\u00f1os fue Director de Seguridad P\u00fablica, su victoria era muy factible en las pr\u00f3ximas elecciones, no se entiende otra motivaci\u00f3n que no sea pol\u00edtica o de amedrentamiento para quitarle la vida.<\/p>\n<div class=\"Tweet-metadata dateline\" style=\"color: #697882\"><a class=\"u-linkBlend u-url customisable-highlight long-permalink\" style=\"color: inherit\" href=\"https:\/\/twitter.com\/SheffieldGto\/status\/995011826579525632\">14:44 &#8211; 11 may. 2018<\/a><\/div>\n<ul class=\"Tweet-actions Tweet-action--newsActions\">\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--heartEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--heart TweetAction TweetAction--heartEdge\" style=\"color: #697882\" title=\"Me gusta\" href=\"https:\/\/twitter.com\/intent\/like?tweet_id=995011826579525632\"><span class=\"TweetAction-stat\">40<\/span><\/a><\/li>\n<li class=\"Tweet-action Tweet-action--newsAction\">\n<div class=\"Icon Icon--replyEdge TweetAction-icon\"><\/div>\n<p><a class=\"Tweet-action--replyEdge TweetAction TweetAction--replyEdge\" style=\"color: #697882\" title=\"Ver la conversaci\u00f3n en Twitter\" href=\"https:\/\/twitter.com\/SheffieldGto\/status\/995011826579525632\"><span class=\"TweetAction-stat\">68 personas est\u00e1n hablando de esto<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/blockquote>\n<\/div>\n<div class=\"tweet-InformationCircle--bottom tweet-InformationCircle\"><a class=\"Icon Icon--informationCircleWhite js-inViewportScribingTarget\" style=\"color: #2b7bb9\" title=\"Informaci\u00f3n y privacidad de Twitter Ads\" href=\"https:\/\/support.twitter.com\/articles\/20175256\"><span class=\"u-hiddenVisually\">Informaci\u00f3n y privacidad de Twitter Ads<\/span><\/a><\/div>\n<\/div>\n<div class=\"resize-sensor\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p style=\"color: #444444\">El coordinador territorial de Morena en el norte del pa\u00eds, Ricardo Monreal, ha expresado a trav\u00e9s de esta misma red social que hab\u00edan advertido a las autoridades del peligro que corr\u00edan sus candidatos y se hab\u00eda enviado un mapa de riesgos. La coordinadora de campa\u00f1a del candidato a la Presidencia,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/andres_manuel_lopez_obrador\/a\">Andr\u00e9s Manuel L\u00f3pez Obrador<\/a>, Tatiana Clouthier tambi\u00e9n ha condenado el asesinato y ha exigido a las autoridades aclarar el hecho.<\/p>\n<p style=\"color: #444444\"><span style=\"font-style: inherit\">La lucha por el poder de miles de candidatos se llevar\u00e1 a cabo en un ambiente marcado por la violencia.\u00a0<\/span>Con este asesinato ya han muerto 19 pol\u00edticos desde el arranque del proceso electoral, en septiembre. S<span style=\"font-style: inherit\">e han registrado m\u00e1s de 30 ataques a candidatos o funcionarios con licencia, desde la precampa\u00f1a. Esto encendi\u00f3 las alarmas de la Organizaci\u00f3n de Estados Americanos (OEA). &#8220;Va un promedio de un asesinato de un candidato cada cuatro o cinco d\u00edas, es un margen de violencia absolutamente inaceptable en un proceso electoral&#8221;, denunci\u00f3 el secretario general del organismo, Luis Almagro, el pasado 16 de marzo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Remedios Aguirre, aspirante de Morena a la alcald\u00eda de Apaseo el Alto, fue atacado en un parque ecol\u00f3gico por un grupo armado<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-477484","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477484"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477484\/revisions"}],"predecessor-version":[{"id":477486,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477484\/revisions\/477486"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}