{"id":477502,"date":"2018-05-17T09:09:12","date_gmt":"2018-05-17T13:09:12","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477502"},"modified":"2018-05-17T09:09:12","modified_gmt":"2018-05-17T13:09:12","slug":"daniel-ortega-se-aferra-a-la-violencia-para-mantener-el-poder-en-nicaragua","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/05\/17\/daniel-ortega-se-aferra-a-la-violencia-para-mantener-el-poder-en-nicaragua\/","title":{"rendered":"Daniel Ortega se aferra a la violencia para mantener el poder en Nicaragua"},"content":{"rendered":"<div id=\"attachment_477503\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1526504337_807867_1526546316_noticia_fotograma.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477503\" class=\"size-large wp-image-477503\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1526504337_807867_1526546316_noticia_fotograma-560x315.jpg\" alt=\"Daniel Ortega y su esposa en la primera mesa de di\u00e1logo. \" width=\"560\" height=\"315\" \/><\/a><p id=\"caption-attachment-477503\" class=\"wp-caption-text\">Daniel Ortega y su esposa en la primera mesa de di\u00e1logo.<\/p><\/div>\n<p style=\"color: #444444\">Madalaine Caracas, estudiante de Comunicaci\u00f3n de apenas 20 a\u00f1os, tom\u00f3 el micr\u00f3fono y uno a uno ley\u00f3 frente al presidente\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/daniel_ortega\/a\/\">Daniel Ortega<\/a>\u00a0la lista de universitarios asesinados durante la dura represi\u00f3n ordenada por el mandatario en\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/nicaragua\/a\/\">Nicaragua<\/a>, que ha dejado cerca de 60 muertos. \u201c\u00a1Presente!\u201d, gritaban los j\u00f3venes convocados este mi\u00e9rcoles en la sala al escuchar el nombre de cada muerto. Ortega los o\u00eda sin inmutarse. El otrora hombre fuerte de Nicaragua quedaba desnudado en una mesa de di\u00e1logo convocada por la Iglesia para encontrar una salida a la profunda crisis que sufre este pa\u00eds centroamericano, en la que se demostr\u00f3, sin embargo, que el mandatario est\u00e1 solo, debilitado, acorralado, pero dispuesto a aferrarse a la violencia como \u00fanica alternativa para mantener el control del poder.<\/p>\n<p style=\"color: #444444\"><span style=\"color: #444444\">Ortega intent\u00f3 imponer en la apertura del di\u00e1logo temas econ\u00f3micos como la reforma a la Seguridad Social que desat\u00f3 en abril la crisis, pero los obispos no permitieron hablar a su delegado, el asesor econ\u00f3mico Bayardo Arce, quien establecer\u00eda la agenda del Ejecutivo.\u00a0<\/span><a style=\"color: #016ca2\" title=\"Los obispos de Nicaragua advierten a Ortega de que \u201cnadie es eterno\u201d\" href=\"https:\/\/elpais.com\/internacional\/2014\/05\/23\/actualidad\/1400870531_878835.html\">Abelardo Mata<\/a><span style=\"color: #444444\">, secretario de la Conferencia Episcopal, marc\u00f3 el tono de la reuni\u00f3n al tomar la palabra y exigir al presidente que ordene el cese de la represi\u00f3n contra las protestas pac\u00edficas que exigen su salida del poder y que \u201cretirara la polic\u00eda a sus cuarteles\u201d. \u201cHa comenzado una revoluci\u00f3n no armada\u201d, dijo el obispo. \u201cSi usted quiere desmontar esa revoluci\u00f3n, no va a ser a fuerza de balas\u201d, advirti\u00f3 Mata.<\/span><\/p>\n<p><br style=\"color: #444444\" \/><span style=\"color: #444444\">Por primera vez en 11 a\u00f1os de mandato, acosado por la presi\u00f3n popular que exige su salida del poder, Ortega daba la cara ante un centenar de personas que se plantaron en el di\u00e1logo con exigencias espec\u00edficas para el mandatario, entre ellas la justicia para las v\u00edctimas de la violencia desatada por el Estado. Ortega lleg\u00f3 a la mesa seguro de que podr\u00eda imponer una agenda que atrajera la atenci\u00f3n del\u00a0<\/span><a style=\"color: #016ca2\" title=\"Los empresarios de Nicaragua se distancian de Ortega\" href=\"https:\/\/elpais.com\/internacional\/2018\/04\/20\/america\/1524260894_677241.html\">sector empresarial<\/a><span style=\"color: #444444\">, con quienes durante m\u00e1s de una d\u00e9cada ha mantenido una relaci\u00f3n de \u201cconsenso\u201d, tomando decisiones a puerta cerrada sobre temas claves para el desarrollo econ\u00f3mico del pa\u00eds. Esa relaci\u00f3n era clara: Ortega se hac\u00eda con el control del Estado, destru\u00eda las instituciones democr\u00e1ticas, acallaba las voces cr\u00edticas y amenazaba a la sociedad civil, mientras daba concesiones que mantuvieran satisfechos a los empresarios.<\/span><br style=\"color: #444444\" \/><br style=\"color: #444444\" \/><span style=\"color: #444444\">Ese esquema se rompi\u00f3 en abril, tras la fuerte represi\u00f3n. Varios empresarios consultados por EL PA\u00cdS al final de la sesi\u00f3n dijeron que Ortega se equivoc\u00f3 al no abordar el grave deterioro institucional que sufre Nicaragua tras m\u00e1s de una d\u00e9cada de mandato del exguerrillero sandinista. \u201cOrtega vino a incrementar la crisis del pa\u00eds. Dudamos de que las intenciones del di\u00e1logo sean en base a lo que hemos expuesto. Hemos sido claros: debe haber justicia, que paguen los culpables y que haya seguridad para la poblaci\u00f3n que se manifiesta\u201d, agrega Michael Healy, presidente de la\u00a0<\/span><a style=\"color: #016ca2\" href=\"http:\/\/www.congresoagropecuarioupanic.com.ni\/\" target=\"_blank\">Uni\u00f3n de Productores y Agropecuarios de Nicaragua (UPANIC)<\/a><span style=\"color: #444444\">.<\/span><\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">Healy se muestra a favor del fin del mandato de Ortega. \u201cAl final de este di\u00e1logo deber\u00edamos tener un nuevo Gobierno, interino, que venga a poner el orden, y posteriormente llamar a elecciones libres\u201d, agreg\u00f3. El empresario apunta, adem\u00e1s, que si el di\u00e1logo fracasa, no descartan un paro nacional. \u201cSe esperaba en esta mesa una respuesta positiva del Gobierno, pero fue negativa, por lo tanto, vamos a evaluar un paro nacional, aunque el pa\u00eds ya est\u00e1 pr\u00e1cticamente parado\u201d. Las conversaciones seguir\u00e1n el viernes.<\/div>\n<\/div>\n<p style=\"color: #444444\">\nNicaragua cumplir\u00e1 ese d\u00eda\u00a0<a style=\"font-style: inherit;color: #016ca2\" title=\"El movimiento juvenil que le planta cara a Daniel Ortega\" href=\"https:\/\/elpais.com\/internacional\/2018\/04\/13\/actualidad\/1523651830_249206.html\">un mes in\u00e9dito de manifestaciones<\/a>. Desde hace dos semanas se han realizado los llamados \u201ctranques\u201d: obstaculizaci\u00f3n en importantes zonas productivas, donde han sido los campesinos quienes han impedido el paso hacia la capital, cada vez m\u00e1s aislada. Las protestas tambi\u00e9n se han sucedido en las principales ciudades del pa\u00eds, que han sido atacadas con violencia por las huestes de Ortega y por la Polic\u00eda Nacional. El martes se dieron cruentos enfrentamientos en\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/www.google.com.mx\/maps\/place\/Matagalpa,+Nicaragua\/@12.3757146,-84.9832077,7z\/data=!4m5!3m4!1s0x8f724830f9561d2f:0x1793a46db7ccdb99!8m2!3d12.9290069!4d-85.9151211\" target=\"_blank\">Matagalpa (norte del pa\u00eds)<\/a>, con un saldo de al menos tres muertos y decenas de heridos.<\/p>\n<p>En pleno choque, Ortega afirm\u00f3 este martes que su Gobierno quiere la paz. E hizo referencia a la masacre del Ej\u00e9rcito israel\u00ed que abati\u00f3 a tiros a 59 manifestantes palestinos esta semana, pero sin dedicar una palabra a la orden dada por su propio Ejecutivo para matar a quienes se protestaban pac\u00edficamente en territorio nacional.<\/p>\n<p style=\"color: #444444\">A medida que los d\u00edas pasan, poco a poco se van conociendo historias de horror. Seg\u00fan las denuncias de organizaciones de derechos humanos, se lleg\u00f3 a emplear francotiradores para abatir a los manifestantes. Entre las decenas de muertos se encuentran al menos\u00a0<a style=\"font-style: inherit;color: #016ca2\" title=\"Ocho heridos en las protestas contra la reforma de la Seguridad Social en Nicaragua\" href=\"https:\/\/elpais.com\/internacional\/2018\/04\/19\/america\/1524095967_183633.html?rel=mas\">25 estudiantes<\/a>, en su mayor\u00eda menores de 25 a\u00f1os. Muchos fallecieron tras recibir disparos en la cabeza y el cuello. Ortega dijo, sin embargo, que quienes se manifiestan \u201caterrorizan\u201d a los nicarag\u00fcenses y son culpables de los saqueos que se han registrado en varias partes del pa\u00eds y de las muertes de oficiales de la Polic\u00eda. El mandatario asegur\u00f3 que de la\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/www.upoli.edu.ni\/\" target=\"_blank\">Universidad Polit\u00e9cnica de Nicaragua (UPOLI)<\/a>\u00a0\u2014basti\u00f3n de la resistencia estudiantil frente al r\u00e9gimen\u2014 \u201csalen bandas de paramilitares\u201d, utilizando el mismo t\u00e9rmino con el que la Iglesia se refiri\u00f3 a los grupos de choque del oficialismo. Ortega, al final, se neg\u00f3 a cesar la represi\u00f3n en Nicaragua.<\/p>\n<p>La intransigencia del mandatario le ha costado el apoyo popular, incluido el de sus seguidores. Una encuesta dada a conocer este martes por la firma CID Gallup muestra que casi siete de cada 10 nicarag\u00fcenses est\u00e1n a favor de que el presidente deje el poder, entre ellos un 30% que se define como &#8220;sandinista&#8221;. Adem\u00e1s, el 78% de los entrevistados opina que el pa\u00eds va \u201cpor mal camino\u201d. La interpretaci\u00f3n de la encuestadora es que estos resultados demuestran que los nicarag\u00fcenses han perdido el miedo a expresar libremente su opini\u00f3n.<\/p>\n<p>Una muestra de esta nueva tendencia es Antonia Saballos, habitante del barrio Juan Emilio Menocal de la capital. &#8220;En Nicaragua hay una lucha justa&#8221;, dice, en referencia a las manifestaciones contra Ortega. &#8220;Queremos que se vaya la dictadura. Soy sandinista, pero no danielista. No estoy de acuerdo con lo que han hecho, porque como madre me duele la muerte de todos esos muchachos que han matado. Ortega tiene que respetar a Nicaragua, porque esto no es Venezuela. Aqu\u00ed manda el pueblo: as\u00ed lleg\u00f3 \u00e9l al poder y as\u00ed lo vamos a sacar&#8221;.<\/p>\n<p>Ortega dej\u00f3 el martes la sede del Seminario de Nuestra Se\u00f1ora de F\u00e1tima de Managua, donde se inaugur\u00f3 el di\u00e1logo, con una lista de asesinados por la represi\u00f3n le\u00edda en su cara, el descontento de los empresarios y una exigencia directa de la Iglesia de parar la violencia del Estado. Afuera lo esperaban vecinos del Seminario que le gritaban \u201c\u00a1asesino, asesino!\u201d, mientras el mandatario, junto a su vicepresidenta y esposa,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/rosario_murillo_zambrana\/a\" target=\"_blank\">Rosario Murillo<\/a>, se retiraba en su Mercedes Benz blindado. Para muchos queda cada vez m\u00e1s claro que la \u00fanica salida a la crisis de Nicaragua pasa por la dimisi\u00f3n de Ortega tras 11 a\u00f1os de mandatario autoritario en Nicaragua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exguerrillero se niega a detener los ataques de sus huestes, pero empieza a perder el favor empresarial tras casi un mes de protestas<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-477502","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477502"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477502\/revisions"}],"predecessor-version":[{"id":477504,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477502\/revisions\/477504"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}