{"id":477551,"date":"2018-05-21T22:35:54","date_gmt":"2018-05-22T02:35:54","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477551"},"modified":"2018-05-21T22:35:54","modified_gmt":"2018-05-22T02:35:54","slug":"las-tortillas-de-amlo-nestora-salgado-y-otras-polemicas-del-debate","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/05\/21\/las-tortillas-de-amlo-nestora-salgado-y-otras-polemicas-del-debate\/","title":{"rendered":"Las tortillas de AMLO, Nestora Salgado y otras pol\u00e9micas del debate"},"content":{"rendered":"<div id=\"attachment_477552\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1526927948_933533_1526930266_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477552\" class=\"size-large wp-image-477552\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1526927948_933533_1526930266_noticia_normal_recorte1-560x304.jpg\" alt=\"Imagen de los candidatos Ricardo Anaya y Andr\u00e9s Manuel L\u00f3pez Obrador durante el segundo debate. INE\" width=\"560\" height=\"304\" \/><\/a><p id=\"caption-attachment-477552\" class=\"wp-caption-text\">Imagen de los candidatos Ricardo Anaya y Andr\u00e9s Manuel L\u00f3pez Obrador durante el segundo debate. INE<\/p><\/div>\n<p style=\"color: #444444\">La gesti\u00f3n de L\u00f3pez Obrador (AMLO) al frente de la Jefatura de Gobierno de la Ciudad de M\u00e9xico volvi\u00f3 a acaparar buena parte del segundo debate entre los candidatos a la presidencia del Gobierno mexicano. Las cifras de aquellos a\u00f1os<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/05\/21\/mexico\/1526881664_964397.html\" target=\"_blank\">sirvieron para que el candidato de Morena diese cuenta de su buen hacer en aquel periodo<\/a>\u00a0y al mismo tiempo le permitieron al l\u00edder de Por M\u00e9xico al frente -la coalici\u00f3n PAN PRD-, Ricardo Anaya, para denostar la capacidad de gobernar del aspirante de izquierdas. Unos datos rodeados de pol\u00e9mica que se suman a las declaraciones de Jos\u00e9 Antonio Meade (PRI) sobre la ex l\u00edder de la polic\u00eda comunitaria de Olinal\u00e1 (Guerrero) Nestora Salgado o los precios que AMLO le atribuye a la tortilla en 1988.<\/p>\n<h3 style=\"color: #111111\">La pol\u00e9mica sobre Nestora Salgado<\/h3>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">Meade llam\u00f3 \u201csecuestradora\u201d a Nestora Salgado, ex l\u00edder de la polic\u00eda comunitaria de Olinal\u00e1, en Guerrero, que aspira ahora a ser senadora por la formaci\u00f3n de L\u00f3pez Obrador. Salgado estuvo en prisi\u00f3n dos a\u00f1os y medio acusada de secuestro. Aunque todav\u00eda quedan procesos abiertos,\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.elfinanciero.com.mx\/nacional\/juez-notifica-libertad-a-nestora-salgado\" target=\"_blank\">el 17 de marzo de 2016 un juzgado de la Ciudad de M\u00e9xico decret\u00f3 la libertad para la activista<\/a>. En febrero de ese a\u00f1o, el Grupo de Trabajo sobre la Detenci\u00f3n Arbitraria de Naciones Unidas consider\u00f3 su detenci\u00f3n \u201cilegal y arbitraria\u201d y\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/www.efe.com\/efe\/america\/mexico\/panel-de-onu-exige-a-mexico-liberacion-inmediata-activista-nestora-salgado\/50000545-2828437\" target=\"_blank\">exigi\u00f3 su puesta en libertad inmediata, as\u00ed como una \u201ccompensaci\u00f3n adecuada\u201d<\/a>\u00a0por las numerosas violaciones a los derechos humanos.<\/div>\n<\/div>\n<h3 style=\"color: #111111\">Las armas que cruzan ilegalmente r\u00edo Bravo<\/h3>\n<p style=\"color: #444444\">Ricardo Anaya asegur\u00f3 durante el debate que 200.000 armas llegan de forma ilegal de Estados Unidos a M\u00e9xico. El candidato de Por M\u00e9xico al frente parec\u00eda<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/www.americanprogress.org\/issues\/guns-crime\/reports\/2018\/02\/02\/445659\/beyond-our-borders\/\" target=\"_blank\">hacer referencia al informe\u00a0<em>Beyond our borders<\/em>\u00a0del Center for American Progress<\/a>que cifra en 213.000 las armas de fuego que cruzan ilegalmente R\u00edo Bravo. Adem\u00e1s, esta investigaci\u00f3n se\u00f1ala que entre 2011 y 2016 al menos 106.000 armas fabricadas en EE UU estuvieron vinculadas con actividades delictivas en M\u00e9xico.<\/p>\n<h3 style=\"color: #111111\">El mandato de L\u00f3pez Obrador, en cuesti\u00f3n<\/h3>\n<p style=\"color: #444444\">Ricardo Anaya acus\u00f3 a L\u00f3pez Obrador de que durante su gesti\u00f3n al frente del Gobierno de la ciudad el desempleo aument\u00f3 un 63%.\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.inegi.org.mx\/est\/contenidos\/espanol\/sistemas\/perspectivas\/perspectiva-df.pdf\" target=\"_blank\">La tasa en el 2000 fue de un 3,5% en la capital mexicana y en 2006 subi\u00f3 al 5,5%,<\/a>\u00a0seg\u00fan datos del Instituto Nacional de Estad\u00edstica. Esto supone un incremento de un 57,14%, aunque bien es cierto que L\u00f3pez Obrador empez\u00f3 su mandato en diciembre, por lo que ser\u00eda m\u00e1s justo atribuirle la tasa de 2001: 3,9%, lo que supone entonces un incremento durante sus a\u00f1os como jefe de Gobierno del 41,03%.<\/p>\n<p style=\"color: #444444\">Anaya tambi\u00e9n quiso atacar a L\u00f3pez Obrador asegurando que durante su gesti\u00f3n en la capital baj\u00f3 la inversi\u00f3n. Sin embargo, el candidato de la izquierda rebati\u00f3 el argumento asegurando que su mandato fue el periodo en el que lleg\u00f3 m\u00e1s inversi\u00f3n extranjera directa a la capital. En concreto asegura que fueron 37.000 millones de d\u00f3lares, una cifra muy similar\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/datos.gob.mx\/busca\/dataset\/inversion-extranjera-directa\/resource\/b3a85b38-37c1-4f12-a35b-060bf55f4510\" target=\"_blank\">a la que aporta la Secretar\u00eda de Econom\u00eda<\/a>\u00a0que considera que entre 2001 y 2006, la inversi\u00f3n extranjera directa fue de 37.353 millones de d\u00f3lares. Se trata de un dato no superado en el sexenio anterior ni posterior al de L\u00f3pez Obrador. Esta misma entidad establece que en los seis a\u00f1os siguientes (2007-2012) solo se alcanzaron los 31.970 millones\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/www.gob.mx\/cms\/uploads\/attachment\/file\/255232\/Carpeta_IED.pdf\" target=\"_blank\">y en los seis anteriores (1995 &#8211; 2000) apenas lleg\u00f3 a 28.853 millones<\/a>. A falta del dato de 2018, desde 2013 hasta 2017 la cifra se ha situado en los 27.687 millones.<\/p>\n<h3 style=\"color: #111111\">El TPP y los votos de Morena<\/h3>\n<p style=\"color: #444444\">\u201cUna secta vot\u00f3 en contra de esto en el Senado, la de Morena, o no saben o no quieren que progresemos\u201d, asegur\u00f3 Meade durante el cara a cara presidencial. El candidato hac\u00eda referencia al Acuerdo de Asociaci\u00f3n Transpac\u00edfico (TPP) que se ratific\u00f3 en abril en el Senado mexicano con 73 votos a favor y 24 en contra. Lo cierto es que Morena no tiene representaci\u00f3n en esta c\u00e1mara. Fue en realidad el PT, con quien esta formaci\u00f3n va en coalici\u00f3n a las presidenciales del 1 de julio, el que dijo no al acuerdo comercial con 11 pa\u00edses del Pac\u00edfico, junto a algunos de senadores del PAN y el PRD.<\/p>\n<h3 style=\"color: #111111\">Las exportaciones de Texas a M\u00e9xico<\/h3>\n<p style=\"color: #444444\">Ricardo Anaya sostuvo que Texas exporta m\u00e1s a M\u00e9xico que todo EE UU a Jap\u00f3n. Una afirmaci\u00f3n que las cifras de la Secretar\u00eda de Econom\u00eda mexicana y el Banco Mundial permiten corroborar.\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/consulmex.sre.gob.mx\/austin\/images\/politicos\/Texas-Mexico-trade-2016.pdf\" target=\"_blank\">El 40% de las exportaciones de Texas son a su vecino del sur,<\/a>\u00a0lo que supone 92.674 millones de d\u00f3lares en 2016, seg\u00fan el Ministerio mexicano, mientras que\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/wits.worldbank.org\/countrysnapshot\/es\/usa\/textview\" target=\"_blank\">las de Estados Unidos al pa\u00eds nip\u00f3n alcanzan los 63.234 millones de d\u00f3lares<\/a>, seg\u00fan el organismo internacional.<\/p>\n<h3 style=\"color: #111111\">Las tortillas de AMLO<\/h3>\n<p style=\"color: #444444\">Andr\u00e9s Manuel L\u00f3pez Obrador quiso ejemplificar la p\u00e9rdida de poder adquisitivo de la gente comparando el precio del salario m\u00ednimo con el del kilogramo de tortilla hace 30 a\u00f1os y en la actualidad. Seg\u00fan el aspirante de Morena, en 1988 se pod\u00edan comprar 50 kilos con el salario m\u00e1s bajo, mientras que en 2018 \u00fanicamente alcanza para seis.<\/p>\n<p style=\"color: #444444\">En 1985\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.dof.gob.mx\/nota_detalle.php?codigo=4778677&amp;fecha=30\/12\/1985\" target=\"_blank\">el precio m\u00e1s bajo del kilo de tortilla se fij\u00f3 en 45 pesos de entonces (0,045 actuales),<\/a>\u00a0seg\u00fan el diario oficial de la federaci\u00f3n y\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.conasami.gob.mx\/pdf\/salario_minimo\/sal_min_gral_prom.pdf\" target=\"_blank\">el salario m\u00ednimo en aquel a\u00f1o se situ\u00f3 en los 938,81 pesos (0,939)<\/a>, seg\u00fan la Comisi\u00f3n Nacional de los Salarios M\u00ednimos. Entonces se pod\u00edan comprar casi 21 kilos de tortilla con el sueldo m\u00e1s bajo.<\/p>\n<p style=\"color: #444444\"><a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/www.researchgate.net\/publication\/262667268_Evolucion_de_los_precios_de_los_alimentos_y_nutrimentos_en_Mexico_entre_1973_Y_2004\" target=\"_blank\">En 1990 el precio del kilo de tortilla se situ\u00f3 en 470 pesos<\/a>\u00a0(0,47 actuales) y el salario m\u00ednimo en 9.138 pesos (19,44 kilos por salario). Ambos datos quedan lejos de los 50 kilogramos que dec\u00eda el l\u00edder de Morena.<\/p>\n<p style=\"color: #444444\">En la actualidad\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.economia-sniim.gob.mx\/Tortilla.asp\" target=\"_blank\">el precio de la tortilla en Ciudad de M\u00e9xico est\u00e1 en 12,85<\/a>\u00a0pesos y el salario m\u00ednimo\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"http:\/\/www.sat.gob.mx\/informacion_fiscal\/tablas_indicadores\/paginas\/salarios_minimos.aspx\" target=\"_blank\">es de 88,36 pesos diarios<\/a>, por lo que solo alcanza para 6,8 kilogramos, una cifra m\u00e1s cercana a la que ofreci\u00f3 L\u00f3pez Obrador durante el debate presidencial.<a id=\"revista\" style=\"font-style: inherit;color: #016ca2\" name=\"revista\"><\/a><\/p>\n<section id=\"sumario_1|despiece\" class=\"sumario_despiece centro\" style=\"color: #444444\"><a style=\"font-style: inherit;color: #016ca2\" name=\"sumario_1\"><\/a><\/p>\n<div class=\"sumario__interior\" style=\"font-style: inherit\">\n<header class=\"sumario-encabezado\" style=\"font-style: inherit\">\n<h4 class=\"sumario-titulo\" style=\"font-style: inherit;color: #111111\"><span class=\"sin_enlace\" style=\"font-weight: inherit;font-style: inherit\">LA PORTADA QUE NO LE GUSTABA DEL TODO A ANAYA<\/span><\/h4>\n<\/header>\n<figure class=\"foto \" style=\"font-style: inherit\"><img loading=\"lazy\" decoding=\"async\" style=\"font-style: inherit\" src=\"https:\/\/ep01.epimg.net\/internacional\/imagenes\/2018\/05\/21\/mexico\/1526927948_933533_1526949331_sumario_normal.jpg\" alt=\"Las tortillas de AMLO, Nestora Salgado y otras pol\u00e9micas del debate\" width=\"980\" height=\"534\" \/><\/figure>\n<div class=\"sumario-texto\" style=\"font-style: inherit\">\n<p style=\"font-style: inherit\">Durante el debate, Ricardo Anaya mostr\u00f3 la portada de la revista Proceso del 24 de febrero. Utilizaba el titular principal de la publicaci\u00f3n para criticar a Jos\u00e9 Antonio Meade, pero una parte de la p\u00e1gina prefiri\u00f3 ocultarla. Era el recuadro superior donde se pod\u00eda leer: El Frente de Anaya tambi\u00e9n recluta fichas negras.<\/p>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p> Algunas de las afirmaciones expresadas por los candidatos en el segundo cara a cara presidencial<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-477551","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477551"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477551\/revisions"}],"predecessor-version":[{"id":477553,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477551\/revisions\/477553"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}