{"id":477580,"date":"2018-05-22T19:47:24","date_gmt":"2018-05-22T23:47:24","guid":{"rendered":"http:\/\/diarioelpopular.com\/?p=477580"},"modified":"2018-05-22T19:47:24","modified_gmt":"2018-05-22T23:47:24","slug":"lopez-obrador-ficha-al-exfiscal-despedido-por-el-gobierno-de-pena-nieto","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2018\/05\/22\/lopez-obrador-ficha-al-exfiscal-despedido-por-el-gobierno-de-pena-nieto\/","title":{"rendered":"L\u00f3pez Obrador ficha al exfiscal despedido por el Gobierno de Pe\u00f1a Nieto"},"content":{"rendered":"<div id=\"attachment_477581\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1527021409_730178_1527021641_noticia_normal_recorte1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-477581\" class=\"size-large wp-image-477581\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2018\/05\/1527021409_730178_1527021641_noticia_normal_recorte1-560x372.jpg\" alt=\"Santiago Nieto y L\u00f3pez Obrador, en Jalisco. MISAEL VALTIERRA CUARTOSCURO\" width=\"560\" height=\"372\" \/><\/a><p id=\"caption-attachment-477581\" class=\"wp-caption-text\">Santiago Nieto y L\u00f3pez Obrador, en Jalisco. MISAEL VALTIERRA CUARTOSCURO<\/p><\/div>\n<p style=\"color: #444444\">Santiago Nieto, el exfiscal electoral que investigaba la entrada de dinero de Odebrecht a la pol\u00edtica mexicana, reapareci\u00f3 en la campa\u00f1a. El pol\u00edtico fulminado en octubre de 2017 por el Gobierno de Enrique Pe\u00f1a Nieto, del PRI, ha aparecido este martes en un evento en Jalisco junto a\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/andres_manuel_lopez_obrador\/a\">Andr\u00e9s Manuel L\u00f3pez Obrador<\/a>, el aspirante presidencial del Movimiento de Regeneraci\u00f3n Nacional (Morena). El favorito en los sondeos rumbo a los comicios del 1 de julio ha dicho que Nieto no repetir\u00eda el cargo en su eventual Gobierno, pero que su figura es de utilidad para su cruzada anticorrupci\u00f3n. \u201cEl exfiscal tiene todo el conocimiento de lo de<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/tag\/odebrecht\/a\">Odebrecht<\/a>, tiene mucha informaci\u00f3n\u201d, dijo L\u00f3pez Obrador en su visita al municipio de Tlaquepaque.<\/p>\n<div id=\"elpais_gpt-INTEXT\" style=\"color: #444444\">\n<div id=\"google_ads_iframe_\/7811748\/elpais_web\/internacional\/intext_0__container__\" style=\"font-style: inherit\">El extitular de la Fiscal\u00eda Especializada para la Atenci\u00f3n de Delitos Electorales (Fepade) tambi\u00e9n ayudar\u00e1 a la campa\u00f1a de Morena en la defensa del voto con un proyecto para evitar la compra de sufragios. Esta es una de las obsesiones del l\u00edder del partido de izquierdas, que concurre a los comicios en la coalici\u00f3n Juntos Haremos Historia (conformada por dos partidos de izquierda y uno de derecha). \u201cA m\u00ed me importa bastante\u2026 porque yo quiero que se haga valer la democracia y que se castigue a los que compran votos, a los que obligan a la gente a votar por un partido o candidato\u201d, dijo L\u00f3pez Obrador, quien se ha considerado v\u00edctima de fraudes electorales en las presidenciales de 2006 y 2012.<\/div>\n<\/div>\n<p style=\"color: #444444\">\u201cVengo como especialista en materia electoral y me encuentro aqu\u00ed presente para mandar un mensaje de que casos como el de Odebrecht no se pueden presentar en la historia del pa\u00eds\u201d, dijo Nieto a los periodistas presentes.<\/p>\n<p style=\"color: #444444\">Nieto\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2017\/10\/20\/mexico\/1508525796_028616.html\">fue destituido de su cargo el 20 de octubre de 2017<\/a>, pocos d\u00edas despu\u00e9s de asegurar al peri\u00f3dico\u00a0<em>Reforma<\/em>\u00a0que hab\u00eda recibido presiones del exdirector de Petr\u00f3leos Mexicanos, Emilio Lozoya. El funcionario de la petrolera mexicana ha sido se\u00f1alado por tres exdirectivos de la constructora brasile\u00f1a Odebrecht de haber recibido 10 millones de d\u00f3lares en sobornos a cambio de contratos entre 2012 y 2016. Parte de la mordida, unos 4.1 millones de d\u00f3lares, se habr\u00edan depositado cuando Lozoya fung\u00eda como jefe de asuntos internacionales de la campa\u00f1a presidencial de Enrique Pe\u00f1a Nieto, que lleg\u00f3 al poder el 1 de diciembre de 2012. Nieto asegur\u00f3 al diario mexicano que Lozoya\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2017\/10\/18\/mexico\/1508338178_095010.html\">lo presion\u00f3 para declararlo inocente<\/a>\u00a0y le exigi\u00f3 una disculpa p\u00fablica.<\/p>\n<p style=\"color: #444444\">El papel de Odebrecht en la pol\u00edtica mexicana es uno de los misterios de la actual campa\u00f1a presidencial. M\u00e9xico y Venezuela son dos pa\u00edses donde el papel de la constructora brasile\u00f1a no ha sido investigado a fondo por las autoridades locales en un esc\u00e1ndalo de corrupci\u00f3n que ha salpicado a buena parte de Am\u00e9rica Latina. La Fepade abri\u00f3 una investigaci\u00f3n en agosto de 2017, despu\u00e9s de las deposiciones juradas de los exdirectivos brasile\u00f1os. Las pesquisas no avanzaron lo suficiente. Dos meses despu\u00e9s, el fiscal electoral fue despedido por haber transgredido con su entrevista con la prensa el c\u00f3digo de funcionarios de la Procuradur\u00eda General de la Rep\u00fablica (PGR, Fiscal\u00eda). El Gobierno mexicano se ha limitado a\u00a0<a style=\"font-style: inherit;color: #016ca2\" href=\"https:\/\/elpais.com\/internacional\/2018\/04\/19\/mexico\/1524150473_535247.html\">sancionar e inhabilitar<\/a>\u00a0a Odebrecht en el pa\u00eds.<\/p>\n<p style=\"color: #444444\">Recientemente, en una charla con\u00a0<em>The Wall Street Journal<\/em>, Nieto afirm\u00f3 que el Gobierno mexicano ha intentado comprar su silencio a trav\u00e9s de un hombre cercano al hoy exsecretario (ministro) de Gobernaci\u00f3n, Miguel \u00c1ngel Osorio Chong. El exfiscal tambi\u00e9n asegur\u00f3 al diario estadounidense que \u00e9l y su exesposa han recibido mensajes amedrentadores y amenazas de muerte.<\/p>\n<p style=\"color: #444444\">L\u00f3pez Obrador consider\u00f3 este martes que Nieto ha sido v\u00edctima de una \u201cinjusticia\u201d al haber sido despedido del Gobierno. El candidato presidencial tambi\u00e9n quiso desactivar el morbo que despierta que se sume a su campa\u00f1a uno de los exfuncionarios que m\u00e1s informaci\u00f3n tiene sobre el caso Odebrecht y la actual Administraci\u00f3n. \u201cYo no soy verdugo, yo no quiero venganza, yo quiero justicia\u201d, afirm\u00f3 el candidato presidencial que, poco a poco, revela sus ases bajo la manga rumbo a los comicios de julio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago Nieto, que investigaba los supuestos sobornos de Odebrecht a la campa\u00f1a del PRI en 2012, reaparece en un mitin de Morena<\/p>\n","protected":false},"author":5842,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-477580","post","type-post","status-publish","format-standard","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/5842"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=477580"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477580\/revisions"}],"predecessor-version":[{"id":477582,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/477580\/revisions\/477582"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=477580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=477580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=477580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}