{"id":478,"date":"2011-05-28T11:53:38","date_gmt":"2011-05-28T15:53:38","guid":{"rendered":"http:\/\/retrolab.ca\/elpopular\/?p=478"},"modified":"2011-05-28T11:53:38","modified_gmt":"2011-05-28T15:53:38","slug":"por-que-algunos-casos-migratorios-tardan-o-se-complican-mucho-mas-que-otros","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2011\/05\/28\/por-que-algunos-casos-migratorios-tardan-o-se-complican-mucho-mas-que-otros\/","title":{"rendered":"\u00bfPor qu\u00e9 algunos casos migratorios tardan o se complican mucho m\u00e1s que otros?"},"content":{"rendered":"<p><!-- \t\t@page { margin: 2cm } \t\tP { margin-bottom: 0.21cm } -->En mi trabajo como asesora en temas migratorios he observado que en muchas oportunidades algunos de los clientes que est\u00e1n haciendo tr\u00e1mites de inmigraci\u00f3n culpan a su abogado o a su consultor de inmigraci\u00f3n por las tardanzas en los tr\u00e1mites. Tambi\u00e9n la costumbre es de culpar al consultor o al abogado de supuestamente no haber enviado alguna documentaci\u00f3n, o de que se haya perdido en su oficina, cuando lo que realmente ha sucedido es que estos documentos se han extraviado en las oficinas del Departamento de Inmigraci\u00f3n.<\/p>\n<p>Todo esto sucede porque aparentemente es muy dif\u00edcil para las personas pensar que el Departamento de Inmigraci\u00f3n de Canad\u00e1 puede cometer errores, cuando a trav\u00e9s de los a\u00f1os hemos visto much\u00edsimos errores cometidos por los consulados y por las distintas oficinas de Inmigraci\u00f3n, algo que por suerte no sucede muy frecuentemente aunque obviamente s\u00ed ocurren.<\/p>\n<p>Tengo en mente un caso en particular, en el cual una solicitud de patrocinio tard\u00f3 m\u00e1s de nueve a\u00f1os y donde el cliente tuvo que hacer los tr\u00e1mite (ex\u00e1menes m\u00e9dicos y chequeos policiales) siete veces porque el consulado no lograba armonizar o coordinar estos dos requisitos: cuando el cliente presentaba uno de los requisitos se venc\u00eda el otro, y as\u00ed en consecuencia se convirti\u00f3 en un c\u00edrculo vicioso que tard\u00f3 nueve a\u00f1os para ser corregido, algo que sucedi\u00f3 hasta que se hizo una carta diciendo que se parara ya con ese juego. Esta fue  es una comedia de errores en la que no se resolvi\u00f3 el problema sino hasta que se logr\u00f3 hacer que coincidieran los tr\u00e1mites.<\/p>\n<p>En la misma l\u00f3gica, esta semana en el peri\u00f3dico Toronto Star apareci\u00f3 un art\u00edculo en relaci\u00f3n a una pareja, un ciudadano canadiense que est\u00e1 patrocinando a su esposa a trav\u00e9s del consulado canadiense en Ghana, y es una de las pocas veces que yo veo que el Departamento de Inmigraci\u00f3n se molesta en pedir disculpa al solicitante por errores cometidos en el expediente.<\/p>\n<p>Hay que tener en mente que cuando se  hace un tr\u00e1mite de matrimonio supuestamente se le tiene que dar prioridad de procesamiento, y a menos que haya una deportaci\u00f3n previa o problemas m\u00e9dicos serios, o problemas criminales, el tr\u00e1mite no deber\u00eda durar m\u00e1s de seis u ocho meses.<\/p>\n<p>En este caso el tr\u00e1mite les ha durado dos a\u00f1os, y es un caso genuino sin complicaciones y que por lo tanto la solicitante ya deber\u00eda tener la residencia, pero el Departamento de Inmigraci\u00f3n cometi\u00f3 error tras error: la mujer ha tenido que hacer los ex\u00e1menes m\u00e9dicos en dos ocasiones, e incluso en una tercera ocasi\u00f3n le dijeron que la carta se le hab\u00eda enviado por error y que por favor no fuera a hacerse una vez m\u00e1s las pruebas. Despu\u00e9s, le lleg\u00f3 una carta dici\u00e9ndole que ten\u00eda que llegar a la oficina consular en Ghana para que se le entregara su residencia permanente y su visa para venir a Canad\u00e1, y la solicitante viaj\u00f3 desde su pueblo a la ciudad en un viaje de 6 horas para ir a recoger su residencia permanente s\u00f3lo para encontrase con que era un error, que esa carta no le tendr\u00eda que haber sido enviada porque su visa aun no estaba lista.<\/p>\n<p>Por suerte parece que ahora todo se ha encaminado bien y que en las oficinas consulares van a apresurarse para procesar su caso y para que pueda finalmente venir a reunirse con su esposo aqu\u00ed en Canad\u00e1<\/p>\n<p>Ya que estas cosas suceden, es importante saber que en situaciones como estas donde los casos se est\u00e1n tardando m\u00e1s tiempo del que est\u00e1 establecido, lo primero que se tiene que hacer en es enviar una carta pidiendo informaci\u00f3n al consulado o la oficina de inmigraci\u00f3n que est\u00e1 tratando el caso. Si no se tiene respuesta en un periodo razonable, que podr\u00eda ser unas dos semanas, se puede escribir nuevamente pero esta vez al Program Manager, que es el gerente de la oficina, explicando lo que est\u00e1 sucediendo y dando una cronolog\u00eda de los eventos, diciendo que ya se ha tratado de contactar con el oficial y que por favor conteste la persona encargada de la oficina.<\/p>\n<p>Si esto no da resultado, porque en algunas de las oficinas o consulados lamentablemente tambi\u00e9n el Program Manager no se molesta en contestar, el siguiente recurso es la oficina regional del Departamento de inmigraci\u00f3n donde est\u00e1 ubicada cada una de esas oficinas, la cual tiene la responsabilidad de supervisar o controlar las distintas oficinas y consulado. Entonces, en esos casos donde no se logra una respuesta del Program Manager, se debe escribir a esta oficina regional del lugar donde se est\u00e1 procesando el caso, y con seguridad se va a poder solucionar el problema.<\/p>\n<p>Pero si esto tambi\u00e9n falla, la \u00fanica alternativa que queda es ir a la Corte Federal explicando la situaci\u00f3n en orden cronol\u00f3gico, demostrando que hay un atraso que no tiene explicaci\u00f3n, y si la Corte est\u00e1 de acuerdo en que el tr\u00e1mite est\u00e1 tomando mucho m\u00e1s tiempo del que deber\u00eda estar tomando y que hay una ruptura del procedimiento justo, entonces la Corte puede dar una orden que se llama un &#8220;Mandamus&#8221;, que es b\u00e1sicamente una orden dici\u00e9ndole a la oficina que tiene que actuar de inmediato. No le va a decir exactamente qu\u00e9 es lo que tiene que hacer, pero s\u00ed le va a decir que tiene que llegar a una decisi\u00f3n final con el caso.<\/p>\n<p>Obviamente esta es una situaci\u00f3n es un poco costosa porque definitivamente se tiene que contratar los servicios de un abogado que deber\u00e1 hacer todos los procesamientos ante la Corte Federal, pero esa es la manera de solucionar el problema.<\/p>\n<p>Explicado todo lo anterior, es importante tener en cuenta que antes de acusar a la persona que lo est\u00e1 representando en un proceso migratorio, en realidad se tiene que hacer una evaluaci\u00f3n a fondo sobre qu\u00e9 es lo que est\u00e1 sucediendo con el caso, as\u00ed como tambi\u00e9n se debe entender de qu\u00e9 dependiendo de en qu\u00e9 oficina es que est\u00e1 el caso, as\u00ed ser\u00e1 la celeridad del procesamiento de dicho caso, dado que hay oficinas s\u00faper eficientes y hay otras que lamentablemente son bastante problem\u00e1ticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En mi trabajo como asesora en temas migratorios he observado que en muchas oportunidades algunos de los clientes que est\u00e1n haciendo tr\u00e1mites de inmigraci\u00f3n culpan&hellip;<\/p>\n","protected":false},"author":1,"featured_media":881,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,290],"tags":[],"class_list":["post-478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmigracion","category-inmigrando-a-canada"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=478"}],"version-history":[{"count":0,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/478\/revisions"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}