{"id":497690,"date":"2021-05-12T12:44:32","date_gmt":"2021-05-12T16:44:32","guid":{"rendered":"https:\/\/diarioelpopular.com\/?p=497690"},"modified":"2021-05-12T12:44:32","modified_gmt":"2021-05-12T16:44:32","slug":"eeuu-pone-la-lupa-en-mexico","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2021\/05\/12\/eeuu-pone-la-lupa-en-mexico\/","title":{"rendered":"EEUU pone la lupa en M\u00e9xico"},"content":{"rendered":"<h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-custom-full-size wp-image-497691\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/05\/cdde05177b6d801cd96644a737edbe1f-636x424.jpg\" alt=\"\" width=\"636\" height=\"424\" srcset=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/05\/cdde05177b6d801cd96644a737edbe1f-636x424.jpg 636w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/05\/cdde05177b6d801cd96644a737edbe1f-300x200.jpg 300w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/05\/cdde05177b6d801cd96644a737edbe1f-768x512.jpg 768w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/05\/cdde05177b6d801cd96644a737edbe1f-110x73.jpg 110w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/05\/cdde05177b6d801cd96644a737edbe1f.jpg 827w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/h4>\n<p><em>Construcci\u00f3n en M\u00e9xico con una t\u00e9cnica de &#8220;super adobe&#8221; (foto: EPA)<\/em><\/p>\n<h4><em><strong>Presiona por violaciones al Acuerdo de Libre Comercio<\/strong><\/em><\/h4>\n<p><em><strong>CIUDAD DE MEXICO, 12 MAY &#8211;<\/strong><\/em> El gobierno de Estados Unidos mantiene bajo la lupa a M\u00e9xico y amenaza con imponer sanciones por violar el Trabado de Libre Comercio que ambos pa\u00edses suscribieron junto con Canad\u00e1 (T-MEC), vigente desde 1994 y renovado en 2020. Adicionalmente la central obrera m\u00e1s grande de Estados Unidos, la AFL-CIO anunci\u00f3 haber solicitado al gobierno de su pa\u00eds presentar la primera denuncia laboral contra M\u00e9xico amparada en el T-MEC, por abusos laborales relacionados con la afiliaci\u00f3n sindical. Los trabajadores de la planta fabricante de componentes para autom\u00f3viles Tridonex, ubicada en Matamoros, frontera con Texas, no se les permite desvincularse del gremio al que pertenecen, la Confederaci\u00f3n de Trabajadores de M\u00e9xico (CTM), para hacerlo en forma independiente. La representante de los operarios, Susana Prieto, denunci\u00f3 que unas 600 personas fueron despedidas el a\u00f1o pasado como represalia por su intenci\u00f3n de cambiar de sindicato luego que la firma cambi\u00f3 su sede de Filadelfia al estado norte\u00f1o de Tamaulipas. La reciente revisi\u00f3n del T-MEC, impulsada por el expresidente Donald Trump, incluy\u00f3 un &#8220;Mecanismo Laboral de Respuesta R\u00e1pida&#8221; por el que empresas de ambos pa\u00edses pueden enfrentar aranceles y otras sanciones si incumplen su obligaci\u00f3n de garantizar derechos de los empleados como la libertad de asociaci\u00f3n. Oscar de la Vega, abogado laboral de la firma D&amp;M, pronostic\u00f3 que por &#8220;la presi\u00f3n y monitoreo del gobierno de Estados Unidos&#8221; y bajo los nuevos t\u00e9rminos del acuerdo M\u00e9xico enfrentar\u00e1 &#8220;conflictos laborales como nunca antes&#8221;. &#8220;Es parte de los reacomodos y muchos sindicatos desaparecer\u00e1n porque no han entendido la nueva din\u00e1mica&#8221;, se\u00f1al\u00f3. Los sindicatos estadounidenses han hecho saber que est\u00e1n interesados en influir para mejorar las condiciones laborales en M\u00e9xico y evitar una competencia desleal, como requisito para mantener el libre comercio bilateral. Katherine Chi Tai, la nueva representante Comercial de Estados Unidos, se\u00f1al\u00f3 el 28 de abril pasado, ante un comit\u00e9 de la C\u00e1mara de Representantes, que existen serias &#8220;preocupaciones sobre c\u00f3mo M\u00e9xico est\u00e1 manejando sus obligaciones dentro del T-MEC&#8221; y que se las ha comunicado ya a la ministra de Econom\u00eda de este pa\u00eds Tatiana Clouthier. La funcionaria dio a conocer que &#8220;no tiene miedo de usar las herramientas de aplicaci\u00f3n de las reglas&#8221; provistas en el T-MEC, lo que &#8220;puede llevarnos a un escenario de cooperaci\u00f3n, enfrentamiento o una combinaci\u00f3n de ambas&#8221;. D\u00edas atr\u00e1s, el American Petroleum Institute (API) envi\u00f3 una carta al secretario de Estado, las secretarias de Comercio y Energ\u00eda y a la representante Comercial del gobierno de Biden, para protestar por &#8220;la discriminaci\u00f3n a las empresas de su pa\u00eds en el mercado energ\u00e9tico mexicano&#8221; en el marco del nuevo T-MEC. El API es un organismo muy influyente que nuclea a empresarios de Estados Unidos, el cual argumenta que las nuevas leyes de la industria el\u00e9ctrica y de hidrocarburos de M\u00e9xico modificaron las reglas para beneficiar a las empresas del Estado, Pemex y la Comisi\u00f3n Federal de Electricidad (CFE) y perjudicar a sus miembros. Esto ha afectado a empresas privadas con cuantiosas inversiones en M\u00e9xico, lo que ha destruido su &#8220;valor econ\u00f3mico&#8221;, violando diversas disposiciones del T-MEC. &#8220;Desgraciadamente, las cosas no se ven bien. Resultan muy preocupantes&#8221; estas noticias, se\u00f1al\u00f3 el analista Leo Zuckermann, quien dijo que &#8220;En este momento, el crecimiento econ\u00f3mico de M\u00e9xico depende de manera cr\u00edtica de su relaci\u00f3n comercial con Estados Unidos&#8221;. &#8220;Las exportaciones a ese pa\u00eds son pr\u00e1cticamente el \u00fanico motor que tiene prendido la econom\u00eda mexicana. Por eso, hoy m\u00e1s que nunca, tenemos que cuidar de esta tabla de salvaci\u00f3n&#8221;, advirti\u00f3. &#8220;Es urgente que el gobierno de Estados Unidos trabaje diplom\u00e1ticamente con el de M\u00e9xico para solucionar este problema&#8221;, indic\u00f3 el experto, quien expuso que &#8220;lo \u00fanico que le falta&#8221; a este pa\u00eds es &#8220;enfrentarse con Sans\u00f3n a las patadas&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construcci\u00f3n en M\u00e9xico con una t\u00e9cnica de &#8220;super adobe&#8221; (foto: EPA) Presiona por violaciones al Acuerdo de Libre Comercio CIUDAD DE MEXICO, 12 MAY &#8211;&hellip;<\/p>\n","protected":false},"author":99,"featured_media":497691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11354],"tags":[],"class_list":["post-497690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sucesos"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/497690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=497690"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/497690\/revisions"}],"predecessor-version":[{"id":497692,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/497690\/revisions\/497692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media\/497691"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=497690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=497690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=497690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}