{"id":498036,"date":"2021-06-01T09:50:26","date_gmt":"2021-06-01T13:50:26","guid":{"rendered":"https:\/\/diarioelpopular.com\/?p=498036"},"modified":"2021-06-01T09:50:26","modified_gmt":"2021-06-01T13:50:26","slug":"ontario-se-acerca-un-paso-mas-al-plan-de-reapertura-este-martes-2-de-junio","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2021\/06\/01\/ontario-se-acerca-un-paso-mas-al-plan-de-reapertura-este-martes-2-de-junio\/","title":{"rendered":"Ontario se acerca un paso m\u00e1s al plan de reapertura este martes 2 de junio"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-custom-full-size wp-image-498038\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1-636x438.jpg\" alt=\"\" width=\"636\" height=\"438\" srcset=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1-636x438.jpg 636w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1-300x207.jpg 300w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1-768x529.jpg 768w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1-80x55.jpg 80w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1-106x73.jpg 106w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/06\/SXTPH3PT3RMNVA3FGDZELUAADY-1.jpg 945w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/h4>\n<h4><em><strong>&#8211; Casi dos meses despu\u00e9s de que el gobierno de Ontario promulg\u00f3 una orden de quedarse en casa en toda la provincia en respuesta a la tercera ola de COVID-19, se prev\u00e9 que se rescinda el 2 de junio, ya que los indicadores de atenci\u00f3n m\u00e9dica contin\u00faan mostrando mejoras.<\/strong><\/em><\/h4>\n<p><em><strong>TORONTO.-<\/strong> <\/em>Sin embargo, a pesar de la finalizaci\u00f3n de la orden, el llamado freno de emergencia (similar a las restricciones de bloqueo gris bajo el antiguo marco de respuesta COVID-19 codificado por colores de Ontario) impuesto en una variedad de sectores, incluidas las empresas, permanecer\u00e1 en su lugar hasta el La provincia pasa a la primera fase del plan de reapertura, que est\u00e1 en camino de suceder a mediados de junio.<\/p>\n<p>Fue el 8 de abril cuando se impuso otra orden de quedarse en casa y una declaraci\u00f3n de emergencia en toda la provincia. En ese momento, los funcionarios dijeron que las \u00f3rdenes eran necesarias para combatir el aumento de los casos de COVID-19 y frenar la mayor propagaci\u00f3n de variantes de casos preocupantes, as\u00ed como la capacidad de la unidad de cuidados intensivos limitada.<\/p>\n<p>Las principales razones para salir de casa incluyen ir de compras a la farmacia o al supermercado, asistir a citas o servicios de atenci\u00f3n m\u00e9dica (incluidas las vacunas COVID-19), hacer ejercicio al aire libre, pasear mascotas, ir a trabajar si no se puede hacer un trabajo. de forma remota, o asistiendo a la guarder\u00eda o la escuela.<\/p>\n<p>Tambi\u00e9n como parte de los pedidos, el gobierno se movi\u00f3 para limitar la mayor\u00eda de los negocios minoristas no esenciales a la recolecci\u00f3n en la acera \u00fanicamente. Las tiendas grandes se limitaron a vender art\u00edculos esenciales solo para las personas que compran en persona y se impusieron l\u00edmites de capacidad.<\/p>\n<p>M\u00e1s de una semana despu\u00e9s, los funcionarios revelaron medidas adicionales, incluido el aumento de los poderes de la polic\u00eda (que se retiraron parcialmente despu\u00e9s de la protesta p\u00fablica), los puestos de control fronterizos provinciales y las restricciones para las reuniones al aire libre.<\/p>\n<p>A medida que los casos de COVID-19 y las hospitalizaciones comenzaron a disminuir en mayo, muchos expertos en salud y otras partes interesadas pidieron al gobierno que alivie las restricciones que rigen los servicios al aire libre. El 22 de mayo reabrieron campos de golf, canchas de tenis y otras instalaciones.<\/p>\n<p>A mediados de mayo, el gobierno de Ontario revel\u00f3 su plan de reapertura en tres fases para toda la provincia.<\/p>\n<p>La fase uno (principalmente permitir la venta minorista y reabrir m\u00e1s entornos al aire libre con restricciones) comenzar\u00e1 tan pronto como el 60 por ciento de todos los residentes elegibles de Ontario hayan recibido la primera de las dos dosis de la vacuna COVID-19.<\/p>\n<p>Al 31 de mayo, la ministra de Salud, Christine Elliott, dijo que alrededor del 67 por ciento de los residentes de Ontario hab\u00edan recibido su primera dosis. Sin embargo, dijo que las hospitalizaciones, la cantidad de personas en las UCI y la capacidad de salud p\u00fablica se tendr\u00e1n en cuenta en el proceso de toma de decisiones a finales de junio.<\/p>\n<p>&#8220;Hay una variedad de factores que deben tenerse en cuenta, pero ciertamente estamos viendo el 14 de junio como la fecha en la que podemos pasar a la etapa uno&#8221;, dijo Elliott a los periodistas el 31 de mayo, reiterando un plazo previamente emitido.<\/p>\n<p>Deber\u00e1 pasar un m\u00ednimo de tres semanas y el 70 por ciento de todos los residentes de Ontario elegibles deber\u00e1n recibir su primera dosis de vacuna COVID-19 y el 20 por ciento de los residentes deber\u00e1n recibir las dos dosis requeridas antes de pasar a la fase dos (reapertura m\u00e1s entornos interiores en una base m\u00e1s peque\u00f1a y ampliando los entornos exteriores).<\/p>\n<p>Despu\u00e9s de otro per\u00edodo m\u00ednimo de tres semanas, junto con hasta el 80 por ciento de los residentes recibiendo su primera dosis de vacuna y el 25 por ciento recibiendo su segunda dosis, se permitir\u00e1 que se vuelvan a abrir m\u00e1s actividades en el interior en la fase tres donde las m\u00e1scaras no siempre se pueden abrir. gastado.<\/p>\n<p>Al final de cada fase, se revisar\u00e1n los indicadores del sistema de salud antes de pasar al siguiente paso. Los funcionarios no han indicado p\u00fablicamente qu\u00e9 suceder\u00e1 si hay un aumento en los casos, hospitalizaciones y \/ o muertes, pero todos han alentado a todos los elegibles para recibir una vacuna a hacerlo.<\/p>\n<p><em><strong>El pedido para quedarse en casa vence este 2 de junio, entonces, \u00bfqu\u00e9 sigue?<\/strong><\/em><\/p>\n<p>A corto plazo, no cambiar\u00e1 mucho hasta que entre en vigencia la primera fase del plan provincial de reapertura. Los negocios, servicios y otras instalaciones de Ontario actualmente cerradas continuar\u00e1n cerradas hasta ese momento.<\/p>\n<p>Sin embargo, las \u00f3rdenes que imponen controles en las fronteras de Quebec y Manitoba, ciertos poderes de ejecuci\u00f3n y otras medidas permanecer\u00e1n vigentes hasta el 16 de junio.<\/p>\n<p>Un portavoz de la procuradora general de Ontario, Sylvia Jones, agreg\u00f3 que algunas o todas esas regulaciones podr\u00edan &#8220;extenderse en incrementos de 14 d\u00edas&#8221;.<\/p>\n<p>El Dr. David Williams, director m\u00e9dico de salud de Ontario, alent\u00f3 a las personas a seguir siguiendo las medidas de salud p\u00fablica.<\/p>\n<p>&#8220;Limitarse a los hogares, quedarse en casa cuando puede &#8230; usar m\u00e1scaras y distanciarse cuando est\u00e1 en entornos congregados&#8221;, dijo, y se\u00f1al\u00f3 que pronto se anunciar\u00e1 informaci\u00f3n adicional sobre la reapertura.<\/p>\n<p>\u201cMant\u00e9n la tarea. Nuestros n\u00fameros est\u00e1n bajando realmente bien a medida que las personas reciben su vacuna (primera y segunda dosis) y permiten que el sistema inmunol\u00f3gico se recupere en esas tres semanas despu\u00e9s de su dosis, pero a\u00fan debe usar las medidas de protecci\u00f3n en este momento. &#8221;<\/p>\n<p>Mientras tanto, en lo que respecta a las escuelas en Ontario, el primer ministro Doug Ford continu\u00f3 reflexionando sobre si las instalaciones se abrir\u00e1n para el aprendizaje en clase durante las \u00faltimas semanas del a\u00f1o acad\u00e9mico. Dijo el lunes que llegar\u00eda un anuncio &#8220;en el pr\u00f3ximo d\u00eda o dos&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &#8211; Casi dos meses despu\u00e9s de que el gobierno de Ontario promulg\u00f3 una orden de quedarse en casa en toda la provincia en respuesta&hellip;<\/p>\n","protected":false},"author":99,"featured_media":498038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-498036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=498036"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498036\/revisions"}],"predecessor-version":[{"id":498039,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498036\/revisions\/498039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media\/498038"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=498036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=498036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=498036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}