{"id":498557,"date":"2021-07-04T14:44:03","date_gmt":"2021-07-04T18:44:03","guid":{"rendered":"https:\/\/diarioelpopular.com\/?p=498557"},"modified":"2021-07-04T14:44:03","modified_gmt":"2021-07-04T18:44:03","slug":"al-oeste-de-canada-se-desatan-mas-de-170-incendios","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2021\/07\/04\/al-oeste-de-canada-se-desatan-mas-de-170-incendios\/","title":{"rendered":"Al oeste de Canad\u00e1, se desatan m\u00e1s de 170 incendios"},"content":{"rendered":"<h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-custom-full-size wp-image-498558\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/incencidos-636x358.jpg\" alt=\"\" width=\"636\" height=\"358\" srcset=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/incencidos-636x358.jpg 636w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/incencidos-300x169.jpg 300w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/incencidos-130x73.jpg 130w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/incencidos.jpg 700w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/h4>\n<p><em>La sequ\u00eda, el calor y los rayos han causado grandes fuegos en ambos pa\u00edses. Foto: AP<\/em><\/p>\n<h4><em><strong>La sequ\u00eda, el calor y los rayos han causado grandes fuegos en ambos pa\u00edses<\/strong><\/em><\/h4>\n<p><em><strong>VANCOUVER.-<\/strong><\/em> Las fuerzas armadas de Canad\u00e1 est\u00e1n en estado de alerta para ayudar a evacuar ciudades y combatir a m\u00e1s de 170 incendios potenciados por una asfixiante ola de calor y sequ\u00eda en el oeste del pa\u00eds.<\/p>\n<p>Al menos 177 incendios estaban activos en la provincia occidental de Columbia Brit\u00e1nica, de los cuales 76 se produjeron en los \u00faltimos dos d\u00edas, dijeron las autoridades. La mayor\u00eda fueron causados por rayos.<\/p>\n<p><em>&#8220;Ayer vimos 12 mil rayos aproximadamente&#8221;<\/em>, dijo Cliff Chapman, director de operaciones del servicio de incendios de Columbia Brit\u00e1nica.<\/p>\n<p>Aunque el fen\u00f3meno de la &#8220;c\u00fapula de calor&#8221; que atrapa el aire caliente en la regi\u00f3n es se\u00f1alado como responsable de las condiciones sofocantes en el oeste de Estados Unidos y Canad\u00e1, expertos afirman que el cambio clim\u00e1tico est\u00e1 haciendo que los r\u00e9cord de temperatura se rompan con m\u00e1s frecuencia.<\/p>\n<p>En Estados Unidos, cientos de bomberos procuraban contener tres incendios forestales en el norte del estado de California, donde la sequ\u00eda favoreci\u00f3 la expansi\u00f3n del fuego por miles de hect\u00e1reas, hasta inmediaciones de un popular lago que se preparaba para recibir a vastos contingentes de turistas el fin de semana festivo del 4 de julio.<\/p>\n<p>Las autoridades extendieron \u00f3rdenes de evacuaci\u00f3n a lo largo de tramos del lago Shasta, un punto de acceso para acampar y navegar a unos 160 kil\u00f3metros al sur de la frontera del estado de Oreg\u00f3n, debido a que las altas temperaturas y los fuertes vientos estimulan las llamas en una etapa relativamente temprana de la temporada de incendios de la regi\u00f3n.<\/p>\n<p>Alrededor de 40 viviendas fueron destruidas, entre ellas al menos media docena de casas cerca de la ciudad de Lakehead.<\/p>\n<p><em>&#8220;Todo est\u00e1 muy seco. Hemos tenido muy poca lluvia, los niveles de nuestros lagos son muy bajos en este momento del a\u00f1o&#8221;<\/em>, declar\u00f3 Cecil Hengst, de 63 a\u00f1os, propietario del campamento Lakehead.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sequ\u00eda, el calor y los rayos han causado grandes fuegos en ambos pa\u00edses. Foto: AP La sequ\u00eda, el calor y los rayos han causado&hellip;<\/p>\n","protected":false},"author":99,"featured_media":498558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-498557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=498557"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498557\/revisions"}],"predecessor-version":[{"id":498559,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498557\/revisions\/498559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media\/498558"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=498557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=498557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=498557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}