{"id":498580,"date":"2021-07-07T12:07:29","date_gmt":"2021-07-07T16:07:29","guid":{"rendered":"https:\/\/diarioelpopular.com\/?p=498580"},"modified":"2021-07-07T12:07:29","modified_gmt":"2021-07-07T16:07:29","slug":"las-restricciones-se-relajan-en-los-hogares-de-cuidado-a-largo-plazo-de-ontario","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2021\/07\/07\/las-restricciones-se-relajan-en-los-hogares-de-cuidado-a-largo-plazo-de-ontario\/","title":{"rendered":"Las restricciones se relajan en los hogares de cuidado a largo plazo de Ontario"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-custom-full-size wp-image-498581\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-07-at-12.06.37-PM-636x345.png\" alt=\"\" width=\"636\" height=\"345\" srcset=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-07-at-12.06.37-PM-636x345.png 636w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-07-at-12.06.37-PM-300x163.png 300w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-07-at-12.06.37-PM-768x416.png 768w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-07-at-12.06.37-PM-135x73.png 135w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2021\/07\/Screen-Shot-2021-07-07-at-12.06.37-PM.png 1009w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/p>\n<h4>\u00a0&#8211;\u00a0<em><strong>Los residentes de cuidados a largo plazo en Ontario ahora pueden tener visitas al aire libre con hasta 10 personas a la vez.<\/strong><\/em><\/h4>\n<h4><em><strong>&#8211; Ontario reporta 194 nuevos casos de COVID-19, cero muertes por primera vez desde el a\u00f1o pasado<\/strong><\/em><\/h4>\n<p><em><strong>TORONTO &#8211;<\/strong><\/em> La provincia anunci\u00f3 que tambi\u00e9n pueden reunirse en interiores con hasta dos cuidadores esenciales y dos visitantes generales.<\/p>\n<p>Los cambios, parte del paso del gobierno provincial al Paso 2 de su plan de reapertura, entraron en vigencia el mi\u00e9rcoles a medida que los casos de COVID-19 contin\u00faan disminuyendo.<\/p>\n<p>Las nuevas reglas tambi\u00e9n permiten que los servicios de cuidado personal se reanuden para los residentes de cuidados a largo plazo.<\/p>\n<p>Adem\u00e1s, ya no existe un l\u00edmite en el n\u00famero de personas que pueden ser consideradas &#8220;cuidadores esenciales&#8221; por los residentes de cuidados a largo plazo o sus sustitutos en la toma de decisiones.<\/p>\n<p>En la etapa 3 del plan de reapertura de Ontario, que entrar\u00e1 en vigor en dos semanas, se reanudar\u00e1n las excursiones y actividades fuera del lugar, como cantar y bailar.<\/p>\n<p>&nbsp;<\/p>\n<h4><em><strong>Ontario reporta 194 nuevos casos de COVID-19, cero muertes por primera vez desde el a\u00f1o pasado<\/strong><\/em><\/h4>\n<p>Actualizado mi\u00e9rcoles 7 de julio de 2021 11:55 a.m.<\/p>\n<p>Ontario report\u00f3 194 nuevos casos de COVID-19 este mi\u00e9rcoles, ya que la provincia tampoco report\u00f3 nuevas muertes por primera vez desde 2020. El total de casos provinciales ahora es de 546,411.<\/p>\n<p>El n\u00famero de muertos en la provincia se mantuvo en 9.224. La \u00faltima vez que la provincia report\u00f3 cero muertes fue el 14 de octubre.<\/p>\n<p>Seg\u00fan el informe, se registraron 42 casos en Waterloo, 35 en Toronto, 26 en la regi\u00f3n de Peel, 16 en Hamilton y 11 en Gray Bruce.<\/p>\n<p>Todas las dem\u00e1s unidades de salud p\u00fablica locales notificaron menos de 10 casos nuevos en el informe provincial.<\/p>\n<p>A partir de las 5 p.m. el martes, se administraron m\u00e1s de 16,1 millones de dosis totales de vacuna COVID-19. Eso marc\u00f3 un aumento de 204,594 vacunas (18,588 para una primera inyecci\u00f3n y 186,006 para una segunda inyecci\u00f3n) en el \u00faltimo d\u00eda.<\/p>\n<p>Hay m\u00e1s de 6 millones de personas completamente inmunizadas con dos dosis, lo que representa el 49,3% de la poblaci\u00f3n adulta (18+). La cobertura de la primera dosis para adultos es del 78,6%.<\/p>\n<p>Mientras tanto, se inform\u00f3 que 535,346 residentes de Ontario se hab\u00edan recuperado del COVID-19, que es aproximadamente el 98 por ciento de los casos conocidos. Los casos resueltos aumentaron en 236 con respecto al d\u00eda anterior.<\/p>\n<p>Hubo m\u00e1s casos resueltos que casos nuevos el mi\u00e9rcoles.<\/p>\n<p>Los casos activos en Ontario ahora ascienden a 1.841, por debajo del d\u00eda anterior cuando estaba en 1.883, y est\u00e1 por debajo del 30 de junio cuando estaba en 2.257. En el pico de la oleada de coronavirus de la segunda ola en enero, los casos activos llegaron a poco m\u00e1s de 30.000. En la tercera ola de abril, los casos activos superaron los 43.000.<\/p>\n<p>El promedio de siete d\u00edas ahora ha llegado a 216, que es superior al de ayer en 215, y est\u00e1 por debajo de la semana pasada en 268. Hace un mes, el promedio de siete d\u00edas era de alrededor de 700.<\/p>\n<p>El gobierno dijo que se procesaron 26.976 pruebas en las \u00faltimas 24 horas. Actualmente hay una acumulaci\u00f3n de 12,072 pruebas en espera de resultados. Se han realizado un total de 16.093.172 pruebas desde el inicio de la pandemia.<\/p>\n<p>La positividad est del mi\u00e9rcoles lleg\u00f3 al 0,9 por ciento, que era la misma que la del d\u00eda anterior. La semana pasada, la positividad de la prueba fue del 1 por ciento.<\/p>\n<p>Ontario inform\u00f3 que 201 personas est\u00e1n hospitalizadas con COVID-19 (una reducci\u00f3n respecto al d\u00eda anterior) con 220 pacientes en unidades de cuidados intensivos (una reducci\u00f3n de seis) y 155 pacientes en UCI con ventilador (una reducci\u00f3n de seis). Las hospitalizaciones han ido disminuyendo desde el pico de la tercera ola en abril.<\/p>\n<p><em><strong>Variantes preocupantes en Ontario<\/strong><\/em><\/p>\n<p>Los funcionarios han enumerado datos desglosados \u200b\u200bpara los nuevos COV (variantes de inter\u00e9s) detectados hasta ahora en la provincia que consisten en el B.1.1.7 (ahora denominado por la OMS como \u201cAlfa\u201d y se detect\u00f3 por primera vez en el Reino Unido), B. 1.351 (ahora nombrado por la OMS como &#8220;Beta&#8221; y se detect\u00f3 por primera vez en Sud\u00e1frica), P.1 (ahora nombrado por la OMS como &#8220;Gamma&#8221; y se detect\u00f3 por primera vez en Brasil) y B.1.617.2 (ahora nombrado por la OMS como &#8220;Delta&#8221; y se detect\u00f3 por primera vez en la India).<\/p>\n<p>&#8220;Alfa&#8221; el VOC B.1.1.7: 144,338 casos variantes, lo que representa un aumento de 349 desde el d\u00eda anterior,<\/p>\n<p>\u201cBeta\u201d el VOC B.1.351: 1.420 cajas variantes, lo que representa un aumento de cinco desde el d\u00eda anterior.<\/p>\n<p>\u201cGamma\u201d el P.1 VOC: 4.650 casos variantes, que ha aumentado en 18 desde el d\u00eda anterior.<\/p>\n<p>\u201cDelta\u201d B.1.617.2 VOC: 2.222 casos variantes, 173 m\u00e1s que el d\u00eda anterior.<\/p>\n<p><em><strong>Casos, muertes y brotes en hogares de cuidados a largo plazo de Ontario<\/strong><\/em><\/p>\n<p>Seg\u00fan el Ministerio de Cuidados a Largo Plazo, se han reportado 3.783 muertes entre residentes y pacientes en hogares de cuidados a largo plazo en Ontario, lo que no ha cambiado desde ayer. Se han informado trece muertes relacionadas con virus en total entre el personal.<\/p>\n<p>Hay 3 brotes actuales en los hogares, que no ha cambiado con respecto al d\u00eda anterior.<\/p>\n<p>El ministerio tambi\u00e9n indic\u00f3 que actualmente hay 23 casos activos entre los residentes de cuidados a largo plazo, nueve casos activos entre el personal, sin cambios y con un aumento de tres, respectivamente, en el \u00faltimo d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0&#8211;\u00a0Los residentes de cuidados a largo plazo en Ontario ahora pueden tener visitas al aire libre con hasta 10 personas a la vez. &#8211; Ontario&hellip;<\/p>\n","protected":false},"author":99,"featured_media":498581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,11191],"tags":[],"class_list":["post-498580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canada","category-top-news"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=498580"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498580\/revisions"}],"predecessor-version":[{"id":498582,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/498580\/revisions\/498582"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media\/498581"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=498580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=498580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=498580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}