{"id":546272,"date":"2026-07-15T09:27:23","date_gmt":"2026-07-15T13:27:23","guid":{"rendered":"https:\/\/diarioelpopular.com\/?p=546272"},"modified":"2026-07-15T09:27:23","modified_gmt":"2026-07-15T13:27:23","slug":"un-juez-de-miami-ordena-pagar-314-millones-de-dolares-a-tres-estadounidenses-torturados-en-venezuela","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2026\/07\/15\/un-juez-de-miami-ordena-pagar-314-millones-de-dolares-a-tres-estadounidenses-torturados-en-venezuela\/","title":{"rendered":"Un juez de Miami ordena pagar 314 millones de d\u00f3lares a tres estadounidenses torturados en Venezuela"},"content":{"rendered":"<div id=\"attachment_546273\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-546273\" class=\"wp-image-546273 size-custom-big-size\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-1200x803.png\" alt=\"\" width=\"1200\" height=\"803\" srcset=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-1200x803.png 1200w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-300x201.png 300w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-768x514.png 768w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-1536x1028.png 1536w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-636x426.png 636w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-80x55.png 80w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM-109x73.png 109w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.25.31-AM.png 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-546273\" class=\"wp-caption-text\">Nicol\u00e1s Maduro y su testaferro Alex Saab en el Palacio Miraflores, en Caracas, el 20 de diciembre de 2023.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Foto Pedro Rances (Anadolu v\u00eda Getty Images)<\/p><\/div>\n<p>&nbsp;<\/p>\n<ul>\n<li><em><strong>La sentencia responsabiliza a Nicol\u00e1s Maduro y otros funcionarios venezolanos por el secuestro de tres ciudadanos de EE UU que fueron utilizados en una \u201cdiplomacia de rehenes\u201d para intercambiarlos por el corrupto empresario y testaferro colombiano Alex Saab<\/strong><\/em><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p class=\"\">Un juez federal de Miami orden\u00f3 pagar 314 millones de d\u00f3lares en indemnizaciones a tres ciudadanos estadounidenses que estuvieron encarcelados en Venezuela, donde fueron torturados por los servicios de inteligencia antes de ser liberados en 2023 como parte de un intercambio con Washington por el empresario colombiano y testaferro de Nicol\u00e1s Maduro,\u00a0<a title=\"https:\/\/elpais.com\/america\/2026-05-18\/alex-saab-acusado-en-miami-de-soborno-a-altos-funcionarios-para-su-lucrarse-con-contratos-gubernamentales.html\" href=\"https:\/\/elpais.com\/america\/2026-05-18\/alex-saab-acusado-en-miami-de-soborno-a-altos-funcionarios-para-su-lucrarse-con-contratos-gubernamentales.html\" target=\"_self\" rel=\"\" data-link-track-dtm=\"\" data-mrf-link=\"https:\/\/elpais.com\/america\/2026-05-18\/alex-saab-acusado-en-miami-de-soborno-a-altos-funcionarios-para-su-lucrarse-con-contratos-gubernamentales.html\">Alex Saab<\/a>.<\/p>\n<p class=\"\">El juez Darrin P. Gayles dict\u00f3 este martes una sentencia en rebeld\u00eda contra Maduro, Saab, otros funcionarios venezolanos y el Cartel de los Soles, por no responder a la demanda, presentada en agosto de 2025 en Miami. No hubo un juicio porque, aunque los demandados fueron notificados, no respondieron ni se defendieron.<\/p>\n<p class=\"\">Delcy Rodr\u00edguez, la mandataria interina de Venezuela, figuraba originalmente entre los demandados, pero, misteriosamente qued\u00f3 fuera de la sentencia. Seg\u00fan <i>The Associated Press<\/i>, sus abogados solicitaron en abril desestimar el caso alegando inmunidad como jefa de Estado ante demandas civiles en EE UU.<\/p>\n<p class=\"\">Los demandantes son Jerrel Kenemore, Jason Saad y Edgar Jos\u00e9 Marval, y varios de sus familiares.<\/p>\n<p class=\"\">La demanda sostiene que los tres estadounidenses fueron arrestados y mantenidos como rehenes para presionar a Washington por la liberaci\u00f3n de Saab, se\u00f1alado como uno de los principales operadores financieros del chavismo. Seg\u00fan el documento judicial, Maduro puso en marcha una estrategia de detenci\u00f3n de ciudadanos estadounidenses despu\u00e9s de que Saab fuera capturado y extraditado a Miami acusado de conspiraci\u00f3n para lavar dinero.<\/p>\n<p class=\"\">Los tres hombres estuvieron detenidos en las instalaciones de la Direcci\u00f3n General de Contrainteligencia Militar, en Caracas. Kenemore pas\u00f3 643 d\u00edas detenido, Saad 560 d\u00edas y Marval 123. La demanda sostiene que los tres fueron sometidos a interrogatorios y torturas que incluyeron golpizas, descargas el\u00e9ctricas, posiciones de estr\u00e9s, amenazas y periodos de aislamiento.<\/p>\n<p class=\"\">En el caso de Kenemore, el documento detalla que fue sometido a privaci\u00f3n de alimentos y agua y distintas formas de abuso psicol\u00f3gico. La orden se\u00f1ala que intent\u00f3 suicidarse dos veces y que contin\u00faa sufriendo ataques de p\u00e1nico, ansiedad, depresi\u00f3n, \u00falceras estomacales y otros padecimientos.<\/p>\n<p class=\"\">En el caso de Marval, dice que las palizas le fracturaron la espalda y le dejaron dolores cr\u00f3nicos. Saad estuvo atado de manos y pies en una posici\u00f3n que le desgarr\u00f3 los tendones del brazo, y pas\u00f3 gran parte de su cautiverio en aislamiento, sin atenci\u00f3n m\u00e9dica adecuada y perdi\u00f3 dos dientes.<\/p>\n<p class=\"\">Seg\u00fan la demanda, la contrainteligencia arrestaba, interrogaba y torturaba habitualmente a sus prisioneros, y el caso de los tres estadounidenses fue parte de una \u201cdiplomacia de rehenes\u201d de Maduro para presionar a EE UU.<\/p>\n<p class=\"\">El fallo les di\u00f3 la raz\u00f3n y se\u00f1al\u00f3 que las acciones constituyeron actos de terrorismo internacional bajo la Ley Federal Antiterrorista, que buscaban influir en la conducta del Gobierno estadounidense. Tambi\u00e9n fueron imputados bajo la Ley Antiterrorista de Florida y la ley federal RICO contra empresas criminales organizadas.<\/p>\n<p class=\"\">La Ley Antiterrorista de EE UU permite que los ciudadanos estadounidenses que han sido v\u00edctimas de actos de terrorismo internacional reclamen por da\u00f1os. El juez utiliz\u00f3 una f\u00f3rmula para compensar cada d\u00eda de cautiverio a raz\u00f3n de 20.127 d\u00f3lares por d\u00eda, m\u00e1s sumas adicionales por las torturas. Despu\u00e9s, las indemnizaciones fueron triplicadas, como establece la ley. El documento judicial no identifica activos concretos para pagar la sentencia.<\/p>\n<p class=\"\">El fallo del martes ser\u00eda la mayor indemnizaci\u00f3n concedida hasta ahora por varias demandas presentadas en EE UU por ciudadanos estadounidenses que fueron encarcelados en Venezuela,\u00a0<i>seg\u00fan The Associated Press<\/i>.<\/p>\n<p class=\"\">El fallo vincul\u00f3 los casos\u00a0<a title=\"https:\/\/elpais.com\/us\/2026-01-06\/estados-unidos-elimina-la-referencia-a-maduro-como-lider-del-cartel-de-los-soles-en-su-nueva-imputacion.html\" href=\"https:\/\/elpais.com\/us\/2026-01-06\/estados-unidos-elimina-la-referencia-a-maduro-como-lider-del-cartel-de-los-soles-en-su-nueva-imputacion.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-link-track-dtm=\"\" data-mrf-link=\"https:\/\/elpais.com\/us\/2026-01-06\/estados-unidos-elimina-la-referencia-a-maduro-como-lider-del-cartel-de-los-soles-en-su-nueva-imputacion.html\">con el narcotr\u00e1fico del que est\u00e1 acusado Maduro<\/a>, indicando que el Cartel de los Soles y los dem\u00e1s demandados proporcionaron \u201capoyo material\u201d a Maduro.<\/p>\n<p class=\"\">Kenemore, Saad y Marval fueron liberados el 20 de diciembre de 2023 junto con otros estadounidenses, en un intercambio por Saab, quien estaba encarcelado en Miami a espera de juicio por cargos de lavado de dinero.<\/p>\n<p class=\"\">Los venezolanos trasladaron a los prisioneros encapuchados hasta San Vicente y las Granadinas, donde se produjo el intercambio.<\/p>\n<p class=\"\"><a title=\"https:\/\/elpais.com\/america\/2026-05-18\/alex-saab-acusado-en-miami-de-soborno-a-altos-funcionarios-para-su-lucrarse-con-contratos-gubernamentales.html\" href=\"https:\/\/elpais.com\/america\/2026-05-18\/alex-saab-acusado-en-miami-de-soborno-a-altos-funcionarios-para-su-lucrarse-con-contratos-gubernamentales.html\" target=\"_blank\" rel=\"noopener noreferrer\" data-link-track-dtm=\"\" data-mrf-link=\"https:\/\/elpais.com\/america\/2026-05-18\/alex-saab-acusado-en-miami-de-soborno-a-altos-funcionarios-para-su-lucrarse-con-contratos-gubernamentales.html\">Saab est\u00e1 nuevamente preso en Miami<\/a>, tras ser entregado en mayo por el Gobierno de Rodr\u00edguez. Est\u00e1 acusado de lavado de dinero en una supuesta trama de sobornos a funcionarios para obtener contratos millonarios del programa estatal de alimentos CLAP, entre otros cargos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La sentencia responsabiliza a Nicol\u00e1s Maduro y otros funcionarios venezolanos por el secuestro de tres ciudadanos de EE UU que fueron utilizados en una&hellip;<\/p>\n","protected":false},"author":99,"featured_media":546273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-546272","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latinoamerica"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/546272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=546272"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/546272\/revisions"}],"predecessor-version":[{"id":546274,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/546272\/revisions\/546274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media\/546273"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=546272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=546272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=546272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}