{"id":546284,"date":"2026-07-15T09:40:54","date_gmt":"2026-07-15T13:40:54","guid":{"rendered":"https:\/\/diarioelpopular.com\/?p=546284"},"modified":"2026-07-15T09:40:54","modified_gmt":"2026-07-15T13:40:54","slug":"estados-unidos-lanza-una-nueva-oleada-de-bombardeos-contra-iran","status":"publish","type":"post","link":"https:\/\/diarioelpopular.com\/index.php\/2026\/07\/15\/estados-unidos-lanza-una-nueva-oleada-de-bombardeos-contra-iran\/","title":{"rendered":"Estados Unidos lanza una nueva oleada de bombardeos contra Ir\u00e1n"},"content":{"rendered":"<div id=\"attachment_546285\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-546285\" class=\"wp-image-546285 size-custom-big-size\" src=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-1200x649.png\" alt=\"\" width=\"1200\" height=\"649\" srcset=\"https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-1200x649.png 1200w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-300x162.png 300w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-768x415.png 768w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-1536x830.png 1536w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-636x344.png 636w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM-135x73.png 135w, https:\/\/diarioelpopular.com\/wp-content\/uploads\/2026\/07\/Screen-Shot-2026-07-15-at-9.39.43-AM.png 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-546285\" class=\"wp-caption-text\">El humo se eleva tras una explosi\u00f3n en un lugar desconocido durante lo que el CENTCOM confirma que son ataques contra Ir\u00e1n, en una captura de pantalla tomada de un v\u00eddeo difundido el 14 de julio. U.S. Foto Central Command (via REUTERS)<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><em><strong>El Mando Central estadounidense afirma que su ofensiva busca \u201cdebilitar\u201d al r\u00e9gimen para que renuncie a su control sobre el estrecho de Ormuz<\/strong><\/em><\/p>\n<p>&nbsp;<\/p>\n<p class=\"\">El ej\u00e9rcito estadounidense ha lanzado este mi\u00e9rcoles\u00a0<a title=\"https:\/\/elpais.com\/internacional\/2026-07-12\/estados-unidos-e-iran-se-enzarzan-en-una-nueva-espiral-de-ataques.html\" href=\"https:\/\/elpais.com\/internacional\/2026-07-12\/estados-unidos-e-iran-se-enzarzan-en-una-nueva-espiral-de-ataques.html\" target=\"_self\" rel=\"\" data-link-track-dtm=\"\" data-mrf-link=\"https:\/\/elpais.com\/internacional\/2026-07-12\/estados-unidos-e-iran-se-enzarzan-en-una-nueva-espiral-de-ataques.html\">una nueva oleada de ataques contra Ir\u00e1n<\/a>. El Mando Central de Estados Unidos (CENTCOM) ha confirmado en una publicaci\u00f3n en X que los ataques han comenzado a las 6.00, hora de Washington (mediod\u00eda en la Espa\u00f1a peninsular), y que tienen como objetivo \u201cdebilitar a\u00fan m\u00e1s las capacidades militares que las fuerzas iran\u00edes han utilizado para atacar a buques mercantes en el estrecho de Ormuz\u201d.<\/p>\n<p class=\"\">\u201cA las seis de la ma\u00f1ana (hora del Este) de hoy, las fuerzas del Mando Central de EE UU comenzaron a lanzar una oleada de ataques contra Ir\u00e1n\u201d, se lee en el tuit.<\/p>\n<p class=\"\">El anuncio del CENTCOM llega d\u00edas despu\u00e9s de que el presidente de Estados Unidos, Donald Trump,\u00a0<a title=\"https:\/\/elpais.com\/internacional\/2026-07-13\/trump-notifico-al-congreso-el-fin-de-semana-que-estados-unidos-esta-de-nuevo-en-guerra-con-iran.html\" href=\"https:\/\/elpais.com\/internacional\/2026-07-13\/trump-notifico-al-congreso-el-fin-de-semana-que-estados-unidos-esta-de-nuevo-en-guerra-con-iran.html\" target=\"_self\" rel=\"\" data-link-track-dtm=\"\" data-mrf-link=\"https:\/\/elpais.com\/internacional\/2026-07-13\/trump-notifico-al-congreso-el-fin-de-semana-que-estados-unidos-esta-de-nuevo-en-guerra-con-iran.html\">notificara al Congreso que el pa\u00eds volv\u00eda a estar en guerra<\/a>\u00a0contra la Rep\u00fablica Isl\u00e1mica, y tras una semana de bombardeos y acusaciones cruzadas de violaciones del acuerdo de tregua firmado el pasado 17 de junio.<\/p>\n<p class=\"\">El martes, Washington ya bombarde\u00f3 varias localidades iran\u00edes y Teher\u00e1n replic\u00f3 con ataques contra instalaciones estadounidenses en pa\u00edses de Oriente Pr\u00f3ximo, adem\u00e1s de lanzar proyectiles contra dos buques que intentaron cruzar el estrecho de Ormuz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El Mando Central estadounidense afirma que su ofensiva busca \u201cdebilitar\u201d al r\u00e9gimen para que renuncie a su control sobre el estrecho de Ormuz &nbsp;&hellip;<\/p>\n","protected":false},"author":99,"featured_media":546285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-546284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"_links":{"self":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/546284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/users\/99"}],"replies":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/comments?post=546284"}],"version-history":[{"count":1,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/546284\/revisions"}],"predecessor-version":[{"id":546286,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/posts\/546284\/revisions\/546286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media\/546285"}],"wp:attachment":[{"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/media?parent=546284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/categories?post=546284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diarioelpopular.com\/index.php\/wp-json\/wp\/v2\/tags?post=546284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}